{"id":11852,"date":"2024-03-01T12:50:04","date_gmt":"2024-03-01T11:50:04","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=11852"},"modified":"2024-03-01T12:50:04","modified_gmt":"2024-03-01T11:50:04","slug":"lavori-inghiottitoio-tiburtina-chiarimenti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/","title":{"rendered":"Lavori inghiottitoio Tiburtina: chiarimenti"},"content":{"rendered":"<p>Con riferimento all&#8217;articolo pubblicato il 29 febbraio da Tiburno.tv dal titolo<a href=\"https:\/\/tiburno.tv\/2024\/02\/29\/tivoli-lavori-allinghiottitoio-sulla-tiburtina-traffico-in-tilt-forza-italia-propone-uninterrogazione\/\">\u00a0&#8220;Lavori all\u2019inghiottitoio sulla Tiburtina, traffico in tilt: Forza Italia propone un\u2019interrogazione&#8221;<\/a>, si specifica che l&#8217;intervento di\u00a0\u201cmitigazione del rischio idrogeologico derivante dall\u2019esondazione del canale di raccolta acque in via tiburtina con eliminazione inghiottitoio in Villa Adriana\u201d \u00e8 stato finanziato con 998mila euro dal Ministero dell&#8217;Interno di concerto con il Ministero dell&#8217;Economia e delle Finanze, grazie ad un bando vinto dal Comune di Tivoli. I lavori in corso sono\u00a0necessari\u00a0per eliminare i continui allagamenti sul tratto della via Tiburtina interessato dall&#8217;intervento, al fine di ridurre i rischi per il traffico automobilistico e per\u00a0la pubblica incolumit\u00e0. Il lavoro\u00a0rientra nei progetti del\u00a0PNRR e, in quanto tale, deve rispettare scadenze assolutamente inderogabili, disposte da Ministero e Comunit\u00e0 Europea.\u00a0<strong>Qualora il lavoro stesso non fosse portato a conclusione nelle rigide tempistiche stabilite, il progetto verrebbe definanziato e il Comune dovrebbe pagare\u00a0con proprie risorse i lavori gi\u00e0 eseguiti<\/strong>. Quindi non \u00e8 assolutamente possibile posticipare di alcuni mesi i lavori, cos\u00ec come propone\u00a0Forza Italia.<\/p>\n<p>L&#8217;Amministrazione comunale si scusa per i disagi arrecati alla popolazione e ricorda che la Polizia Locale, competente in materia, ha disposto, dopo un&#8217;attenta analisi, per tutta la durata dei lavori una\u00a0<a href=\"https:\/\/www.comune.tivoli.rm.it\/novita\/notizie\/da-lunedi-26-febbraio-inizio-lavori-eliminazione-inghiottitoio-villa-adriana\">nuova organizzazione del traffico nelle strade limitrofe<\/a>\u00a0con lo scopo di limitare i disagi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con riferimento all&#8217;articolo pubblicato il 29 febbraio da Tiburno.tv dal titolo\u00a0&#8220;Lavori all\u2019inghiottitoio sulla Tiburtina, traffico in tilt: Forza Italia propone un\u2019interrogazione&#8221;, si specifica che l&#8217;intervento di\u00a0\u201cmitigazione del rischio idrogeologico derivante [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-11852","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavori inghiottitoio Tiburtina: chiarimenti - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavori inghiottitoio Tiburtina: chiarimenti - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Con riferimento all&#8217;articolo pubblicato il 29 febbraio da Tiburno.tv dal titolo\u00a0&#8220;Lavori all\u2019inghiottitoio sulla Tiburtina, traffico in tilt: Forza Italia propone un\u2019interrogazione&#8221;, si specifica che l&#8217;intervento di\u00a0\u201cmitigazione del rischio idrogeologico derivante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T11:50:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Lavori inghiottitoio Tiburtina: chiarimenti\",\"datePublished\":\"2024-03-01T11:50:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/\"},\"wordCount\":224,\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/\",\"name\":\"Lavori inghiottitoio Tiburtina: chiarimenti - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2024-03-01T11:50:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/03\\\/01\\\/lavori-inghiottitoio-tiburtina-chiarimenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavori inghiottitoio Tiburtina: chiarimenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavori inghiottitoio Tiburtina: chiarimenti - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/","og_locale":"it_IT","og_type":"article","og_title":"Lavori inghiottitoio Tiburtina: chiarimenti - Tivoli","og_description":"Con riferimento all&#8217;articolo pubblicato il 29 febbraio da Tiburno.tv dal titolo\u00a0&#8220;Lavori all\u2019inghiottitoio sulla Tiburtina, traffico in tilt: Forza Italia propone un\u2019interrogazione&#8221;, si specifica che l&#8217;intervento di\u00a0\u201cmitigazione del rischio idrogeologico derivante [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-03-01T11:50:04+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Lavori inghiottitoio Tiburtina: chiarimenti","datePublished":"2024-03-01T11:50:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/"},"wordCount":224,"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/","url":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/","name":"Lavori inghiottitoio Tiburtina: chiarimenti - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2024-03-01T11:50:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/03\/01\/lavori-inghiottitoio-tiburtina-chiarimenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Lavori inghiottitoio Tiburtina: chiarimenti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=11852"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11852\/revisions"}],"predecessor-version":[{"id":11853,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/11852\/revisions\/11853"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=11852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=11852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=11852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}