{"id":1272,"date":"2017-12-20T17:01:21","date_gmt":"2017-12-20T16:01:21","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1272"},"modified":"2017-12-20T17:01:21","modified_gmt":"2017-12-20T16:01:21","slug":"arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/","title":{"rendered":"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA"},"content":{"rendered":"<p>Nella seduta di oggi, la giunta comunale ha approvato il rapporto preliminare per la redazione della valutazione ambientale strategica relativa al recupero del nucleo edilizio sorto spontaneamente nel quartiere Arci. Con lo stesso atto la giunta ha dato mandato all\u2019ufficio urbanistica di procedere all\u2019attivazione della procedura per la variante speciale relativa al suddetto recupero, inviando alla Regione Lazio la documentazione necessaria.<\/p>\n<p>L\u2019incarico per la redazione del documento, obbligatorio e propedeutico alla variante speciale, era stato affidato lo scorso ottobre dal Comune di Tivoli a una associazione temporanea di professionisti.<\/p>\n<p>&#8220;Con questo atto l&#8217;amministrazione comunale ha fatto un altro importante passo in avanti nel percorso che porter\u00e0 al recupero urbanistico e alla riqualificazione del quartiere, di concerto con il lavoro delle associazioni e dei comitati &#8211; ha commentato l&#8217;assessore all&#8217;urbanistica Nello Rondoni -. Una volta completata la procedura per la vas, il passo successivo e definitivo sar\u00e0 la redazione della relativa variante al Prg&#8221;.<\/p>\n<p>Tivoli, 20 dicembre 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella seduta di oggi, la giunta comunale ha approvato il rapporto preliminare per la redazione della valutazione ambientale strategica relativa al recupero del nucleo edilizio sorto spontaneamente nel quartiere Arci. [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Nella seduta di oggi, la giunta comunale ha approvato il rapporto preliminare per la redazione della valutazione ambientale strategica relativa al recupero del nucleo edilizio sorto spontaneamente nel quartiere Arci. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-20T16:01:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"274\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA\",\"datePublished\":\"2017-12-20T16:01:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/\"},\"wordCount\":172,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/\",\"name\":\"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"datePublished\":\"2017-12-20T16:01:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"width\":274,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/12\\\/20\\\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/","og_locale":"it_IT","og_type":"article","og_title":"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA - Tivoli","og_description":"Nella seduta di oggi, la giunta comunale ha approvato il rapporto preliminare per la redazione della valutazione ambientale strategica relativa al recupero del nucleo edilizio sorto spontaneamente nel quartiere Arci. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-12-20T16:01:21+00:00","og_image":[{"width":274,"height":385,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA","datePublished":"2017-12-20T16:01:21+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/"},"wordCount":172,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/","name":"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","datePublished":"2017-12-20T16:01:21+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","width":274,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/12\/20\/arci-piano-di-recupero-approvata-dalla-giunta-la-deliberazione-relativa-alla-valutazione-ambientale-strategica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"ARCI, PIANO DI RECUPERO: APPROVATA DALLA GIUNTA LA DELIBERAZIONE RELATIVA ALLA VALUTAZIONE AMBIENTALE STRATEGICA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1272"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1272\/revisions"}],"predecessor-version":[{"id":1273,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1272\/revisions\/1273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/617"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}