{"id":12837,"date":"2024-12-16T10:38:53","date_gmt":"2024-12-16T09:38:53","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=12837"},"modified":"2024-12-16T10:38:53","modified_gmt":"2024-12-16T09:38:53","slug":"26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/","title":{"rendered":"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano"},"content":{"rendered":"<p class=\"selectable-text copyable-text x15bjb6t x1n2onr6\" dir=\"ltr\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\u2728<\/span><\/span><span class=\"selectable-text copyable-text false\"> Vivi lo spettacolo del Presepe Vivente al Villaggio Adriano.<\/span><\/p>\n<p class=\"selectable-text copyable-text x15bjb6t x1n2onr6\" dir=\"ltr\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\ud83d\udcc6<\/span><\/span><span class=\"selectable-text copyable-text false\"> Il 26 Dicembre ed il 6 Gennaio, dalle 15:30 alle 19.<\/span><\/p>\n<p class=\"selectable-text copyable-text x15bjb6t x1n2onr6\" dir=\"ltr\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\ud83e\udd1d\ud83c\udffb<\/span><\/span><span class=\"selectable-text copyable-text false\"> Si rinnova, anche quest&#8217;anno, un&#8217;importante tradizione che rafforza il messaggio di pace e di fratellanza. <\/span><\/p>\n<p class=\"selectable-text copyable-text x15bjb6t x1n2onr6\" dir=\"ltr\"><span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu x4uap5 x18d9i69 xkhd6sd\"><span class=\"xrtxmta x1bhl96m\">\u2764\ufe0f<\/span><\/span><span class=\"selectable-text copyable-text false\"> Si ringrazia l&#8217;Ass. Culturale &#8220;Villa Adriana Nostra&#8221; ed il Comitato &#8220;Villaggio Adriano&#8221; per l&#8217;organizzazione.<\/span><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>\u2728 Vivi lo spettacolo del Presepe Vivente al Villaggio Adriano. \ud83d\udcc6 Il 26 Dicembre ed il 6 Gennaio, dalle 15:30 alle 19. \ud83e\udd1d\ud83c\udffb Si rinnova, anche quest&#8217;anno, un&#8217;importante tradizione che [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":12838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano - Tivoli\" \/>\n<meta property=\"og:description\" content=\"\u2728 Vivi lo spettacolo del Presepe Vivente al Villaggio Adriano. \ud83d\udcc6 Il 26 Dicembre ed il 6 Gennaio, dalle 15:30 alle 19. \ud83e\udd1d\ud83c\udffb Si rinnova, anche quest&#8217;anno, un&#8217;importante tradizione che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T09:38:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2024\/12\/PHOTO-2024-12-10-10-13-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"938\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano\",\"datePublished\":\"2024-12-16T09:38:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/\"},\"wordCount\":54,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2024\\\/12\\\/PHOTO-2024-12-10-10-13-19.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/\",\"name\":\"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2024\\\/12\\\/PHOTO-2024-12-10-10-13-19.jpg\",\"datePublished\":\"2024-12-16T09:38:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2024\\\/12\\\/PHOTO-2024-12-10-10-13-19.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2024\\\/12\\\/PHOTO-2024-12-10-10-13-19.jpg\",\"width\":670,\"height\":938},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2024\\\/12\\\/16\\\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/","og_locale":"it_IT","og_type":"article","og_title":"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano - Tivoli","og_description":"\u2728 Vivi lo spettacolo del Presepe Vivente al Villaggio Adriano. \ud83d\udcc6 Il 26 Dicembre ed il 6 Gennaio, dalle 15:30 alle 19. \ud83e\udd1d\ud83c\udffb Si rinnova, anche quest&#8217;anno, un&#8217;importante tradizione che [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-16T09:38:53+00:00","og_image":[{"width":670,"height":938,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2024\/12\/PHOTO-2024-12-10-10-13-19.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano","datePublished":"2024-12-16T09:38:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/"},"wordCount":54,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2024\/12\/PHOTO-2024-12-10-10-13-19.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/","url":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/","name":"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2024\/12\/PHOTO-2024-12-10-10-13-19.jpg","datePublished":"2024-12-16T09:38:53+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2024\/12\/PHOTO-2024-12-10-10-13-19.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2024\/12\/PHOTO-2024-12-10-10-13-19.jpg","width":670,"height":938},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2024\/12\/16\/26-dicembre-e-6-gennaio-il-presepe-vivente-al-villaggio-adriano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"26 Dicembre e 6 Gennaio: Il presepe vivente al Villaggio Adriano"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/12837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=12837"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/12837\/revisions"}],"predecessor-version":[{"id":12839,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/12837\/revisions\/12839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/12838"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=12837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=12837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=12837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}