{"id":12959,"date":"2025-01-03T17:11:14","date_gmt":"2025-01-03T16:11:14","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=12959"},"modified":"2025-01-03T17:11:14","modified_gmt":"2025-01-03T16:11:14","slug":"capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/","title":{"rendered":"Capodanno di Tivoli: una serata magica per festeggiare il 2025"},"content":{"rendered":"<p><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83c\udf87<\/span><\/span> Capodanno di Tivoli: una festa della Citt\u00e0 per iniziare il 2025.<\/p>\n<p><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\u2764\ufe0f<\/span><\/span> L&#8217;Amministrazione ringrazia tutti i Cittadini presenti, gli organizzatori e gli artisti che si sono esibiti nel corso della serata.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12961\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Capodanno-1-1024x682.jpeg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Capodanno-1-1024x682.jpeg 1024w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Capodanno-1-300x200.jpeg 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Capodanno-1-768x512.jpeg 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Capodanno-1-1536x1023.jpeg 1536w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Capodanno-1.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12962\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-2-1024x646.jpeg\" alt=\"\" width=\"640\" height=\"404\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-2-1024x646.jpeg 1024w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-2-300x189.jpeg 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-2-768x484.jpeg 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-2-1536x969.jpeg 1536w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-2.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12963\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-4-1024x694.jpeg\" alt=\"\" width=\"640\" height=\"434\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-4-1024x694.jpeg 1024w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-4-300x203.jpeg 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-4-768x521.jpeg 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-4-1536x1042.jpeg 1536w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-4.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-12964\" src=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-5-1024x744.jpeg\" alt=\"\" width=\"640\" height=\"465\" srcset=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-5-1024x744.jpeg 1024w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-5-300x218.jpeg 300w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-5-768x558.jpeg 768w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-5-1536x1116.jpeg 1536w, https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-5.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf87 Capodanno di Tivoli: una festa della Citt\u00e0 per iniziare il 2025. \u2764\ufe0f L&#8217;Amministrazione ringrazia tutti i Cittadini presenti, gli organizzatori e gli artisti che si sono esibiti nel corso [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":12960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-12959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capodanno di Tivoli: una serata magica per festeggiare il 2025 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capodanno di Tivoli: una serata magica per festeggiare il 2025 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"\ud83c\udf87 Capodanno di Tivoli: una festa della Citt\u00e0 per iniziare il 2025. \u2764\ufe0f L&#8217;Amministrazione ringrazia tutti i Cittadini presenti, gli organizzatori e gli artisti che si sono esibiti nel corso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-03T16:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1051\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Capodanno di Tivoli: una serata magica per festeggiare il 2025\",\"datePublished\":\"2025-01-03T16:11:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/\"},\"wordCount\":39,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/capodanno-3.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/\",\"name\":\"Capodanno di Tivoli: una serata magica per festeggiare il 2025 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/capodanno-3.jpeg\",\"datePublished\":\"2025-01-03T16:11:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/capodanno-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/capodanno-3.jpeg\",\"width\":1600,\"height\":1051},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/03\\\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capodanno di Tivoli: una serata magica per festeggiare il 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capodanno di Tivoli: una serata magica per festeggiare il 2025 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Capodanno di Tivoli: una serata magica per festeggiare il 2025 - Tivoli","og_description":"\ud83c\udf87 Capodanno di Tivoli: una festa della Citt\u00e0 per iniziare il 2025. \u2764\ufe0f L&#8217;Amministrazione ringrazia tutti i Cittadini presenti, gli organizzatori e gli artisti che si sono esibiti nel corso [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-01-03T16:11:14+00:00","og_image":[{"width":1600,"height":1051,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-3.jpeg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Capodanno di Tivoli: una serata magica per festeggiare il 2025","datePublished":"2025-01-03T16:11:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/"},"wordCount":39,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-3.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/","name":"Capodanno di Tivoli: una serata magica per festeggiare il 2025 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-3.jpeg","datePublished":"2025-01-03T16:11:14+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-3.jpeg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/capodanno-3.jpeg","width":1600,"height":1051},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/03\/capodanno-di-tivoli-una-serata-magica-per-festeggiare-il-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Capodanno di Tivoli: una serata magica per festeggiare il 2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/12959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=12959"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/12959\/revisions"}],"predecessor-version":[{"id":12965,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/12959\/revisions\/12965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/12960"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=12959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=12959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=12959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}