{"id":13031,"date":"2025-01-16T08:01:32","date_gmt":"2025-01-16T07:01:32","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13031"},"modified":"2025-01-16T08:01:32","modified_gmt":"2025-01-16T07:01:32","slug":"procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/","title":{"rendered":"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027"},"content":{"rendered":"<p>Si rende noto dell\u2019avvio della <strong>procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027<\/strong> con decorrenza dalla data di esecutivit\u00e0 dell&#8217;atto di nomina, di cui alla determinazione dirigenziale n. 108 del 14\/01\/2025.<\/p>\n<p>I soggetti interessati potranno presentare la propria candidatura liberamente redatta secondo il modello allegato e debitamente sottoscritta con firma autografa o digitale, corredata di dettagliato curriculum formativo e professionale da cui si evinca il possesso dei titoli, esperienze e conoscenze idonee all\u2019espletamento dell\u2019incarico e a copia di un documento di identit\u00e0 in corso di validit\u00e0.<\/p>\n<p>La domanda di partecipazione deve essere inviata esclusivamente a mezzo Posta Elettronica Certificata all\u2019indirizzo <em>info@pec.comune.tivoli.rm.it<\/em> <strong>entro e non oltre le ore 12 del 05 febbraio 2025<\/strong> con oggetto<strong> \u201cManifestazione di interesse a partecipare alla procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo del Comune di Tivoli\u201d.<\/strong><\/p>\n<p>Tutti i dettagli nell&#8217;avviso pubblico in allegato.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_13033\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/avviso-manifestazione-di-interesse.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/avviso-manifestazione-di-interesse.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso manifestazione di interesse<\/a><\/li>\n<li><a id=\"wpba_attachment_list_13034\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Domanda-manifestazione-di-interesse.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Domanda-manifestazione-di-interesse.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Domanda manifestazione di interesse<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si rende noto dell\u2019avvio della procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-13031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si rende noto dell\u2019avvio della procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T07:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Titolo-13.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\\\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027\",\"datePublished\":\"2025-01-16T07:01:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/\"},\"wordCount\":213,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/Titolo-13.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/\",\"name\":\"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\\\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/Titolo-13.png\",\"datePublished\":\"2025-01-16T07:01:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/Titolo-13.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/01\\\/Titolo-13.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/01\\\/16\\\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\\\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/","og_locale":"it_IT","og_type":"article","og_title":"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027 - Tivoli","og_description":"Si rende noto dell\u2019avvio della procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-01-16T07:01:32+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Titolo-13.png","type":"image\/png"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027","datePublished":"2025-01-16T07:01:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/"},"wordCount":213,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Titolo-13.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/","name":"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Titolo-13.png","datePublished":"2025-01-16T07:01:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Titolo-13.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/01\/Titolo-13.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/01\/16\/procedura-di-selezione-di-n-1-membro-esperto-esterno-del-comitato-per-il-controllo-analogo-sulle-societa-in-house-providing-e-del-controllo-sulle-altre-societa-e-o-organismi-partecipati-del-comune-di\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Procedura di selezione di n. 1 membro esperto esterno del Comitato per il Controllo analogo sulle societ\u00e0 in house providing e del controllo sulle altre societ\u00e0 e\/o organismi partecipati del Comune di Tivoli per il triennio 2025 \u2013 2027"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13031"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13031\/revisions"}],"predecessor-version":[{"id":13035,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13031\/revisions\/13035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13032"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}