{"id":13416,"date":"2025-03-20T10:57:29","date_gmt":"2025-03-20T09:57:29","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13416"},"modified":"2025-03-20T11:05:06","modified_gmt":"2025-03-20T10:05:06","slug":"avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/","title":{"rendered":"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024"},"content":{"rendered":"<p>Si informa che, \u00e8 stato pubblicato sull\u2019Albo Pretorio l\u2019<strong>avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024<\/strong>.<\/p>\n<p>\u00c8 possibile reperire tutte le necessarie informazioni nell&#8217;avviso in allegato.<\/p>\n<p>Si ricorda all\u2019utenza che \u00e8 possibile ricevere supporto gratuito per la compilazione, al bisogno, prendendo appuntamento presso lo sportello di Facilitazione Digitale sito in Via Missoni 5 ai seguenti recapiti: 3346494995 (anche Whatsapp) e inform5.3@digitalefacile.online.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_13417\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/avviso-pubblico-2.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/avviso-pubblico-2.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso pubblico<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che, \u00e8 stato pubblicato sull\u2019Albo Pretorio l\u2019avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024. \u00c8 possibile reperire tutte le necessarie [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-13416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si informa che, \u00e8 stato pubblicato sull\u2019Albo Pretorio l\u2019avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024. \u00c8 possibile reperire tutte le necessarie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T09:57:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T10:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/Aggiungi-corpo-del-testo-6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024\",\"datePublished\":\"2025-03-20T09:57:29+00:00\",\"dateModified\":\"2025-03-20T10:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/\"},\"wordCount\":83,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/Aggiungi-corpo-del-testo-6.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/\",\"name\":\"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/Aggiungi-corpo-del-testo-6.png\",\"datePublished\":\"2025-03-20T09:57:29+00:00\",\"dateModified\":\"2025-03-20T10:05:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/Aggiungi-corpo-del-testo-6.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/Aggiungi-corpo-del-testo-6.png\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024 - Tivoli","og_description":"Si informa che, \u00e8 stato pubblicato sull\u2019Albo Pretorio l\u2019avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024. \u00c8 possibile reperire tutte le necessarie [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-20T09:57:29+00:00","article_modified_time":"2025-03-20T10:05:06+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/Aggiungi-corpo-del-testo-6.png","type":"image\/png"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024","datePublished":"2025-03-20T09:57:29+00:00","dateModified":"2025-03-20T10:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/"},"wordCount":83,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/Aggiungi-corpo-del-testo-6.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/","name":"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/Aggiungi-corpo-del-testo-6.png","datePublished":"2025-03-20T09:57:29+00:00","dateModified":"2025-03-20T10:05:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/Aggiungi-corpo-del-testo-6.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/Aggiungi-corpo-del-testo-6.png","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/avviso-pubblico-relativo-al-contributo-a-rimborso-dei-canoni-di-locazione-pagati-nel-corso-del-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico relativo al contributo a rimborso dei canoni di locazione pagati nel corso del 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13416"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13416\/revisions"}],"predecessor-version":[{"id":13419,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13416\/revisions\/13419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13418"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}