{"id":13420,"date":"2025-03-20T20:18:13","date_gmt":"2025-03-20T19:18:13","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13420"},"modified":"2025-03-20T20:18:13","modified_gmt":"2025-03-20T19:18:13","slug":"alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/","title":{"rendered":"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini"},"content":{"rendered":"<p>Il Comune di Tivoli invita cittadini e visitatori a un evento speciale dedicato alla scoperta del miele del Lazio. L&#8217;iniziativa \u00e8 realizzata da A.L.API \u2013 Associazione Laziale Apicoltori per valorizzare un&#8217;eccellenza del nostro territorio.<\/p>\n<p>\ud83d\udcc5 23 marzo 2025<br \/>\n\ud83d\udd59 Dalle 10:00 alle 19:00<br \/>\n\ud83d\udccd Piazza Plebiscito, Tivoli<\/p>\n<p>Degustazione gratuita, museo itinerante e attivit\u00e0 didattiche per bambini per conoscere da vicino il mondo delle api e il valore del miele. Un&#8217;occasione unica per riscoprire la dolcezza della nostra regione e sostenere i produttori locali.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Tivoli invita cittadini e visitatori a un evento speciale dedicato alla scoperta del miele del Lazio. L&#8217;iniziativa \u00e8 realizzata da A.L.API \u2013 Associazione Laziale Apicoltori per valorizzare [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-13420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Tivoli invita cittadini e visitatori a un evento speciale dedicato alla scoperta del miele del Lazio. L&#8217;iniziativa \u00e8 realizzata da A.L.API \u2013 Associazione Laziale Apicoltori per valorizzare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T19:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/IMG-20250318-WA0131.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1122\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini\",\"datePublished\":\"2025-03-20T19:18:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/\"},\"wordCount\":87,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/IMG-20250318-WA0131.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/\",\"name\":\"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/IMG-20250318-WA0131.jpg\",\"datePublished\":\"2025-03-20T19:18:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/IMG-20250318-WA0131.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/03\\\/IMG-20250318-WA0131.jpg\",\"width\":1122,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/03\\\/20\\\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini - Tivoli","og_description":"Il Comune di Tivoli invita cittadini e visitatori a un evento speciale dedicato alla scoperta del miele del Lazio. L&#8217;iniziativa \u00e8 realizzata da A.L.API \u2013 Associazione Laziale Apicoltori per valorizzare [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-20T19:18:13+00:00","og_image":[{"width":1122,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/IMG-20250318-WA0131.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini","datePublished":"2025-03-20T19:18:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/"},"wordCount":87,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/IMG-20250318-WA0131.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/","name":"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/IMG-20250318-WA0131.jpg","datePublished":"2025-03-20T19:18:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/IMG-20250318-WA0131.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/03\/IMG-20250318-WA0131.jpg","width":1122,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/03\/20\/alla-scoperta-del-miele-del-lazio-degustazioni-e-attivita-per-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Alla scoperta del miele del Lazio: degustazioni e attivit\u00e0 per bambini"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13420"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13420\/revisions"}],"predecessor-version":[{"id":13422,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13420\/revisions\/13422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13421"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}