{"id":1346,"date":"2018-01-25T13:16:57","date_gmt":"2018-01-25T12:16:57","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1346"},"modified":"2018-01-25T13:16:57","modified_gmt":"2018-01-25T12:16:57","slug":"si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/","title":{"rendered":"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#8217;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE"},"content":{"rendered":"<p>Tutti i cittadini sono invitati alla\u00a0inaugurazione\u00a0delle nuove mostre\u00a0del Museo della Citt\u00e0 di Tivoli:<\/p>\n<p><strong>Tivoli, fonte di luce<\/strong> e <strong>Tivoli<\/strong> <strong>e \u00a0la vestale<\/strong> <strong>Cossinia.<\/strong><\/p>\n<p>Marted\u00ec 30 gennaio 2018<\/p>\n<p>Programma:<\/p>\n<p>Ore 15<\/p>\n<p>Parco della Vestale Cossinia (via Mazzini)<\/p>\n<p>Visita guidata a cura del Gruppo Archeologico latino \u201cLatium Vetus\u201d sezione Valle dell\u2019Aniene<\/p>\n<p>Ore 16.30<\/p>\n<p>Ex Chiesa dell\u2019Annunziata<\/p>\n<p>Presentazione delle Mostre<\/p>\n<p>Ore 17.30<\/p>\n<p>Museo della citt\u00e0 di Tivoli<\/p>\n<p>Piazza Campitelli<\/p>\n<p>Visita alle Mostre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutti i cittadini sono invitati alla\u00a0inaugurazione\u00a0delle nuove mostre\u00a0del Museo della Citt\u00e0 di Tivoli: Tivoli, fonte di luce e Tivoli e \u00a0la vestale Cossinia. Marted\u00ec 30 gennaio 2018 Programma: Ore 15 [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":1347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#039;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#039;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Tutti i cittadini sono invitati alla\u00a0inaugurazione\u00a0delle nuove mostre\u00a0del Museo della Citt\u00e0 di Tivoli: Tivoli, fonte di luce e Tivoli e \u00a0la vestale Cossinia. Marted\u00ec 30 gennaio 2018 Programma: Ore 15 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-25T12:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/01\/invito-mostre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"917\" \/>\n\t<meta property=\"og:image:height\" content=\"642\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#8217;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE\",\"datePublished\":\"2018-01-25T12:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/\"},\"wordCount\":85,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/01\\\/invito-mostre.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/\",\"name\":\"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA', INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/01\\\/invito-mostre.jpg\",\"datePublished\":\"2018-01-25T12:16:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/01\\\/invito-mostre.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/01\\\/invito-mostre.jpg\",\"width\":917,\"height\":642},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/01\\\/25\\\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#8217;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA', INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/","og_locale":"it_IT","og_type":"article","og_title":"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA', INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE - Tivoli","og_description":"Tutti i cittadini sono invitati alla\u00a0inaugurazione\u00a0delle nuove mostre\u00a0del Museo della Citt\u00e0 di Tivoli: Tivoli, fonte di luce e Tivoli e \u00a0la vestale Cossinia. Marted\u00ec 30 gennaio 2018 Programma: Ore 15 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-01-25T12:16:57+00:00","og_image":[{"width":917,"height":642,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/01\/invito-mostre.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#8217;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE","datePublished":"2018-01-25T12:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/"},"wordCount":85,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/01\/invito-mostre.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/","name":"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA', INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/01\/invito-mostre.jpg","datePublished":"2018-01-25T12:16:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/01\/invito-mostre.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/01\/invito-mostre.jpg","width":917,"height":642},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/01\/25\/si-aprono-due-nuove-mostre-al-museo-della-citta-invito-per-tutti-i-cittadini-alla-presentazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"SI APRONO DUE NUOVE MOSTRE AL MUSEO DELLA CITTA&#8217;, INVITO PER TUTTI I CITTADINI ALLA PRESENTAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1346"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1346\/revisions"}],"predecessor-version":[{"id":1348,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1346\/revisions\/1348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/1347"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}