{"id":13535,"date":"2025-04-04T08:05:27","date_gmt":"2025-04-04T06:05:27","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13535"},"modified":"2025-04-04T08:05:27","modified_gmt":"2025-04-04T06:05:27","slug":"la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/","title":{"rendered":"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti"},"content":{"rendered":"<p>Il Comune di Tivoli invita tutta la cittadinanza a partecipare a un appuntamento speciale in occasione del 3240\u00b0 Natale di Tivoli:<br \/>\n&#8220;La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti&#8221;.<\/p>\n<p>Un viaggio tra immagini, parole e memoria per riscoprire 190 anni di storia legata al fiume Aniene, protagonista assoluto del passato e del presente della nostra citt\u00e0.<\/p>\n<p>L\u2019incontro si terr\u00e0 domenica 6 aprile alle ore 17.00 presso le Scuderie Estensi.<br \/>\nIngresso libero.<\/p>\n<p>Introduce e modera: Giorgia Montesano<br \/>\nLetture a cura di Fabiana Marino e Franca Eletti<br \/>\nPresentazione: Carlo Innocenti<\/p>\n<p>Un&#8217;occasione per riflettere sul valore del nostro patrimonio idrico, storico e culturale.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Tivoli invita tutta la cittadinanza a partecipare a un appuntamento speciale in occasione del 3240\u00b0 Natale di Tivoli: &#8220;La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13536,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-13535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Tivoli invita tutta la cittadinanza a partecipare a un appuntamento speciale in occasione del 3240\u00b0 Natale di Tivoli: &#8220;La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-04T06:05:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/tivoli-acque.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1137\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti\",\"datePublished\":\"2025-04-04T06:05:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/\"},\"wordCount\":115,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/tivoli-acque.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/\",\"name\":\"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/tivoli-acque.jpg\",\"datePublished\":\"2025-04-04T06:05:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/tivoli-acque.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/tivoli-acque.jpg\",\"width\":1137,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/04\\\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/","og_locale":"it_IT","og_type":"article","og_title":"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti - Tivoli","og_description":"Il Comune di Tivoli invita tutta la cittadinanza a partecipare a un appuntamento speciale in occasione del 3240\u00b0 Natale di Tivoli: &#8220;La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-04T06:05:27+00:00","og_image":[{"width":1137,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/tivoli-acque.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti","datePublished":"2025-04-04T06:05:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/"},"wordCount":115,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/tivoli-acque.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/","name":"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/tivoli-acque.jpg","datePublished":"2025-04-04T06:05:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/tivoli-acque.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/tivoli-acque.jpg","width":1137,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/04\/la-citta-salvata-dalle-acque-i-cunicoli-gregoriani-le-centrali-e-gli-acquedotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"La citt\u00e0 salvata dalle acque \u2013 I cunicoli gregoriani, le centrali e gli acquedotti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13535"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13535\/revisions"}],"predecessor-version":[{"id":13537,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13535\/revisions\/13537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13536"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}