{"id":13556,"date":"2025-04-06T19:48:33","date_gmt":"2025-04-06T17:48:33","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13556"},"modified":"2025-04-06T19:48:33","modified_gmt":"2025-04-06T17:48:33","slug":"la-gregoriana-domenica-mattina-allinsegna-dello-sport","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/","title":{"rendered":"La Gregoriana: Domenica mattina all&#8217;insegna dello sport"},"content":{"rendered":"<p>Si \u00e8 svolta oggi &#8220;La Gregoriana&#8221;, prima edizione della gara podistica che da Tivoli \u00e8 arrivata a San Gregorio da Sassola.<\/p>\n<p>L\u2019Amministrazione comunale di Tivoli ha preso parte all\u2019evento, per testimoniare la vicinanza a una manifestazione che unisce sport, memoria e territorio.<\/p>\n<p>Presenti il Sindaco, l\u2019Assessore allo Sport Clizia Lauri, insieme ai Consiglieri Asquini, Attilia e Sordini, da sempre impegnati nella promozione della cultura sportiva come strumento di crescita, inclusione e partecipazione. L&#8217;attivit\u00e0 sportiva \u00e8 un valore centrale per questa Amministrazione, che continuer\u00e0 a sostenere iniziative capaci di coinvolgere cittadini, atleti e realt\u00e0 locali.<\/p>\n<p>La grande adesione dimostra quanto lo sport sappia parlare al cuore della Comunit\u00e0 e costruire legami forti tra le persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolta oggi &#8220;La Gregoriana&#8221;, prima edizione della gara podistica che da Tivoli \u00e8 arrivata a San Gregorio da Sassola. L\u2019Amministrazione comunale di Tivoli ha preso parte all\u2019evento, per [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-13556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Gregoriana: Domenica mattina all&#039;insegna dello sport - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Gregoriana: Domenica mattina all&#039;insegna dello sport - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 svolta oggi &#8220;La Gregoriana&#8221;, prima edizione della gara podistica che da Tivoli \u00e8 arrivata a San Gregorio da Sassola. L\u2019Amministrazione comunale di Tivoli ha preso parte all\u2019evento, per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-06T17:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250406-WA0142-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"La Gregoriana: Domenica mattina all&#8217;insegna dello sport\",\"datePublished\":\"2025-04-06T17:48:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/\"},\"wordCount\":121,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250406-WA0142-scaled.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/\",\"name\":\"La Gregoriana: Domenica mattina all'insegna dello sport - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250406-WA0142-scaled.jpg\",\"datePublished\":\"2025-04-06T17:48:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250406-WA0142-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250406-WA0142-scaled.jpg\",\"width\":1440,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/06\\\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Gregoriana: Domenica mattina all&#8217;insegna dello sport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Gregoriana: Domenica mattina all'insegna dello sport - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/","og_locale":"it_IT","og_type":"article","og_title":"La Gregoriana: Domenica mattina all'insegna dello sport - Tivoli","og_description":"Si \u00e8 svolta oggi &#8220;La Gregoriana&#8221;, prima edizione della gara podistica che da Tivoli \u00e8 arrivata a San Gregorio da Sassola. L\u2019Amministrazione comunale di Tivoli ha preso parte all\u2019evento, per [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-06T17:48:33+00:00","og_image":[{"width":1440,"height":2560,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250406-WA0142-scaled.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"La Gregoriana: Domenica mattina all&#8217;insegna dello sport","datePublished":"2025-04-06T17:48:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/"},"wordCount":121,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250406-WA0142-scaled.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/","name":"La Gregoriana: Domenica mattina all'insegna dello sport - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250406-WA0142-scaled.jpg","datePublished":"2025-04-06T17:48:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250406-WA0142-scaled.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250406-WA0142-scaled.jpg","width":1440,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/06\/la-gregoriana-domenica-mattina-allinsegna-dello-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"La Gregoriana: Domenica mattina all&#8217;insegna dello sport"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13556"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13556\/revisions"}],"predecessor-version":[{"id":13558,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13556\/revisions\/13558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13557"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}