{"id":13634,"date":"2025-04-12T15:10:07","date_gmt":"2025-04-12T13:10:07","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13634"},"modified":"2025-04-12T15:10:07","modified_gmt":"2025-04-12T13:10:07","slug":"tivoli-dice-no-alla-violenza-sulle-donne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/","title":{"rendered":"Tivoli dice no alla violenza sulle donne"},"content":{"rendered":"<p>Nella serata di venerd\u00ec 11 aprile 2025, il Comune di Tivoli ha preso parte alla fiaccolata organizzata a Poli per dire con forza \u201cNo alla violenza sulle donne\u201d.<\/p>\n<p>A rappresentare il nostro Comune \u00e8 stato il Consigliere Comunale Paola Sordini, che ha partecipato all\u2019evento in segno di vicinanza e solidariet\u00e0 a una battaglia che non pu\u00f2 e non deve conoscere confini territoriali, politici o culturali.<\/p>\n<p>L\u2019Amministrazione Comunale di Tivoli ribadisce con convinzione il proprio impegno contro ogni forma di violenza e discriminazione di genere. Siamo e saremo sempre accanto a tutte le donne, perch\u00e9 possano vivere vive e libere, come recita lo slogan della manifestazione, in una societ\u00e0 giusta, sicura e rispettosa dei diritti fondamentali.<\/p>\n<p>Solo attraverso la partecipazione attiva, la consapevolezza collettiva e l\u2019azione condivisa sar\u00e0 possibile costruire un futuro libero dalla violenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella serata di venerd\u00ec 11 aprile 2025, il Comune di Tivoli ha preso parte alla fiaccolata organizzata a Poli per dire con forza \u201cNo alla violenza sulle donne\u201d. A rappresentare [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-13634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tivoli dice no alla violenza sulle donne - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tivoli dice no alla violenza sulle donne - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Nella serata di venerd\u00ec 11 aprile 2025, il Comune di Tivoli ha preso parte alla fiaccolata organizzata a Poli per dire con forza \u201cNo alla violenza sulle donne\u201d. A rappresentare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-12T13:10:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250412-WA0043.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Tivoli dice no alla violenza sulle donne\",\"datePublished\":\"2025-04-12T13:10:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/\"},\"wordCount\":141,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250412-WA0043.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/\",\"name\":\"Tivoli dice no alla violenza sulle donne - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250412-WA0043.jpg\",\"datePublished\":\"2025-04-12T13:10:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250412-WA0043.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/IMG-20250412-WA0043.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/04\\\/12\\\/tivoli-dice-no-alla-violenza-sulle-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tivoli dice no alla violenza sulle donne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tivoli dice no alla violenza sulle donne - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/","og_locale":"it_IT","og_type":"article","og_title":"Tivoli dice no alla violenza sulle donne - Tivoli","og_description":"Nella serata di venerd\u00ec 11 aprile 2025, il Comune di Tivoli ha preso parte alla fiaccolata organizzata a Poli per dire con forza \u201cNo alla violenza sulle donne\u201d. A rappresentare [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-12T13:10:07+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250412-WA0043.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Tivoli dice no alla violenza sulle donne","datePublished":"2025-04-12T13:10:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/"},"wordCount":141,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250412-WA0043.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/","name":"Tivoli dice no alla violenza sulle donne - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250412-WA0043.jpg","datePublished":"2025-04-12T13:10:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250412-WA0043.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/IMG-20250412-WA0043.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/04\/12\/tivoli-dice-no-alla-violenza-sulle-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Tivoli dice no alla violenza sulle donne"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13634"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13634\/revisions"}],"predecessor-version":[{"id":13636,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13634\/revisions\/13636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13635"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}