{"id":13770,"date":"2025-05-03T09:15:56","date_gmt":"2025-05-03T07:15:56","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13770"},"modified":"2025-05-03T09:15:56","modified_gmt":"2025-05-03T07:15:56","slug":"xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/","title":{"rendered":"XIa Finale di Gala del Concorso Lirico Internazionale &#8220;Jole De Maria&#8221;"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">Domenica 4 maggio 2025, alle ore 17:00, presso le Scuderie Estensi di Tivoli (Piazza Garibaldi), si terr\u00e0 la Finale di gala del prestigioso Concorso Lirico Internazionale \u201cJole De Maria\u201d, giunto alla sua undicesima edizione.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019iniziativa, ideata dall\u2019Associazione Arcipelago, rappresenta un appuntamento di rilievo nel panorama musicale europeo, nonch\u00e9 un omaggio alla memoria della celebre soprano Jole De Maria, artista di straordinario talento e ambasciatrice della cultura italiana nel mondo.<\/p>\n<p>&nbsp;<\/p>\n<p>La serata vedr\u00e0 esibirsi giovani cantanti lirici selezionati da una giuria internazionale di grande prestigio, in un contesto di altissimo valore artistico e simbolico. Il concorso sostiene inoltre un\u2019importante causa sociale: la Ricerca sul cancro, dimostrando come l\u2019arte possa farsi veicolo di solidariet\u00e0 e impegno civile.<\/p>\n<p>Invitiamo la cittadinanza a partecipare numerosa a questo evento che unisce cultura, memoria e speranza, e che conferma ancora una volta Tivoli come centro propulsore di eccellenze artistiche e sensibilit\u00e0 sociale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 4 maggio 2025, alle ore 17:00, presso le Scuderie Estensi di Tivoli (Piazza Garibaldi), si terr\u00e0 la Finale di gala del prestigioso Concorso Lirico Internazionale \u201cJole De Maria\u201d, giunto [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13771,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-13770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XIa Finale di Gala del Concorso Lirico Internazionale &quot;Jole De Maria&quot; - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XIa Finale di Gala del Concorso Lirico Internazionale &quot;Jole De Maria&quot; - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Domenica 4 maggio 2025, alle ore 17:00, presso le Scuderie Estensi di Tivoli (Piazza Garibaldi), si terr\u00e0 la Finale di gala del prestigioso Concorso Lirico Internazionale \u201cJole De Maria\u201d, giunto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-03T07:15:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/05\/FB_IMG_1746256163740.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"XIa Finale di Gala del Concorso Lirico Internazionale &#8220;Jole De Maria&#8221;\",\"datePublished\":\"2025-05-03T07:15:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/\"},\"wordCount\":160,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/05\\\/FB_IMG_1746256163740.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/\",\"name\":\"XIa Finale di Gala del Concorso Lirico Internazionale \\\"Jole De Maria\\\" - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/05\\\/FB_IMG_1746256163740.jpg\",\"datePublished\":\"2025-05-03T07:15:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/05\\\/FB_IMG_1746256163740.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/05\\\/FB_IMG_1746256163740.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/03\\\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XIa Finale di Gala del Concorso Lirico Internazionale &#8220;Jole De Maria&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XIa Finale di Gala del Concorso Lirico Internazionale \"Jole De Maria\" - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/","og_locale":"it_IT","og_type":"article","og_title":"XIa Finale di Gala del Concorso Lirico Internazionale \"Jole De Maria\" - Tivoli","og_description":"Domenica 4 maggio 2025, alle ore 17:00, presso le Scuderie Estensi di Tivoli (Piazza Garibaldi), si terr\u00e0 la Finale di gala del prestigioso Concorso Lirico Internazionale \u201cJole De Maria\u201d, giunto [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-03T07:15:56+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/05\/FB_IMG_1746256163740.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"XIa Finale di Gala del Concorso Lirico Internazionale &#8220;Jole De Maria&#8221;","datePublished":"2025-05-03T07:15:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/"},"wordCount":160,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/05\/FB_IMG_1746256163740.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/","name":"XIa Finale di Gala del Concorso Lirico Internazionale \"Jole De Maria\" - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/05\/FB_IMG_1746256163740.jpg","datePublished":"2025-05-03T07:15:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/05\/FB_IMG_1746256163740.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/05\/FB_IMG_1746256163740.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/03\/xia-finale-di-gala-del-concorso-lirico-internazionale-jole-de-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"XIa Finale di Gala del Concorso Lirico Internazionale &#8220;Jole De Maria&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13770"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13770\/revisions"}],"predecessor-version":[{"id":13772,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13770\/revisions\/13772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13771"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}