{"id":13812,"date":"2025-05-09T11:10:28","date_gmt":"2025-05-09T09:10:28","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=13812"},"modified":"2025-05-09T11:10:28","modified_gmt":"2025-05-09T09:10:28","slug":"via-del-colle-modifiche-viabilita-10-maggio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/","title":{"rendered":"Via del Colle &#8211; Modifiche viabilit\u00e0 10 maggio"},"content":{"rendered":"<p>A causa di una copiosa perdita d&#8217;acqua nei pressi del civico 41 di via del Colle, segnalata nei giorni scorsi e seguita da richiesta di intervento da parte di ACEA Ato2, si rende necessaria la chiusura temporanea della strada per consentire i lavori urgenti.<\/p>\n<p>Quando:<br \/>\n<span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\u27a1\ufe0f<\/span><\/span> Sabato 10 maggio 2025, dalle ore 6:00 alle 17:00 (e comunque fino al termine dei lavori)<\/p>\n<p><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\ud83d\udeab<\/span><\/span> Divieto di transito per tutti i veicoli nel tratto:<\/p>\n<p>da civico 41 di via del Colle fino a piazza San Silvestro<\/p>\n<p><span class=\"x1xsqp64 xiy17q3 x1o6pynw x19co3pv xdj266r xcwd3tp xat24cr x39eecv x2b8uid\" data-testid=\"emoji\"><span class=\"xexx8yu xn5pp95 x18d9i69 x2fxd7x x3jgonx x1bhl96m\">\u2705<\/span><\/span> Fanno eccezione solo:<\/p>\n<p>&#8211; veicoli di soccorso in emergenza<\/p>\n<p>&#8211; mezzi della ditta incaricata ai lavori<\/p>\n<p>L\u2019intervento \u00e8 urgente e necessario per evitare danni alla strada e agli edifici circostanti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa di una copiosa perdita d&#8217;acqua nei pressi del civico 41 di via del Colle, segnalata nei giorni scorsi e seguita da richiesta di intervento da parte di ACEA [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":13673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-13812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Via del Colle - Modifiche viabilit\u00e0 10 maggio - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Via del Colle - Modifiche viabilit\u00e0 10 maggio - Tivoli\" \/>\n<meta property=\"og:description\" content=\"A causa di una copiosa perdita d&#8217;acqua nei pressi del civico 41 di via del Colle, segnalata nei giorni scorsi e seguita da richiesta di intervento da parte di ACEA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-09T09:10:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/FB_IMG_1744983260790.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Via del Colle &#8211; Modifiche viabilit\u00e0 10 maggio\",\"datePublished\":\"2025-05-09T09:10:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/\"},\"wordCount\":113,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/FB_IMG_1744983260790.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/\",\"name\":\"Via del Colle - Modifiche viabilit\u00e0 10 maggio - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/FB_IMG_1744983260790.jpg\",\"datePublished\":\"2025-05-09T09:10:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/FB_IMG_1744983260790.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/04\\\/FB_IMG_1744983260790.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/05\\\/09\\\/via-del-colle-modifiche-viabilita-10-maggio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Via del Colle &#8211; Modifiche viabilit\u00e0 10 maggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Via del Colle - Modifiche viabilit\u00e0 10 maggio - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/","og_locale":"it_IT","og_type":"article","og_title":"Via del Colle - Modifiche viabilit\u00e0 10 maggio - Tivoli","og_description":"A causa di una copiosa perdita d&#8217;acqua nei pressi del civico 41 di via del Colle, segnalata nei giorni scorsi e seguita da richiesta di intervento da parte di ACEA [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-09T09:10:28+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/FB_IMG_1744983260790.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Via del Colle &#8211; Modifiche viabilit\u00e0 10 maggio","datePublished":"2025-05-09T09:10:28+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/"},"wordCount":113,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/FB_IMG_1744983260790.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/","name":"Via del Colle - Modifiche viabilit\u00e0 10 maggio - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/FB_IMG_1744983260790.jpg","datePublished":"2025-05-09T09:10:28+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/FB_IMG_1744983260790.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/04\/FB_IMG_1744983260790.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/05\/09\/via-del-colle-modifiche-viabilita-10-maggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Via del Colle &#8211; Modifiche viabilit\u00e0 10 maggio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=13812"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13812\/revisions"}],"predecessor-version":[{"id":13813,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/13812\/revisions\/13813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/13673"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=13812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=13812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=13812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}