{"id":14060,"date":"2025-06-09T15:12:42","date_gmt":"2025-06-09T13:12:42","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=14060"},"modified":"2025-06-09T15:12:42","modified_gmt":"2025-06-09T13:12:42","slug":"la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/","title":{"rendered":"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva"},"content":{"rendered":"<p>Venerd\u00ec 13 giugno 2025, alle ore 13:00 presso le Scuderie Estensi, si terr\u00e0 il convegno \u201cLa violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva\u201d, promosso dalla Procura della Repubblica di Tivoli e dal Comune di Tivoli.<br \/>\nUn incontro pubblico per affrontare, con voci autorevoli e competenze trasversali, una delle forme di violenza pi\u00f9 gravi e radicate nella nostra societ\u00e0: quella domestica e di genere. Un fenomeno che colpisce quotidianamente donne di ogni et\u00e0 e condizione sociale e che richiede una risposta ferma, coordinata e continua da parte delle istituzioni e della comunit\u00e0.<\/p>\n<p>La giornata si aprir\u00e0 alle ore 13:00 con la proiezione integrale del documentario \u201cProcesso per stupro\u201d (RAI, 1979), la prima proiezione pubblica autorizzata. Il documentario mostr\u00f2 per la prima volta in TV un processo per violenza sessuale, rivelando l\u2019atteggiamento colpevolizzante nei confronti della vittima, e segnando una svolta nel dibattito pubblico sul tema.<\/p>\n<p>Alle ore 15:00 inizieranno i lavori del convegno, coordinati dal Procuratore Francesco Menditto, con i saluti istituzionali del Sindaco di Tivoli Marco Innocenzi.<br \/>\nSeguiranno gli interventi di: Margherita Cassano, Prima Presidente della Corte di Cassazione; Raffaele Sabato, Giudice presso la Corte europea dei diritti umani; Andrea Calice, della Procura di Tivoli e rappresentanti della rete territoriale impegnati nel contrasto alla violenza di genere e domestica.<\/p>\n<p>Si parler\u00e0 delle norme nazionali e internazionali \u2013 dalla Convenzione di Istanbul alle leggi 69\/2019 e 168\/2023 \u2013 che hanno rafforzato gli strumenti giuridici a tutela delle vittime, e dell\u2019importanza di un lavoro di rete tra magistratura, forze dell\u2019ordine, servizi sociali, centri antiviolenza e amministrazioni locali.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 13 giugno 2025, alle ore 13:00 presso le Scuderie Estensi, si terr\u00e0 il convegno \u201cLa violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva\u201d, [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":14061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-14060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 13 giugno 2025, alle ore 13:00 presso le Scuderie Estensi, si terr\u00e0 il convegno \u201cLa violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T13:12:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/06\/procura.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva\",\"datePublished\":\"2025-06-09T13:12:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/\"},\"wordCount\":270,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/06\\\/procura.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/\",\"name\":\"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/06\\\/procura.jpeg\",\"datePublished\":\"2025-06-09T13:12:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/06\\\/procura.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/06\\\/procura.jpeg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/06\\\/09\\\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/","og_locale":"it_IT","og_type":"article","og_title":"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva - Tivoli","og_description":"Venerd\u00ec 13 giugno 2025, alle ore 13:00 presso le Scuderie Estensi, si terr\u00e0 il convegno \u201cLa violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva\u201d, [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-06-09T13:12:42+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/06\/procura.jpeg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva","datePublished":"2025-06-09T13:12:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/"},"wordCount":270,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/06\/procura.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/","name":"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/06\/procura.jpeg","datePublished":"2025-06-09T13:12:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/06\/procura.jpeg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/06\/procura.jpeg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/06\/09\/la-violenza-domestica-e-contro-le-donne-dalle-fonti-sovranazionali-e-nazionali-alla-tutela-effettiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"La violenza domestica e contro le donne. Dalle fonti sovranazionali e nazionali alla tutela effettiva"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=14060"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14060\/revisions"}],"predecessor-version":[{"id":14062,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14060\/revisions\/14062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/14061"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=14060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=14060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=14060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}