{"id":14414,"date":"2025-08-20T10:51:36","date_gmt":"2025-08-20T08:51:36","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=14414"},"modified":"2025-08-20T10:51:36","modified_gmt":"2025-08-20T08:51:36","slug":"ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/","title":{"rendered":"Ufficio stato civile: nuovi orari di apertura al pubblico"},"content":{"rendered":"<p>Al fine di facilitare la fruizione dei servizi da parte dell\u2019utenza ed allo scopo di rispondere adeguatamente alle esigenze dei cittadini, l\u2019Ufficio di Stato Civile, dal 1\u00b0 Settembre 2025, osserver\u00e0 un nuovo orario di apertura al pubblico.<br \/>\nNel dettaglio, l\u2019Ufficio sar\u00e0 aperto:<br \/>\n&#8211; per atti di nascita e morte, dal luned\u00ec al venerd\u00ec, dalle ore 9,00 alle 12,00 &#8211; marted\u00ec e gioved\u00ec anche dalle ore 15,00 alle ore 17,00; il sabato mattina, dalle ore 8,30 sino al completamento delle attivit\u00e0;<br \/>\n&#8211; per tutte le altre richieste che comportano impegno procedurale ed adempimenti pi\u00f9 complessi, come cittadinanze, pubblicazione atti di matrimonio, separazioni, divorzi, unioni civili, richieste di trascrizioni ed annotazione di atti, l\u2019Ufficio osserver\u00e0 l\u2019apertura al pubblico nei seguenti giorni ed orari: marted\u00ec e gioved\u00ec, dalle ore 9,00 alle ore 12,00 e dalle ore 15,00 alle ore 17,00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al fine di facilitare la fruizione dei servizi da parte dell\u2019utenza ed allo scopo di rispondere adeguatamente alle esigenze dei cittadini, l\u2019Ufficio di Stato Civile, dal 1\u00b0 Settembre 2025, osserver\u00e0 [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":14415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-14414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ufficio stato civile: nuovi orari di apertura al pubblico - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ufficio stato civile: nuovi orari di apertura al pubblico - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Al fine di facilitare la fruizione dei servizi da parte dell\u2019utenza ed allo scopo di rispondere adeguatamente alle esigenze dei cittadini, l\u2019Ufficio di Stato Civile, dal 1\u00b0 Settembre 2025, osserver\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T08:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/08\/Aggiungi-corpo-del-testo-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Ufficio stato civile: nuovi orari di apertura al pubblico\",\"datePublished\":\"2025-08-20T08:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/\"},\"wordCount\":140,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/08\\\/Aggiungi-corpo-del-testo-2.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/\",\"name\":\"Ufficio stato civile: nuovi orari di apertura al pubblico - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/08\\\/Aggiungi-corpo-del-testo-2.png\",\"datePublished\":\"2025-08-20T08:51:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/08\\\/Aggiungi-corpo-del-testo-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/08\\\/Aggiungi-corpo-del-testo-2.png\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/08\\\/20\\\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ufficio stato civile: nuovi orari di apertura al pubblico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ufficio stato civile: nuovi orari di apertura al pubblico - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/","og_locale":"it_IT","og_type":"article","og_title":"Ufficio stato civile: nuovi orari di apertura al pubblico - Tivoli","og_description":"Al fine di facilitare la fruizione dei servizi da parte dell\u2019utenza ed allo scopo di rispondere adeguatamente alle esigenze dei cittadini, l\u2019Ufficio di Stato Civile, dal 1\u00b0 Settembre 2025, osserver\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-08-20T08:51:36+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/08\/Aggiungi-corpo-del-testo-2.png","type":"image\/png"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Ufficio stato civile: nuovi orari di apertura al pubblico","datePublished":"2025-08-20T08:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/"},"wordCount":140,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/08\/Aggiungi-corpo-del-testo-2.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/","name":"Ufficio stato civile: nuovi orari di apertura al pubblico - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/08\/Aggiungi-corpo-del-testo-2.png","datePublished":"2025-08-20T08:51:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/08\/Aggiungi-corpo-del-testo-2.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/08\/Aggiungi-corpo-del-testo-2.png","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/08\/20\/ufficio-stato-civile-nuovi-orari-di-apertura-al-pubblico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Ufficio stato civile: nuovi orari di apertura al pubblico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=14414"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14414\/revisions"}],"predecessor-version":[{"id":14416,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14414\/revisions\/14416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/14415"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=14414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=14414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=14414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}