{"id":1466,"date":"2018-03-01T11:59:26","date_gmt":"2018-03-01T10:59:26","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1466"},"modified":"2018-03-01T11:59:26","modified_gmt":"2018-03-01T10:59:26","slug":"nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/","title":{"rendered":"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI"},"content":{"rendered":"<p>E\u2019 attivo da oggi, al numero 800 894 520, il contact center certificato del nuovo Servizio luce del Comune di Tivoli. Il numero verde gratuito \u00e8 a disposizione dei cittadini 24 ore su 24 tutti i giorni dell\u2019anno, anche le domeniche e i festivi, e riceve segnalazioni su guasti e malfunzionamenti di tutti gli impianti della pubblica illuminazione del territorio di Tivoli.<\/p>\n<p>Il contact center \u00e8 gestito dalla societ\u00e0 affidataria del servizio, Conversion &amp; Lighting del gruppo Engie.<\/p>\n<p>In questa prima fase, come da programma, la societ\u00e0 affidataria si occuper\u00e0 della manutenzione degli impianti e degli interventi di ripristino e di riparazione dei punti luce e delle reti della pubblica illuminazione. Nelle prossime settimane sar\u00e0 avviato l\u2019ampio programma di interventi per la sostituzione delle vecchie lampade con dispositivi a led e del rifacimento delle vecchie reti e dei vecchi impianti, come da convenzione (leggi anche il comunicato del 8 gennaio scorso al seguente link <a href=\"http:\/\/www.comune.tivoli.rm.it\/node\/3201\">http:\/\/www.comune.tivoli.rm.it\/node\/3201<\/a> ).<\/p>\n<p>\u201cDa oggi a Tivoli parte di fatto il nuovo servizio di illuminazione pubblica, un cambiamento che definirei epocale per la nostra citt\u00e0 verso l\u2019efficienza, il risparmio energetico e la sicurezza dei cittadini \u2013 ha commentato il vicesindaco e assessore ai lavori pubblici Irene Vota -. Da oggi scatta la prima fase di un programma complesso e importantissimo per risolvere finalmente e in maniera organica un problema annoso per la nostra citt\u00e0, che dopo aver avuto il lustro di essere la citt\u00e0 dove venne inaugurata la prima illuminazione pubblica in corrente alternata, oggi vede la sua rete fortemente deteriorata perch\u00e9 vetusta e mai ammodernata, in molti casi, da pi\u00f9 di 50 anni. In questa prima fase partir\u00e0 il servizio di gestione con la messa a disposizione dei cittadini di un numero verde per segnalare guasti alla rete esistente. Contestualmente sono in partenza i progetti esecutivi per avviare gli ingenti lavori di sostituzione sull\u2019infrastruttura dell\u2019intero territorio comunale che prevedono la conversione a led dell\u2019illuminazione, con il complessivo efficientamento, risparmio energetico e messa in sicurezza\u201d.<\/p>\n<p>Tivoli, gioved\u00ec 1 marzo 2018<\/p>\n<p>(foto di Alberto Proli)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 attivo da oggi, al numero 800 894 520, il contact center certificato del nuovo Servizio luce del Comune di Tivoli. Il numero verde gratuito \u00e8 a disposizione dei cittadini [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":1467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI - Tivoli\" \/>\n<meta property=\"og:description\" content=\"E\u2019 attivo da oggi, al numero 800 894 520, il contact center certificato del nuovo Servizio luce del Comune di Tivoli. Il numero verde gratuito \u00e8 a disposizione dei cittadini [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-01T10:59:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/03\/luce-sulla-citt\u00e0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI\",\"datePublished\":\"2018-03-01T10:59:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/\"},\"wordCount\":350,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/03\\\/luce-sulla-citt\u00e0.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/\",\"name\":\"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/03\\\/luce-sulla-citt\u00e0.jpg\",\"datePublished\":\"2018-03-01T10:59:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/03\\\/luce-sulla-citt\u00e0.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/03\\\/luce-sulla-citt\u00e0.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/01\\\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/","og_locale":"it_IT","og_type":"article","og_title":"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI - Tivoli","og_description":"E\u2019 attivo da oggi, al numero 800 894 520, il contact center certificato del nuovo Servizio luce del Comune di Tivoli. Il numero verde gratuito \u00e8 a disposizione dei cittadini [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-03-01T10:59:26+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/03\/luce-sulla-citt\u00e0.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI","datePublished":"2018-03-01T10:59:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/"},"wordCount":350,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/03\/luce-sulla-citt\u00e0.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/","name":"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/03\/luce-sulla-citt\u00e0.jpg","datePublished":"2018-03-01T10:59:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/03\/luce-sulla-citt\u00e0.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/03\/luce-sulla-citt\u00e0.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/01\/nuovo-servizio-luce-a-tivoli-da-oggi-attivo-il-contact-center-per-le-segnalazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"NUOVO SERVIZIO LUCE A TIVOLI, DA OGGI ATTIVO IL CONTACT CENTER PER LE SEGNALAZIONI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1466\/revisions"}],"predecessor-version":[{"id":1468,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1466\/revisions\/1468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/1467"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}