{"id":14868,"date":"2025-11-18T18:58:25","date_gmt":"2025-11-18T17:58:25","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=14868"},"modified":"2025-11-18T18:58:25","modified_gmt":"2025-11-18T17:58:25","slug":"eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/","title":{"rendered":"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale"},"content":{"rendered":"<p>Si invita la cittadinanza al secondo appuntamento del ciclo di incontri culturali ospitato presso la Biblioteca Comunale \u201cMaria Coccanari Fornari\u201d. L\u2019incontro, curato dalle professoresse Maria Luisa Angrisani e Maria Antonietta Coccanari de\u2019 Fornari, approfondir\u00e0 il legame tra Eleonora Duse e Tivoli, con particolare riferimento ai suoi soggiorni presso Villa Osti Giambruni al Quintiliolo, dove fu ospite di una delle sue amiche pi\u00f9 care e dove ricevette cure per i suoi problemi respiratori dal medico condotto Felice Santori.<\/p>\n<p>La drammaturga Alma Daddario presenter\u00e0 in anteprima un\u2019opera dedicata alla grande attrice. Alcuni estratti saranno letti dall\u2019attrice e regista Alessandra Fallucchi, con introduzione del dr. Matteo Centani, che offrir\u00e0 un inquadramento della figura della Duse nella storia del teatro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si invita la cittadinanza al secondo appuntamento del ciclo di incontri culturali ospitato presso la Biblioteca Comunale \u201cMaria Coccanari Fornari\u201d. L\u2019incontro, curato dalle professoresse Maria Luisa Angrisani e Maria Antonietta [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":14869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-14868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si invita la cittadinanza al secondo appuntamento del ciclo di incontri culturali ospitato presso la Biblioteca Comunale \u201cMaria Coccanari Fornari\u201d. L\u2019incontro, curato dalle professoresse Maria Luisa Angrisani e Maria Antonietta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-18T17:58:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/11\/coccanari.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale\",\"datePublished\":\"2025-11-18T17:58:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/\"},\"wordCount\":129,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/11\\\/coccanari.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/\",\"name\":\"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/11\\\/coccanari.jpg\",\"datePublished\":\"2025-11-18T17:58:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/11\\\/coccanari.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2025\\\/11\\\/coccanari.jpg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2025\\\/11\\\/18\\\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale - Tivoli","og_description":"Si invita la cittadinanza al secondo appuntamento del ciclo di incontri culturali ospitato presso la Biblioteca Comunale \u201cMaria Coccanari Fornari\u201d. L\u2019incontro, curato dalle professoresse Maria Luisa Angrisani e Maria Antonietta [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-11-18T17:58:25+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/11\/coccanari.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale","datePublished":"2025-11-18T17:58:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/"},"wordCount":129,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/11\/coccanari.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/","url":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/","name":"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/11\/coccanari.jpg","datePublished":"2025-11-18T17:58:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/11\/coccanari.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2025\/11\/coccanari.jpg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2025\/11\/18\/eleonora-duse-e-tivoli-il-legame-raccontato-alla-biblioteca-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Eleonora Duse e Tivoli: il legame raccontato alla Biblioteca Comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=14868"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14868\/revisions"}],"predecessor-version":[{"id":14870,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/14868\/revisions\/14870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/14869"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=14868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=14868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=14868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}