{"id":15120,"date":"2026-01-08T18:57:12","date_gmt":"2026-01-08T17:57:12","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=15120"},"modified":"2026-01-08T18:57:12","modified_gmt":"2026-01-08T17:57:12","slug":"trasporto-pubblico-regionale-la-gestione-alla-regione-lazio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/","title":{"rendered":"Trasporto pubblico regionale: la gestione alla Regione Lazio"},"content":{"rendered":"<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\" dir=\"auto\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\" data-ad-rendering-role=\"story_message\">\n<div id=\"_r_7q_\" class=\"x1l90r2v x1iorvi4 x1g0dm76 xpdmqnj\" data-ad-comet-preview=\"message\" data-ad-preview=\"message\">\n<div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\">\n<div class=\"xu06os2 x1ok221b\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<div dir=\"auto\">Si ricorda che, in tutto il Lazio, compreso il territorio di Tivoli, la gestione del Trasporto Pubblico Locale (TPL) \u00e8 passata dai Comuni alla Regione Lazio, tramite Astral.<\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<div dir=\"auto\">Il cambiamento comporta importanti novit\u00e0 sia nella bigliettazione sia nell\u2019organizzazione di linee, percorsi e fermate, che interessano direttamente il territorio comunale.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">In questa fase iniziale si invita la Cittadinanza a segnalare eventuali criticit\u00e0 o suggerimenti per contribuire a migliorare la pianificazione del servizio e a rendere il TPL sempre pi\u00f9 efficiente e funzionale.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">L&#8217;Amministrazione sta monitorando le nuove linee e i percorsi per inoltrare alla Regione Lazio ed Astral eventuali richieste di adeguamento sulla base delle effettive necessit\u00e0 degli utenti.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Sono previsti tre differenti tipi di biglietti: &#8211; Biglietto semplice 100 (\u20ac 1,10)<\/div>\n<div dir=\"auto\">Durata: 100 minuti oppure una corsa semplice Cotral<\/div>\n<div dir=\"auto\">Validit\u00e0: utilizzabile su 1 operatore UDR per 100 minuti oppure per una corsa Cotral fino a 10 km<\/div>\n<div dir=\"auto\">Biglietto semplice 100 on board (\u20ac 2,00)<\/div>\n<div dir=\"auto\">Durata: 100 minuti<\/div>\n<div dir=\"auto\">Validit\u00e0: solo su 1 operatore UDR (acquistato a bordo)<\/div>\n<div dir=\"auto\">Biglietto integrato UDR-Cotral Rete 10\/100 (\u20ac 2,10)<\/div>\n<div dir=\"auto\">Durata: 100 minuti + una corsa semplice Cotral<\/div>\n<div dir=\"auto\">Validit\u00e0: valido su 1 operatore UDR + una corsa Cotral fino a 10 km<\/div>\n<div dir=\"auto\">Le tipologie di abbonamento presenti sono le seguenti: Mensile \u20ac 30,00 &#8211; \u20ac 26,00 con Metrebus Lazio)<\/div>\n<div dir=\"auto\">Validit\u00e0: 1 mese solare<\/div>\n<div dir=\"auto\">Utilizzabile per un&#8217;unica Unit\u00e0 di Rete<\/div>\n<div dir=\"auto\">Annuale \u20ac 210,00 &#8211; \u20ac 180,00 con Metrebus Lazio)<\/div>\n<div dir=\"auto\">Validit\u00e0: 365 giorni dalla data di acquisto<\/div>\n<div dir=\"auto\">Utilizzabile per un&#8217;unica Unit\u00e0 di Rete<\/div>\n<div dir=\"auto\">Annuale studenti \u20ac 175,00 &#8211; \u20ac 150,00 con Metrebus Lazio)<\/div>\n<div dir=\"auto\">Validit\u00e0: 10 mesi (settembre-giugno)<\/div>\n<div dir=\"auto\">Utilizzabile per un&#8217;unica Unit\u00e0 di Rete<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Per informazioni aggiornate su linee, orari e servizi \u00e8 possibile consultare il seguente link:<\/div>\n<div dir=\"auto\"><span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n x18oe1m7 x1sy0etr xstzfhl x972fbf x10w94by x1qhh985 x14e42zd x9f619 x1ypdohk xt0psk2 x3ct3a4 xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj x1fey0fg x1s688f\" role=\"link\" href=\"https:\/\/udr.astralspa.it\/wp-content\/uploads\/2025\/12\/UdR5_Orario-scolastico_e_percorsi.pdf?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBEwekd0cFRReGJNempscEVETnNydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR4jSPDH9xTIphkvZ966fPb446rNDDQnW5xMG5Jb_buvbOUdwak7QEXllEn7yg_aem_oG2SrveeRiax_iPYy0LJmw\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/udr.astralspa.it\/&#8230;\/UdR5_Orario-scolastico_e&#8230;<\/a><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"_r_7r_\" class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1n2onr6\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1n2onr6\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"x1n2onr6\">\n<div class=\"x1n2onr6\">\n<div class=\"x6ikm8r x10wlt62 x10l6tqk\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si ricorda che, in tutto il Lazio, compreso il territorio di Tivoli, la gestione del Trasporto Pubblico Locale (TPL) \u00e8 passata dai Comuni alla Regione Lazio, tramite Astral. Il cambiamento [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":15121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-15120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasporto pubblico regionale: la gestione alla Regione Lazio - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasporto pubblico regionale: la gestione alla Regione Lazio - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si ricorda che, in tutto il Lazio, compreso il territorio di Tivoli, la gestione del Trasporto Pubblico Locale (TPL) \u00e8 passata dai Comuni alla Regione Lazio, tramite Astral. Il cambiamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T17:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/tpl-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1006\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Trasporto pubblico regionale: la gestione alla Regione Lazio\",\"datePublished\":\"2026-01-08T17:57:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/\"},\"wordCount\":257,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/tpl-1.jpeg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/\",\"name\":\"Trasporto pubblico regionale: la gestione alla Regione Lazio - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/tpl-1.jpeg\",\"datePublished\":\"2026-01-08T17:57:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/tpl-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/tpl-1.jpeg\",\"width\":1006,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/08\\\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasporto pubblico regionale: la gestione alla Regione Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasporto pubblico regionale: la gestione alla Regione Lazio - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Trasporto pubblico regionale: la gestione alla Regione Lazio - Tivoli","og_description":"Si ricorda che, in tutto il Lazio, compreso il territorio di Tivoli, la gestione del Trasporto Pubblico Locale (TPL) \u00e8 passata dai Comuni alla Regione Lazio, tramite Astral. Il cambiamento [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-08T17:57:12+00:00","og_image":[{"width":1006,"height":1440,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/tpl-1.jpeg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Trasporto pubblico regionale: la gestione alla Regione Lazio","datePublished":"2026-01-08T17:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/"},"wordCount":257,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/tpl-1.jpeg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/","url":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/","name":"Trasporto pubblico regionale: la gestione alla Regione Lazio - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/tpl-1.jpeg","datePublished":"2026-01-08T17:57:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/tpl-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/tpl-1.jpeg","width":1006,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/08\/trasporto-pubblico-regionale-la-gestione-alla-regione-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Trasporto pubblico regionale: la gestione alla Regione Lazio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=15120"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15120\/revisions"}],"predecessor-version":[{"id":15122,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15120\/revisions\/15122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/15121"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=15120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=15120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=15120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}