{"id":15130,"date":"2026-01-13T08:20:11","date_gmt":"2026-01-13T07:20:11","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=15130"},"modified":"2026-01-13T08:20:11","modified_gmt":"2026-01-13T07:20:11","slug":"svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/","title":{"rendered":"Svincolo di Castel Madama Autostrada A24 &#8211; Modifiche alla viabilit\u00e0"},"content":{"rendered":"<p>Dalle ore 8.00 di mercoled\u00ec 14 gennaio alle ore 18.00 di venerd\u00ec 16 gennaio lo svincolo di Castel Madama dell\u2019autostrada A24 sar\u00e0 chiuso per lavori urgenti e inderogabili di manutenzione sulla carreggiata ovest (direzione Roma), limitatamente all\u2019uscita verso la viabilit\u00e0 ordinaria.<\/p>\n<p>Lo stop alla circolazione \u00e8 richiesto da lavori di manutenzione non rinviabili lungo il tratto interessato dello svincolo di Castel Madama, sulla A24 Roma\u2013L\u2019Aquila\u2013Teramo. Il provvedimento \u00e8 stato comunicato da Strada dei Parchi S.p.A. agli enti competenti, tra cui il Comune di Tivoli.<\/p>\n<p>Nelle date e negli orari indicati non sar\u00e0 possibile uscire a Castel Madama per i veicoli provenienti dalla carreggiata ovest della A24, direzione Roma, e diretti sulla viabilit\u00e0 ordinaria. In alternativa, agli automobilisti viene consigliato di utilizzare lo svincolo di Vicovaro\u2013Mandela e proseguire sulla SS5 Tiburtina Valeria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle ore 8.00 di mercoled\u00ec 14 gennaio alle ore 18.00 di venerd\u00ec 16 gennaio lo svincolo di Castel Madama dell\u2019autostrada A24 sar\u00e0 chiuso per lavori urgenti e inderogabili di manutenzione [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":15128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-15130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Svincolo di Castel Madama Autostrada A24 - Modifiche alla viabilit\u00e0 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Svincolo di Castel Madama Autostrada A24 - Modifiche alla viabilit\u00e0 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dalle ore 8.00 di mercoled\u00ec 14 gennaio alle ore 18.00 di venerd\u00ec 16 gennaio lo svincolo di Castel Madama dell\u2019autostrada A24 sar\u00e0 chiuso per lavori urgenti e inderogabili di manutenzione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T07:20:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/FB_IMG_1767970634601.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Svincolo di Castel Madama Autostrada A24 &#8211; Modifiche alla viabilit\u00e0\",\"datePublished\":\"2026-01-13T07:20:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/\"},\"wordCount\":143,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/FB_IMG_1767970634601.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/\",\"name\":\"Svincolo di Castel Madama Autostrada A24 - Modifiche alla viabilit\u00e0 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/FB_IMG_1767970634601.jpg\",\"datePublished\":\"2026-01-13T07:20:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/FB_IMG_1767970634601.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/FB_IMG_1767970634601.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/01\\\/13\\\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Svincolo di Castel Madama Autostrada A24 &#8211; Modifiche alla viabilit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Svincolo di Castel Madama Autostrada A24 - Modifiche alla viabilit\u00e0 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/","og_locale":"it_IT","og_type":"article","og_title":"Svincolo di Castel Madama Autostrada A24 - Modifiche alla viabilit\u00e0 - Tivoli","og_description":"Dalle ore 8.00 di mercoled\u00ec 14 gennaio alle ore 18.00 di venerd\u00ec 16 gennaio lo svincolo di Castel Madama dell\u2019autostrada A24 sar\u00e0 chiuso per lavori urgenti e inderogabili di manutenzione [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-13T07:20:11+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/FB_IMG_1767970634601.jpg","type":"image\/jpeg"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Svincolo di Castel Madama Autostrada A24 &#8211; Modifiche alla viabilit\u00e0","datePublished":"2026-01-13T07:20:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/"},"wordCount":143,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/FB_IMG_1767970634601.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/","url":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/","name":"Svincolo di Castel Madama Autostrada A24 - Modifiche alla viabilit\u00e0 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/FB_IMG_1767970634601.jpg","datePublished":"2026-01-13T07:20:11+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/FB_IMG_1767970634601.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/FB_IMG_1767970634601.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/01\/13\/svincolo-di-castel-madama-autostrada-a24-modifiche-alla-viabilita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Svincolo di Castel Madama Autostrada A24 &#8211; Modifiche alla viabilit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=15130"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15130\/revisions"}],"predecessor-version":[{"id":15131,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15130\/revisions\/15131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/15128"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=15130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=15130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=15130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}