{"id":15238,"date":"2026-02-01T11:08:06","date_gmt":"2026-02-01T10:08:06","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=15238"},"modified":"2026-02-01T11:08:06","modified_gmt":"2026-02-01T10:08:06","slug":"modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/","title":{"rendered":"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore"},"content":{"rendered":"<p>Si informa la cittadinanza che nei prossimi giorni saranno introdotte modifiche temporanee alla circolazione stradale in alcune zone del territorio comunale per consentire l\u2019esecuzione di lavori di rifacimento del manto stradale e la realizzazione della nuova rete di pubblica illuminazione. Gli interventi, richiesti da ASTRAL S.p.A., rientrano in un pi\u00f9 ampio programma di messa in sicurezza della sede viaria e si rendono necessari per migliorare le condizioni di percorrenza e la sicurezza stradale.<\/p>\n<p>In particolare, i lavori interesseranno Piazza Padre Pio e Strada San Pastore e comporteranno una temporanea revisione della disciplina del traffico, al fine di permettere lo svolgimento delle operazioni in condizioni di piena sicurezza sia per gli addetti ai lavori sia per gli utenti della strada.<\/p>\n<p>In Piazza Padre Pio, nelle giornate di luned\u00ec 2 e marted\u00ec 3 febbraio 2026, nella fascia oraria compresa tra le ore 7.00 e le ore 16.00, sul lato destro della piazza rispetto al senso di marcia da via Casal Bellini verso via San Francesco d\u2019Assisi, sar\u00e0 vietato il transito e la sosta dei veicoli, con rimozione forzata. Il divieto non si applica ai mezzi impegnati nell\u2019esecuzione dei lavori.<\/p>\n<p>Su Strada San Pastore, invece, dal 4 al 24 febbraio 2026, dal luned\u00ec al venerd\u00ec ed esclusi i giorni festivi, nella fascia oraria 7.00\u201316.00, sar\u00e0 istituito il divieto di transito e di sosta con rimozione forzata nel tratto compreso tra l\u2019intersezione con Strada Colle Nocello e il ponticello situato a monte dell\u2019incrocio. Anche in questo caso, potranno transitare esclusivamente i mezzi d\u2019opera della ditta incaricata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa la cittadinanza che nei prossimi giorni saranno introdotte modifiche temporanee alla circolazione stradale in alcune zone del territorio comunale per consentire l\u2019esecuzione di lavori di rifacimento del manto [&hellip;]<\/p>\n","protected":false},"author":412,"featured_media":15149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-15238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si informa la cittadinanza che nei prossimi giorni saranno introdotte modifiche temporanee alla circolazione stradale in alcune zone del territorio comunale per consentire l\u2019esecuzione di lavori di rifacimento del manto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T10:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/MODIFICHE-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"segreteriasindaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteriasindaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/\"},\"author\":{\"name\":\"segreteriasindaco\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"headline\":\"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore\",\"datePublished\":\"2026-02-01T10:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/\"},\"wordCount\":261,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/MODIFICHE-1.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/\",\"name\":\"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/MODIFICHE-1.png\",\"datePublished\":\"2026-02-01T10:08:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/MODIFICHE-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2026\\\/01\\\/MODIFICHE-1.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2026\\\/02\\\/01\\\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/7f572a0c75c72ccc7dd760a17ff34e17\",\"name\":\"segreteriasindaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g\",\"caption\":\"segreteriasindaco\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/segreteriasindaco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/","og_locale":"it_IT","og_type":"article","og_title":"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore - Tivoli","og_description":"Si informa la cittadinanza che nei prossimi giorni saranno introdotte modifiche temporanee alla circolazione stradale in alcune zone del territorio comunale per consentire l\u2019esecuzione di lavori di rifacimento del manto [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-01T10:08:06+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/MODIFICHE-1.png","type":"image\/png"}],"author":"segreteriasindaco","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteriasindaco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/"},"author":{"name":"segreteriasindaco","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"headline":"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore","datePublished":"2026-02-01T10:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/"},"wordCount":261,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/MODIFICHE-1.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/","url":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/","name":"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/MODIFICHE-1.png","datePublished":"2026-02-01T10:08:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/MODIFICHE-1.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2026\/01\/MODIFICHE-1.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2026\/02\/01\/modifiche-alla-viabilita-piazza-padre-pio-e-strada-san-pastore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Modifiche alla viabilit\u00e0: piazza Padre Pio e strada San Pastore"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/7f572a0c75c72ccc7dd760a17ff34e17","name":"segreteriasindaco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5c82a36d8f0aa7110c6ad839662d62e4c49252a225dd9dfba53a0c2f37ad69e?s=96&d=mm&r=g","caption":"segreteriasindaco"},"url":"https:\/\/comunicacity.net\/tivoli\/author\/segreteriasindaco\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/412"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=15238"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15238\/revisions"}],"predecessor-version":[{"id":15239,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/15238\/revisions\/15239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/15149"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=15238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=15238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=15238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}