{"id":1535,"date":"2018-03-15T14:10:38","date_gmt":"2018-03-15T13:10:38","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1535"},"modified":"2018-03-15T14:10:38","modified_gmt":"2018-03-15T13:10:38","slug":"lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/","title":{"rendered":"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA"},"content":{"rendered":"<div class=\"\">\n<div class=\"_1mf _1mj\"><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Citt\u00e0 Metropolitana di Roma Capitale, gestore della strada, informa che dalle ore 22 di domenica 18 marzo e fino alle ore 6 di sabato 31 marzo sar\u00e0 chiusa al traffico per tutti i mezzi la strada provinciale che collega Tivoli a Marcellina (SP 31a).<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>La totale interdizione al traffico veicolare \u00e8 stata disposta per permettere a RFI, gestore della rete ferroviaria, la realizzazione di urgenti lavori di messa in sicurezza e ristrutturazione del viadotto che si trova al km 37,140 della linea ferroviaria Roma \u2013 Sulmona.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>La strada rester\u00e0 aperta solo per il traffico locale nel tratto compreso tra piazza Massimo e l\u2019incrocio con via Maria Santissima di Quintiliolo, che rester\u00e0 raggiungibile e percorribile in entrambe le direzioni. Pi\u00f9 in particolare, da Tivoli centro in direzione Marcellina si potr\u00e0 arrivare fino via Maria Santissima di Quintiliolo e percorrerla verso valle; in direzione contraria, si potr\u00e0 salire da valle lungo via Maria Santissima di Quintiliolo con obbligo di svolta a destra in direzione Tivoli piazza Massimo una volta raggiunta la strada provinciale 31a.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Allo stesso tempo, da Marcellina non sar\u00e0 possibile raggiungere Tivoli percorrendo la strada provinciale, chiusa al km 2,100 (il blocco si trova, in direzione Tivoli, poco prima dell\u2019incrocio con via Maria Santissima di Quintiliolo).<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>La disposizione riguarda anche i collegamenti Cotral tra Tivoli, Marcellina e Palombara: tutte le corse, nel periodo dei lavori, vengono deviate per Guidonia sia all\u2019andata sia al ritorno.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Tivoli, 15 marzo 2018<\/span><\/div>\n<\/div>\n<div class=\"\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Citt\u00e0 Metropolitana di Roma Capitale, gestore della strada, informa che dalle ore 22 di domenica 18 marzo e fino alle ore 6 di sabato 31 marzo sar\u00e0 chiusa al traffico [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Citt\u00e0 Metropolitana di Roma Capitale, gestore della strada, informa che dalle ore 22 di domenica 18 marzo e fino alle ore 6 di sabato 31 marzo sar\u00e0 chiusa al traffico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-15T13:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA\",\"datePublished\":\"2018-03-15T13:10:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/\"},\"wordCount\":245,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/\",\"name\":\"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"datePublished\":\"2018-03-15T13:10:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/03\\\/15\\\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/","og_locale":"it_IT","og_type":"article","og_title":"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA - Tivoli","og_description":"Citt\u00e0 Metropolitana di Roma Capitale, gestore della strada, informa che dalle ore 22 di domenica 18 marzo e fino alle ore 6 di sabato 31 marzo sar\u00e0 chiusa al traffico [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-03-15T13:10:38+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA","datePublished":"2018-03-15T13:10:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/"},"wordCount":245,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/","name":"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","datePublished":"2018-03-15T13:10:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/03\/15\/lavori-rete-ferroviaria-dal-18-al-31-marzo-chiusa-la-strada-che-collega-tivoli-a-marcellina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"LAVORI RETE FERROVIARIA, DAL 18 AL 31 MARZO CHIUSA LA STRADA CHE COLLEGA TIVOLI A MARCELLINA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"predecessor-version":[{"id":1536,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1535\/revisions\/1536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/832"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}