{"id":1618,"date":"2018-04-18T10:18:34","date_gmt":"2018-04-18T08:18:34","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1618"},"modified":"2018-04-18T10:18:34","modified_gmt":"2018-04-18T08:18:34","slug":"variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/","title":{"rendered":"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA"},"content":{"rendered":"<p>A causa di esigenze di cantiere e di viabilit\u00e0 relative ai lavori avviati oggi in via Acquaregna, la polizia locale ha appena disposto una prima variazione alle modifiche alla viabilit\u00e0 comunicate ieri. Pertanto la prima fase dei lavori, che riguarda il tratto di via Acquaregna compreso tra largo San Giovanni e vicolo Empolitano, viene divisa in due step. Il primo step della prima fase riguarder\u00e0 soltanto il tratto di via Acquaregna compreso tra vicolo Empolitano e vicolo Acquaregna.<\/p>\n<p>Pertanto da questa mattina (mercoled\u00ec 18 aprile) fino al termine del primo step della prima fase sono in vigore le seguenti modifiche alla viabilit\u00e0 (in sostituzione di quelle diffuse ieri):<\/p>\n<ul>\n<li>Tutti i giorni della settimana compresi sabato e domenica (per tutte le 24 ore della giornata) via Acquaregna sar\u00e0 percorribile solo per il traffico locale fino all\u2019incrocio con vicolo Empolitano, da cui sar\u00e0 possibile raggiungere via Empolitana;<\/li>\n<li>Resta percorribile e aperto al traffico h24 il tratto di via Acquaregna compreso tra vicolo Acquaregna e largo San Giovanni, raggiungibile da via Empolitana attraverso vicolo Acquaregna, in cui rimane invariato il senso unico a scendere;<\/li>\n<li>gli autobus di linea provenienti da largo Saragat (cimitero) sono deviati h24 per via Tiburto, fino a piazza Garibaldi, anche nei giorni di sabato e domenica ;<\/li>\n<li>restano confermati l\u2019obbligo di svolta a destra al termine della rampa in salita che porta a via Roma (nei pressi dell\u2019ospedale) per i veicoli che provengono dal parcheggio del lunganiene Impastato e il divieto di svolta a sinistra in prossimit\u00e0 della discesa verso il lunganiene Impastato per i veicoli provenienti da via Roma in direzione largo San Giovanni.<\/li>\n<li>In viale Mannelli resta il divieto di sosta h24 sull\u2019intero lato destro in direzione piazza Garibaldi.<\/li>\n<\/ul>\n<p>Eventuali\u00a0 ulteriori modifiche saranno comunicate attraverso i mezzi di informazione del Comune di Tivoli: la app \u201cComunicacity\u201d, il sito <a href=\"http:\/\/www.comune.tivoli.rm.it\">www.comune.tivoli.rm.it<\/a> e la pagina face book ufficiale Comune di Tivoli Palazzo San Bernardino.<\/p>\n<p>Per ulteriori informazioni sulla viabilit\u00e0: Comando Polizia locale 0774453501.<\/p>\n<p>Tivoli, 18 aprile 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa di esigenze di cantiere e di viabilit\u00e0 relative ai lavori avviati oggi in via Acquaregna, la polizia locale ha appena disposto una prima variazione alle modifiche alla viabilit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA - Tivoli\" \/>\n<meta property=\"og:description\" content=\"A causa di esigenze di cantiere e di viabilit\u00e0 relative ai lavori avviati oggi in via Acquaregna, la polizia locale ha appena disposto una prima variazione alle modifiche alla viabilit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-18T08:18:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA\",\"datePublished\":\"2018-04-18T08:18:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/\"},\"wordCount\":340,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/\",\"name\":\"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"datePublished\":\"2018-04-18T08:18:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"width\":921,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/04\\\/18\\\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/","og_locale":"it_IT","og_type":"article","og_title":"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA - Tivoli","og_description":"A causa di esigenze di cantiere e di viabilit\u00e0 relative ai lavori avviati oggi in via Acquaregna, la polizia locale ha appena disposto una prima variazione alle modifiche alla viabilit\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-04-18T08:18:34+00:00","og_image":[{"width":921,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA","datePublished":"2018-04-18T08:18:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/"},"wordCount":340,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/","name":"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","datePublished":"2018-04-18T08:18:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","width":921,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/04\/18\/variazione-alle-modifiche-alla-viabilita-per-i-lavori-in-via-acquaregna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"VARIAZIONE ALLE MODIFICHE ALLA VIABILITA\u2019 PER I LAVORI IN VIA ACQUAREGNA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1618"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1618\/revisions"}],"predecessor-version":[{"id":1619,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1618\/revisions\/1619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}