{"id":1794,"date":"2018-06-04T11:32:44","date_gmt":"2018-06-04T09:32:44","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1794"},"modified":"2018-06-04T11:32:44","modified_gmt":"2018-06-04T09:32:44","slug":"viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/","title":{"rendered":"VIABILITA&#8217;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL"},"content":{"rendered":"<p>Sono segnalati in via Tiburtina Valeria, nei pressi del comando della polizia locale, rallentamenti al traffico in entrambe le direzioni per la riparazione urgente da parte di Enel di un guasto alla linea elettrica.<\/p>\n<p>Fino al termine dei lavori, nel tratto interessato dal cantiere si procede a senso unico alternato.<\/p>\n<p>Tivoli, 4 giugno 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono segnalati in via Tiburtina Valeria, nei pressi del comando della polizia locale, rallentamenti al traffico in entrambe le direzioni per la riparazione urgente da parte di Enel di un [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIABILITA&#039;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIABILITA&#039;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sono segnalati in via Tiburtina Valeria, nei pressi del comando della polizia locale, rallentamenti al traffico in entrambe le direzioni per la riparazione urgente da parte di Enel di un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-04T09:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"VIABILITA&#8217;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL\",\"datePublished\":\"2018-06-04T09:32:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/\"},\"wordCount\":63,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/\",\"name\":\"VIABILITA', TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"datePublished\":\"2018-06-04T09:32:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-2.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/04\\\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIABILITA&#8217;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIABILITA', TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/","og_locale":"it_IT","og_type":"article","og_title":"VIABILITA', TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL - Tivoli","og_description":"Sono segnalati in via Tiburtina Valeria, nei pressi del comando della polizia locale, rallentamenti al traffico in entrambe le direzioni per la riparazione urgente da parte di Enel di un [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-06-04T09:32:44+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"VIABILITA&#8217;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL","datePublished":"2018-06-04T09:32:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/"},"wordCount":63,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/","name":"VIABILITA', TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","datePublished":"2018-06-04T09:32:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-2.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/04\/viabilita-traffico-rallentato-in-via-valeria-per-riparazione-urgente-guasto-enel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"VIABILITA&#8217;, TRAFFICO RALLENTATO IN VIA VALERIA PER RIPARAZIONE URGENTE GUASTO ENEL"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1794"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1794\/revisions"}],"predecessor-version":[{"id":1795,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1794\/revisions\/1795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/832"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}