{"id":1817,"date":"2018-06-07T18:46:47","date_gmt":"2018-06-07T16:46:47","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1817"},"modified":"2018-06-07T18:46:47","modified_gmt":"2018-06-07T16:46:47","slug":"palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/","title":{"rendered":"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Partono luned\u00ec 18 giugno i lavori di recupero del Palazzetto dello sport &#8220;Paolo Tosto&#8221; agli Arci. L&#8217;intervento \u00e8 stato progettato, finanziato e appaltato, a seguito della relativa gara pubblica,dal Comune di Tivoli, per un importo di circa 460mila euro.<\/p>\n<p>Le opere in fase di realizzazione consistono nell&#8217;abbattimento e nella ricostruzione dell&#8217;intera parete di fondo, oggetto da quasi dieci anni di un cedimento che rendeva inutilizzabile l&#8217;intero impianto. Inoltre sar\u00e0 realizzato un nuovo pavimento interno, che permetter\u00e0 la pratica di tutte le discipline sportive, comprese il pattinaggio e l&#8217;hockey. Infine saranno ripristinati tutti gli impianti, danneggiati prima del 2014 da furti e atti vandalici.<\/p>\n<p>I lavori dovrebbero essere completati in circa cinque mesi, in modo che l&#8217;impianto possa essere utilizzato fin dalla prossima stagione sportiva agonistica.<\/p>\n<p>Tivoli, 7 giugno 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Partono luned\u00ec 18 giugno i lavori di recupero del Palazzetto dello sport &#8220;Paolo Tosto&#8221; agli Arci. L&#8217;intervento \u00e8 stato progettato, finanziato e appaltato, a seguito della relativa gara pubblica,dal [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":1818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO - Tivoli\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Partono luned\u00ec 18 giugno i lavori di recupero del Palazzetto dello sport &#8220;Paolo Tosto&#8221; agli Arci. L&#8217;intervento \u00e8 stato progettato, finanziato e appaltato, a seguito della relativa gara pubblica,dal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-07T16:46:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/06\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO\",\"datePublished\":\"2018-06-07T16:46:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/\"},\"wordCount\":138,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/06\\\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/\",\"name\":\"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/06\\\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg\",\"datePublished\":\"2018-06-07T16:46:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/06\\\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/06\\\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/06\\\/07\\\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/","og_locale":"it_IT","og_type":"article","og_title":"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO - Tivoli","og_description":"&nbsp; Partono luned\u00ec 18 giugno i lavori di recupero del Palazzetto dello sport &#8220;Paolo Tosto&#8221; agli Arci. L&#8217;intervento \u00e8 stato progettato, finanziato e appaltato, a seguito della relativa gara pubblica,dal [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-06-07T16:46:47+00:00","og_image":[{"width":700,"height":400,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/06\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO","datePublished":"2018-06-07T16:46:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/"},"wordCount":138,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/06\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/","name":"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/06\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg","datePublished":"2018-06-07T16:46:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/06\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/06\/lavori-per-gli-impianti-sportivi-di-tivoli.jpg","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/06\/07\/palazzetto-dello-sport-agli-arci-al-via-i-lavori-per-il-recupero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"PALAZZETTO DELLO SPORT AGLI ARCI, AL VIA I LAVORI PER IL RECUPERO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1817"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1817\/revisions"}],"predecessor-version":[{"id":1819,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1817\/revisions\/1819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/1818"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}