{"id":1973,"date":"2018-07-12T13:40:41","date_gmt":"2018-07-12T11:40:41","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=1973"},"modified":"2018-07-12T13:40:41","modified_gmt":"2018-07-12T11:40:41","slug":"da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/","title":{"rendered":"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE"},"content":{"rendered":"<p>Da luned\u00ec 16 luglio saranno avviate le attivit\u00e0 di ripavimentazione di viale Mazzini, al termine dei lavori di realizzazione della nuova rete fognaria da parte di Acea.<\/p>\n<p>Il tratto interessato dai lavori \u00e8 quello compreso tra la sede dell\u2019Inps e l\u2019inizio di via Sant\u2019Agnese e comprende pertanto anche il piazzale della stazione ferroviaria e i relativi parcheggi. In tutta l\u2019area di cantiere, dalle ore 8 di luned\u00ec 16 luglio e fino al termine dei lavori (fissato a venerd\u00ec 20 luglio salvo imprevisti) sar\u00e0 in vigore il divieto di sosta.<\/p>\n<p>I cittadini che abitualmente utilizzano i parcheggi in viale Mazzini e nei pressi della stazione possono utilizzare in alternativa l\u2019area del lunganiene Impastato, anche nella giornata di mercoled\u00ec (il mercato settimanale al lunganiene si svolge la domenica fino al termine dei lavori in via Acquaregna).<\/p>\n<p>Per informazioni: Comando Polizia locale 0774453501.<\/p>\n<p>Tivoli, 12 luglio 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da luned\u00ec 16 luglio saranno avviate le attivit\u00e0 di ripavimentazione di viale Mazzini, al termine dei lavori di realizzazione della nuova rete fognaria da parte di Acea. Il tratto interessato [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Da luned\u00ec 16 luglio saranno avviate le attivit\u00e0 di ripavimentazione di viale Mazzini, al termine dei lavori di realizzazione della nuova rete fognaria da parte di Acea. Il tratto interessato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-12T11:40:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE\",\"datePublished\":\"2018-07-12T11:40:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/\"},\"wordCount\":154,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/\",\"name\":\"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"datePublished\":\"2018-07-12T11:40:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"width\":921,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/07\\\/12\\\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/","og_locale":"it_IT","og_type":"article","og_title":"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE - Tivoli","og_description":"Da luned\u00ec 16 luglio saranno avviate le attivit\u00e0 di ripavimentazione di viale Mazzini, al termine dei lavori di realizzazione della nuova rete fognaria da parte di Acea. Il tratto interessato [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-07-12T11:40:41+00:00","og_image":[{"width":921,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE","datePublished":"2018-07-12T11:40:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/"},"wordCount":154,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/","name":"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","datePublished":"2018-07-12T11:40:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","width":921,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/07\/12\/da-lunedi-16-luglio-lavori-di-ripavimentazione-in-viale-mazzini-e-piazzale-della-stazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"DA LUNEDI\u2019 16 LUGLIO LAVORI DI RIPAVIMENTAZIONE IN VIALE MAZZINI E PIAZZALE DELLA STAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=1973"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1973\/revisions"}],"predecessor-version":[{"id":1974,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/1973\/revisions\/1974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=1973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=1973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=1973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}