{"id":2095,"date":"2018-09-07T14:20:10","date_gmt":"2018-09-07T12:20:10","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=2095"},"modified":"2018-09-07T14:20:10","modified_gmt":"2018-09-07T12:20:10","slug":"domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/","title":{"rendered":"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI"},"content":{"rendered":"<p>Una gara podistica con un percorso che unisce i luoghi pi\u00f9 belli della citt\u00e0, tra cui il tempio di Ercole Vincitore, Villa d\u2019Este e l\u2019area archeologica di Villa Adriana. E\u2019 la quarta edizione del Trofeo Fabrizio Irilli, manifestazione organizzata da Tivoli Marathon con il patrocinio del Comune di Tivoli, in programma domenica 9 settembre.<\/p>\n<p>Il ritrovo per gli atleti \u00e8 fissato alle ore 7.30 a Villa Adriana\u00a0 nel parcheggio in via Lago di Annone., con partenza prevista alle ore 9:30.<\/p>\n<p>Per la gara competitiva di 11 chilometri la quota di iscrizione \u00e8 di 12 euro con pacco gara assicurato ai primi 400. Gruppi e singoli possono iscriversi\u00a0 inviando una mail a <a href=\"mailto:info@raceservice.it\">info@raceservice.it<\/a> .<\/p>\n<p>Per la gara non competitiva di 3 chilometri ci si iscrive sul posto, quota 6 euro.<\/p>\n<p>Il pagamento delle quote di iscrizione avviene contestualmente al ritiro del pettorale e pacco gara.<\/p>\n<p><strong><u>Informazioni sulle modifiche alla viabilit\u00e0 relative alla manifestazione<\/u><\/strong><\/p>\n<p>Saranno temporaneamente chiuse al transito veicolare le strade direttamente interessate dalla manifestazione e relative intersezioni nell\u2019arco temporale\u00a0 compreso tra le ore 9:30 e le ore 11:00. La sospensione della circolazione sar\u00e0 attuata nelle seguenti vie in modo cadenzato secondo l\u2019incedere della\u00a0 corsa deviando il traffico, ove possibile, su percorsi alternativi:<\/p>\n<p><em>Via Imperatore Adriano \u2013 Via Lago di Misurina \u2013 Via di Villa Adriana \u2013 Via Orazio Coccanari \u2013 Via Paterno \u2013 Strada Acquoria \u2013 Strada degli Orti \u2013 Via degli Stabilimenti \u2013 Via del Colle \u2013 Via della Missione \u2013 Via Vincenzo Pacifici \u2013 Strada Pisoni \u2013 Via del Tramvai \u2013 Largo Margherita Youcenar \u2013 Strada Roccabruna \u2013 Via Galli \u2013 Via Puglie.<\/em><\/p>\n<p><strong>Tivoli, 7 settembre 2018<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una gara podistica con un percorso che unisce i luoghi pi\u00f9 belli della citt\u00e0, tra cui il tempio di Ercole Vincitore, Villa d\u2019Este e l\u2019area archeologica di Villa Adriana. E\u2019 [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":2096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Una gara podistica con un percorso che unisce i luoghi pi\u00f9 belli della citt\u00e0, tra cui il tempio di Ercole Vincitore, Villa d\u2019Este e l\u2019area archeologica di Villa Adriana. E\u2019 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-07T12:20:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/09\/trofeo-fabrizio-Irilli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"629\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI\",\"datePublished\":\"2018-09-07T12:20:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/\"},\"wordCount\":257,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/09\\\/trofeo-fabrizio-Irilli.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/\",\"name\":\"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/09\\\/trofeo-fabrizio-Irilli.jpg\",\"datePublished\":\"2018-09-07T12:20:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/09\\\/trofeo-fabrizio-Irilli.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2018\\\/09\\\/trofeo-fabrizio-Irilli.jpg\",\"width\":629,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/09\\\/07\\\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/","og_locale":"it_IT","og_type":"article","og_title":"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI - Tivoli","og_description":"Una gara podistica con un percorso che unisce i luoghi pi\u00f9 belli della citt\u00e0, tra cui il tempio di Ercole Vincitore, Villa d\u2019Este e l\u2019area archeologica di Villa Adriana. E\u2019 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-09-07T12:20:10+00:00","og_image":[{"width":629,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/09\/trofeo-fabrizio-Irilli.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI","datePublished":"2018-09-07T12:20:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/"},"wordCount":257,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/09\/trofeo-fabrizio-Irilli.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/","name":"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/09\/trofeo-fabrizio-Irilli.jpg","datePublished":"2018-09-07T12:20:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/09\/trofeo-fabrizio-Irilli.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2018\/09\/trofeo-fabrizio-Irilli.jpg","width":629,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/09\/07\/domenica-a-tivoli-il-trofeo-irilli-la-gara-podistica-nei-monumenti-cittadini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"DOMENICA A TIVOLI IL TROFEO IRILLI, LA GARA PODISTICA NEI MONUMENTI CITTADINI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=2095"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2095\/revisions"}],"predecessor-version":[{"id":2097,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2095\/revisions\/2097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/2096"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=2095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=2095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=2095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}