{"id":2363,"date":"2018-12-02T12:50:36","date_gmt":"2018-12-02T11:50:36","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=2363"},"modified":"2018-12-03T10:03:38","modified_gmt":"2018-12-03T09:03:38","slug":"chiusa-al-traffico-strada-tivoli-marcellina-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/","title":{"rendered":"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA"},"content":{"rendered":"<p>La strada privinciale Tivoli Marcellina \u00e8 stata chiusa al traffico all&#8217;altezza del km 1 a causa del cedimento di un muro di contenimento ai margini della sede stradale. In entrambe le direzioni \u00e8 consentito solo il traffico locale non di attraversamento. Non \u00e8 consentito pertanto a chi proviene da Tivoli centro raggiungere l&#8217;incrocio con la strada di Quintiliolo, allo stesso modo chi sale dalla zona di Colle Nocello passando per la strada di Quintiliolo non pu\u00f2 raggiungere il centro cittadino. In attesa dei lavori di ripristino, i bus Cotral che percorrono abitualmente la strada Tivoli Marcellina vengono deviati per Villanova di Guidonia.<\/p>\n<p>Per informazioni: Polizia locale 0774453501.<\/p>\n<p>Tivoli, 2 dicembre 2018 &#8211; ufficio stampa e informazione<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La strada privinciale Tivoli Marcellina \u00e8 stata chiusa al traffico all&#8217;altezza del km 1 a causa del cedimento di un muro di contenimento ai margini della sede stradale. In entrambe [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA - Tivoli\" \/>\n<meta property=\"og:description\" content=\"La strada privinciale Tivoli Marcellina \u00e8 stata chiusa al traffico all&#8217;altezza del km 1 a causa del cedimento di un muro di contenimento ai margini della sede stradale. In entrambe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-02T11:50:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-03T09:03:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"274\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA\",\"datePublished\":\"2018-12-02T11:50:36+00:00\",\"dateModified\":\"2018-12-03T09:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/\"},\"wordCount\":116,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/\",\"name\":\"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"datePublished\":\"2018-12-02T11:50:36+00:00\",\"dateModified\":\"2018-12-03T09:03:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/05\\\/stemam-comune.jpg\",\"width\":274,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2018\\\/12\\\/02\\\/chiusa-al-traffico-strada-tivoli-marcellina-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/","og_locale":"it_IT","og_type":"article","og_title":"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA - Tivoli","og_description":"La strada privinciale Tivoli Marcellina \u00e8 stata chiusa al traffico all&#8217;altezza del km 1 a causa del cedimento di un muro di contenimento ai margini della sede stradale. In entrambe [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-12-02T11:50:36+00:00","article_modified_time":"2018-12-03T09:03:38+00:00","og_image":[{"width":274,"height":385,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA","datePublished":"2018-12-02T11:50:36+00:00","dateModified":"2018-12-03T09:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/"},"wordCount":116,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/","url":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/","name":"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","datePublished":"2018-12-02T11:50:36+00:00","dateModified":"2018-12-03T09:03:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/05\/stemam-comune.jpg","width":274,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2018\/12\/02\/chiusa-al-traffico-strada-tivoli-marcellina-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"CHIUSA AL TRAFFICO STRADA TIVOLI MARCELLINA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=2363"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2363\/revisions"}],"predecessor-version":[{"id":2364,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2363\/revisions\/2364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/617"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=2363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=2363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=2363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}