{"id":2453,"date":"2019-01-11T17:30:48","date_gmt":"2019-01-11T16:30:48","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=2453"},"modified":"2019-01-11T17:30:48","modified_gmt":"2019-01-11T16:30:48","slug":"da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/","title":{"rendered":"DA LUNEDI&#8217; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE"},"content":{"rendered":"<p>Dalle ore 8 di luned\u00ec 14 gennaio e fino a fine lavori sar\u00e0 chiusa al traffico, per tutti i veicoli e in entrambe le direzioni di marcia, la strada provinciale Tivoli-Marcellina. I lavori sono necessari per mettere in sicurezza la strada nei pressi del &#8220;ponticello&#8221; (vicino alla stazione di Marcellina), la cui sede stradale risulta danneggiata a causa degli straripamenti del corso d&#8217;acqua sottostante.<\/p>\n<p>I lavori, secondo quanto ha riferito Citt\u00e0 Metropolitana, che ha la competenza della strada, dovrebbero durare una decina di giorni.<\/p>\n<p>La provinciale Tivoli-Marcellina resta comunque percorribile nel tratto compreso tra il centro della citt\u00e0 tiburtina e la strada Maria Santissima di Quintiliolo.<\/p>\n<p>Tivoli, 11 gennaio 2019 &#8211; ufficio stampa e informazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle ore 8 di luned\u00ec 14 gennaio e fino a fine lavori sar\u00e0 chiusa al traffico, per tutti i veicoli e in entrambe le direzioni di marcia, la strada provinciale [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DA LUNEDI&#039; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DA LUNEDI&#039; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dalle ore 8 di luned\u00ec 14 gennaio e fino a fine lavori sar\u00e0 chiusa al traffico, per tutti i veicoli e in entrambe le direzioni di marcia, la strada provinciale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-11T16:30:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"DA LUNEDI&#8217; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE\",\"datePublished\":\"2019-01-11T16:30:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/\"},\"wordCount\":122,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/\",\"name\":\"DA LUNEDI' 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"datePublished\":\"2019-01-11T16:30:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"width\":921,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/01\\\/11\\\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DA LUNEDI&#8217; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DA LUNEDI' 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/","og_locale":"it_IT","og_type":"article","og_title":"DA LUNEDI' 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE - Tivoli","og_description":"Dalle ore 8 di luned\u00ec 14 gennaio e fino a fine lavori sar\u00e0 chiusa al traffico, per tutti i veicoli e in entrambe le direzioni di marcia, la strada provinciale [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-11T16:30:48+00:00","og_image":[{"width":921,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"DA LUNEDI&#8217; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE","datePublished":"2019-01-11T16:30:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/"},"wordCount":122,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/","url":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/","name":"DA LUNEDI' 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","datePublished":"2019-01-11T16:30:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","width":921,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/01\/11\/da-lunedi-14-chiusa-al-traffico-la-provinciale-tivoli-marcellina-quintiliolo-resta-percorribile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"DA LUNEDI&#8217; 14 CHIUSA AL TRAFFICO LA PROVINCIALE TIVOLI-MARCELLINA. QUINTILIOLO RESTA PERCORRIBILE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=2453"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2453\/revisions"}],"predecessor-version":[{"id":2454,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2453\/revisions\/2454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=2453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=2453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=2453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}