{"id":2561,"date":"2019-02-27T13:52:40","date_gmt":"2019-02-27T12:52:40","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=2561"},"modified":"2019-02-27T13:52:40","modified_gmt":"2019-02-27T12:52:40","slug":"domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/","title":{"rendered":"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO"},"content":{"rendered":"<p>Proseguono i lavori di ripavimentazione compresi nel Piano strade del Comune di Tivoli. Domani 28 febbraio dalle ore 07:00 alle ore 17:00 e comunque \u00a0fino al termine dei lavori si proceder\u00e0 all\u2019asfaltatura di via Maria SS Quintiliolo.<\/p>\n<p>Per consentire l\u2019effettuazione dei lavori non sar\u00e0 possibile transitare o sostare nel tratto stradale interessato (dall\u2019intersezione con via Colle Nocello all\u2019intersezione con Strada Provinciale Tivoli-Marcellina)<\/p>\n<p>Maggiori dettagli sul piano strade e sui servizi di manutenzione \u201cglobal service\u201d sono disponibili al seguente link\u00a0<a href=\"http:\/\/www.comune.tivoli.rm.it\/node\/3598\"><strong>http:\/\/www.comune.tivoli.rm.it\/node\/3598<\/strong><\/a>\u00a0.<\/p>\n<p>Si invitano gli automobilisti a rispettare i divieti di sosta e gli eventuali divieti di transito in vigore in tutte le strade interessate dai lavori di ripavimentazione e per le successive attivit\u00e0 di rifacimento della segnaletica a terra. Eventuali altre informazioni possono essere richieste alla Polizia locale al numero 0774453501.<\/p>\n<p>Si ricorda che \u00e8 stato attivato il numero verde gratuito per le segnalazioni da parte dei cittadini di situazioni di pericolo su tutte le strade di competenza del Comune di Tivoli. Il numero verde\u00a0<strong>800199693<\/strong>\u00a0\u00e8 in funzione 24 ore su 24, anche la domenica e i festivi ed \u00e8 gestito dalla centrale operativa della Zini Elio srl (societ\u00e0 del raggruppamento di imprese che si \u00e8 aggiudicata la gara)<\/p>\n<p>Tivoli, 27 febbraio 2019 \u2013 ufficio stampa e informazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proseguono i lavori di ripavimentazione compresi nel Piano strade del Comune di Tivoli. Domani 28 febbraio dalle ore 07:00 alle ore 17:00 e comunque \u00a0fino al termine dei lavori si [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Proseguono i lavori di ripavimentazione compresi nel Piano strade del Comune di Tivoli. Domani 28 febbraio dalle ore 07:00 alle ore 17:00 e comunque \u00a0fino al termine dei lavori si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-27T12:52:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO\",\"datePublished\":\"2019-02-27T12:52:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/\"},\"wordCount\":212,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/\",\"name\":\"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"datePublished\":\"2019-02-27T12:52:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso-1.jpg\",\"width\":921,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/02\\\/27\\\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/","og_locale":"it_IT","og_type":"article","og_title":"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO - Tivoli","og_description":"Proseguono i lavori di ripavimentazione compresi nel Piano strade del Comune di Tivoli. Domani 28 febbraio dalle ore 07:00 alle ore 17:00 e comunque \u00a0fino al termine dei lavori si [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-27T12:52:40+00:00","og_image":[{"width":921,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO","datePublished":"2019-02-27T12:52:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/"},"wordCount":212,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/","url":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/","name":"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","datePublished":"2019-02-27T12:52:40+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso-1.jpg","width":921,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/02\/27\/domani-giovedi-28-lavori-di-ripavimentazione-in-via-quintiliolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"DOMANI GIOVEDI 28 LAVORI DI RIPAVIMENTAZIONE IN VIA QUINTILIOLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=2561"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2561\/revisions"}],"predecessor-version":[{"id":2562,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2561\/revisions\/2562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/829"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=2561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=2561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=2561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}