{"id":2646,"date":"2019-04-01T14:48:56","date_gmt":"2019-04-01T12:48:56","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=2646"},"modified":"2019-04-01T14:48:56","modified_gmt":"2019-04-01T12:48:56","slug":"tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/","title":{"rendered":"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE"},"content":{"rendered":"<p>Acea Acqua informa che, per consentire interventi di potenziamento dell\u2019impianto idrico, sar\u00e0 sospesa l\u2019erogazione dell\u2019acqua nella notte tra marted\u00ec 2 e mercoled\u00ec 3 aprile a Tivoli \u00a0in parte del centro cittadino e dei quartieri Empolitano e Acquaregna.<\/p>\n<p>Pertanto dalle ore 22 del 2 aprile alle ore 7 del 3 aprile si verificheranno abbassamenti di pressione o mancanza d\u2019acqua nelle seguenti vie e zone limitrofe: viale Trieste, viale Tomei, via Tiburtina (da piazza Garibaldi fino all\u2019altezza della caserma della Guardia di Finanza), via Colsereno, via del Trevio, via delle Piagge, via Empolitana, via Acquaregna.<\/p>\n<p>Per ulteriori informazioni si pu\u00f2 contattare il numero verde Acea 800.130.335.<\/p>\n<p>Tivoli, 1 aprile 2019 \u2013 ufficio stampa e informazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acea Acqua informa che, per consentire interventi di potenziamento dell\u2019impianto idrico, sar\u00e0 sospesa l\u2019erogazione dell\u2019acqua nella notte tra marted\u00ec 2 e mercoled\u00ec 3 aprile a Tivoli \u00a0in parte del centro [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-2646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Acea Acqua informa che, per consentire interventi di potenziamento dell\u2019impianto idrico, sar\u00e0 sospesa l\u2019erogazione dell\u2019acqua nella notte tra marted\u00ec 2 e mercoled\u00ec 3 aprile a Tivoli \u00a0in parte del centro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-01T12:48:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/ACQUA-150.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"615\" \/>\n\t<meta property=\"og:image:height\" content=\"249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE\",\"datePublished\":\"2019-04-01T12:48:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/\"},\"wordCount\":121,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/ACQUA-150.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/\",\"name\":\"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/ACQUA-150.jpg\",\"datePublished\":\"2019-04-01T12:48:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/ACQUA-150.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/ACQUA-150.jpg\",\"width\":615,\"height\":249},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/04\\\/01\\\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/","og_locale":"it_IT","og_type":"article","og_title":"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE - Tivoli","og_description":"Acea Acqua informa che, per consentire interventi di potenziamento dell\u2019impianto idrico, sar\u00e0 sospesa l\u2019erogazione dell\u2019acqua nella notte tra marted\u00ec 2 e mercoled\u00ec 3 aprile a Tivoli \u00a0in parte del centro [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-04-01T12:48:56+00:00","og_image":[{"width":615,"height":249,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/ACQUA-150.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE","datePublished":"2019-04-01T12:48:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/"},"wordCount":121,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/ACQUA-150.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/","url":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/","name":"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/ACQUA-150.jpg","datePublished":"2019-04-01T12:48:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/ACQUA-150.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/ACQUA-150.jpg","width":615,"height":249},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/04\/01\/tivoli-centro-sospensione-del-flusso-idrico-nella-notte-tra-martedi-2-e-mercoledi-3-aprile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"TIVOLI CENTRO, SOSPENSIONE DEL FLUSSO IDRICO NELLA NOTTE TRA MARTEDI\u2019 2 E MERCOLEDI\u2019 3 APRILE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=2646"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2646\/revisions"}],"predecessor-version":[{"id":2647,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2646\/revisions\/2647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/847"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=2646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=2646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=2646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}