{"id":2699,"date":"2019-05-13T11:53:08","date_gmt":"2019-05-13T09:53:08","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=2699"},"modified":"2019-05-13T11:53:08","modified_gmt":"2019-05-13T09:53:08","slug":"domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/","title":{"rendered":"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO &#8211; VIA DEI SOSII"},"content":{"rendered":"<p style=\"text-align: justify\">Per effettuare urgenti lavori alla rete idrica, \u00e8 stata disposta la chiusura al traffico di via del Trevio altezza del civico n. 59 dalle ore 14:00 alle ore 17:00 (e comunque fino a fine lavori) di domani, marted\u00ec 14 maggio. Altres\u00ec rester\u00e0 chiusa al transito veicolare via dei Sosii.<\/p>\n<p style=\"text-align: justify\">Nel caso in cui i lavori dovessero protrarsi oltre le ore 17:00 sar\u00e0 disattivato il varco elettronico della zona a traffico limitato medievale. Il percorso alternativo consentito a tutti i veicoli, anche quelli senza permesso di accesso alla ztl, sar\u00e0 via San Valerio &#8211; Arco del Macello &#8211; via Postera,<\/p>\n<p style=\"text-align: justify\">Si invita in ogni caso a prestare sempre attenzione allo stato dei cartelli a messaggio variabile posizionati agli ingressi della ztl: &#8220;varco attivo&#8221; equivale ad accesso consentito soltanto agli autorizzati.<\/p>\n<p>Per informazioni: Polizia locale 0774453501.<\/p>\n<p>Tivoli, 13 maggio 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per effettuare urgenti lavori alla rete idrica, \u00e8 stata disposta la chiusura al traffico di via del Trevio altezza del civico n. 59 dalle ore 14:00 alle ore 17:00 (e [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO - VIA DEI SOSII - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO - VIA DEI SOSII - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Per effettuare urgenti lavori alla rete idrica, \u00e8 stata disposta la chiusura al traffico di via del Trevio altezza del civico n. 59 dalle ore 14:00 alle ore 17:00 (e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-13T09:53:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO &#8211; VIA DEI SOSII\",\"datePublished\":\"2019-05-13T09:53:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/\"},\"wordCount\":141,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/\",\"name\":\"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO - VIA DEI SOSII - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso.jpg\",\"datePublished\":\"2019-05-13T09:53:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/07\\\/lavori-in-corso.jpg\",\"width\":921,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/05\\\/13\\\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO &#8211; VIA DEI SOSII\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO - VIA DEI SOSII - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/","og_locale":"it_IT","og_type":"article","og_title":"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO - VIA DEI SOSII - Tivoli","og_description":"Per effettuare urgenti lavori alla rete idrica, \u00e8 stata disposta la chiusura al traffico di via del Trevio altezza del civico n. 59 dalle ore 14:00 alle ore 17:00 (e [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-13T09:53:08+00:00","og_image":[{"width":921,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO &#8211; VIA DEI SOSII","datePublished":"2019-05-13T09:53:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/"},"wordCount":141,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/","url":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/","name":"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO - VIA DEI SOSII - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso.jpg","datePublished":"2019-05-13T09:53:08+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/07\/lavori-in-corso.jpg","width":921,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/05\/13\/domani-14-maggio-chiusa-al-traffico-via-del-trevio-via-dei-sosii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"DOMANI 14 MAGGIO CHIUSA AL TRAFFICO VIA DEL TREVIO &#8211; VIA DEI SOSII"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=2699"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2699\/revisions"}],"predecessor-version":[{"id":2700,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/2699\/revisions\/2700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/811"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=2699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=2699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=2699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}