{"id":3272,"date":"2019-10-29T12:30:23","date_gmt":"2019-10-29T11:30:23","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=3272"},"modified":"2019-10-29T12:30:23","modified_gmt":"2019-10-29T11:30:23","slug":"bando-di-concorso-per-dirigente-finanziario-contabile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/","title":{"rendered":"Bando di concorso per Dirigente Finanziario\/ Contabile"},"content":{"rendered":"<p>Sull&#8217;<a href=\"https:\/\/albopretorio.datamanagementitalia.it\/AlboPretorioWeb\/?ente=ComuneDiTivoli&amp;tipoSubmit=ricerca\" target=\"_blank\" rel=\"noopener\">albo pretorio<\/a> online dell&#8217;ente nonch\u00e9 sul sito <a href=\"https:\/\/trasparenza.strategicpa.it\/comunetivoli\/archivio\/2898-bandi-e-avvisi-in-corso-\" target=\"_blank\" rel=\"noopener\">amministrazione trasparente<\/a> sezione bandi di concorso \u00e8 pubblicato il bando di concorso pubblico, per titoli e per esami, per la copertura a tempo pieno e indeterminato di 1 posto da Dirigente Finanziario\/ Contabile per il Settore VII servizio economico e finanziario del Comune di Tivoli con il relativo modello di domanda di partecipazione.<\/p>\n<p align=\"justify\">\u00c9 possibile presentare la domanda entro il termine perentorio del 25 novembre 2019, ore 12:00.<\/p>\n<p>In allegato bando integrale e modulo per la domanda.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3273\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/10\/Bando.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/10\/Bando.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Bando per Dirigente Finanziario\/ Contabile<\/a><\/li>\n<li><a id=\"wpba_attachment_list_3274\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/10\/Modello.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/10\/Modello.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modello di domanda<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sull&#8217;albo pretorio online dell&#8217;ente nonch\u00e9 sul sito amministrazione trasparente sezione bandi di concorso \u00e8 pubblicato il bando di concorso pubblico, per titoli e per esami, per la copertura a tempo [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":2809,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando di concorso per Dirigente Finanziario\/ Contabile - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando di concorso per Dirigente Finanziario\/ Contabile - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sull&#8217;albo pretorio online dell&#8217;ente nonch\u00e9 sul sito amministrazione trasparente sezione bandi di concorso \u00e8 pubblicato il bando di concorso pubblico, per titoli e per esami, per la copertura a tempo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-29T11:30:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Bando di concorso per Dirigente Finanziario\\\/ Contabile\",\"datePublished\":\"2019-10-29T11:30:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/\"},\"wordCount\":85,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/\",\"name\":\"Bando di concorso per Dirigente Finanziario\\\/ Contabile - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"datePublished\":\"2019-10-29T11:30:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/10\\\/29\\\/bando-di-concorso-per-dirigente-finanziario-contabile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando di concorso per Dirigente Finanziario\\\/ Contabile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando di concorso per Dirigente Finanziario\/ Contabile - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/","og_locale":"it_IT","og_type":"article","og_title":"Bando di concorso per Dirigente Finanziario\/ Contabile - Tivoli","og_description":"Sull&#8217;albo pretorio online dell&#8217;ente nonch\u00e9 sul sito amministrazione trasparente sezione bandi di concorso \u00e8 pubblicato il bando di concorso pubblico, per titoli e per esami, per la copertura a tempo [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-10-29T11:30:23+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Bando di concorso per Dirigente Finanziario\/ Contabile","datePublished":"2019-10-29T11:30:23+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/"},"wordCount":85,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/","url":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/","name":"Bando di concorso per Dirigente Finanziario\/ Contabile - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","datePublished":"2019-10-29T11:30:23+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/10\/29\/bando-di-concorso-per-dirigente-finanziario-contabile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Bando di concorso per Dirigente Finanziario\/ Contabile"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/3272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=3272"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/3272\/revisions"}],"predecessor-version":[{"id":3275,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/3272\/revisions\/3275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/2809"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=3272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=3272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=3272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}