{"id":3345,"date":"2019-11-12T12:37:14","date_gmt":"2019-11-12T11:37:14","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=3345"},"modified":"2019-11-12T12:37:14","modified_gmt":"2019-11-12T11:37:14","slug":"temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/","title":{"rendered":"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre."},"content":{"rendered":"<p>Di seguito il<a href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/11\/Ordinanza-555-dell111119.pdf\" target=\"_blank\" rel=\"noopener\">\u00a0link<\/a>\u00a0all\u2019ordinanza n. 555 dell&#8217;11 novembre 2019<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3346\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/11\/Ordinanza-555-dell111119.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/11\/Ordinanza-555-dell111119.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza 555 dell'111119<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Di seguito il\u00a0link\u00a0all\u2019ordinanza n. 555 dell&#8217;11 novembre 2019 \ud83d\udcce AllegatiOrdinanza 555 dell&#8217;111119<\/p>\n","protected":false},"author":174,"featured_media":2815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-3345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre. - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre. - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Di seguito il\u00a0link\u00a0all\u2019ordinanza n. 555 dell&#8217;11 novembre 2019 \ud83d\udcce AllegatiOrdinanza 555 dell&#039;111119\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-12T11:37:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre.\",\"datePublished\":\"2019-11-12T11:37:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/\"},\"wordCount\":23,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/\",\"name\":\"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre. - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"datePublished\":\"2019-11-12T11:37:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2019\\\/11\\\/12\\\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre. - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/","og_locale":"it_IT","og_type":"article","og_title":"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre. - Tivoli","og_description":"Di seguito il\u00a0link\u00a0all\u2019ordinanza n. 555 dell&#8217;11 novembre 2019 \ud83d\udcce AllegatiOrdinanza 555 dell'111119","og_url":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-11-12T11:37:14+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre.","datePublished":"2019-11-12T11:37:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/"},"wordCount":23,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/","url":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/","name":"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre. - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","datePublished":"2019-11-12T11:37:14+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2019\/11\/12\/temporanea-modifica-dellattuale-regolamentazione-stradale-in-via-degli-olivi-per-il-giorno-14-novembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Temporanea modifica dell\u2019attuale regolamentazione stradale in Via degli Olivi, per il giorno 14 novembre."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/3345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=3345"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/3345\/revisions"}],"predecessor-version":[{"id":3347,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/3345\/revisions\/3347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/2815"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=3345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=3345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=3345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}