{"id":356,"date":"2017-02-02T14:47:00","date_gmt":"2017-02-02T13:47:00","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=356"},"modified":"2017-02-02T14:47:00","modified_gmt":"2017-02-02T13:47:00","slug":"il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/","title":{"rendered":"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI"},"content":{"rendered":"<p>Venerd\u00ec 3 febbraio al Teatro Giuseppetti un appuntamento da non perdere. &#8220;Mumble Mumble ovvero confessioni di un orfano d&#8217;arte&#8221; di Emanuele Salce e Andrea Pergolari,\u00a0<span class=\"text_exposed_show\">con Emanuele Salce e Paolo Giommarelli.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>\u00abCi vuole l\u2019opportunit\u00e0 di esser figlio d\u2019arte di due padri \u2013 quello naturale, Luciano Salce e quello adottivo, Vittorio Gassman \u2013 che hanno lasciato un segno nello spettacolo italiano. Ci vuole un misto di grazia e faccia tosta nel volgere in racconto i due-funerali-due per la scomparsa di entrambi. E ci vuole sense of humor (venato di grottesco nostrano) che discende dal filone britannico dell\u2019Evelyn Waugh de Il caro estinto o dell\u2019Alan Bennet de La cerimonia del massaggio&#8230;\u00bb. Nella sua lusinghiera recensione a Mumble Mumble, sulle colonne de \u201cLa Repubblica\u201d, Rodolfo Di Giammarco condensa cos\u00ec gli \u201cingredienti\u201d di uno spettacolo coraggioso e divertente, firmato e interpretato da Emanuele Salce. L\u2019attore, che per la drammaturgia \u00e8 affiancato da Andrea Pergolari e in scena conta sul contraltare gustoso di Paolo Giommarelli (un personaggio-spettatore ora complice, ora provocatore), in questa pi\u00e9ce porta in scena se stesso. Un attore che in una pausa delle prove, chiuso in camerino, si trova a fare i conti con la propria realt\u00e0, l\u2019essere attore e uomo, funzione di una societ\u00e0 che gli sfugge e identit\u00e0 ricercata e mai trovata. Lo fa fra voragini di seriet\u00e0 e voli di ironia, conciliando le pagine di Dostoevskij agli europei di calcio, i cerimoniali funebri paterni all\u2019effetto di una meravigliosa bionda australiana o a quello di un dannato flacone di medicinale&#8230; Eros e Thanatos, drammatico e grottesco per raccontare e ridere di sogni incubi e ossessioni di un validissimo attore.<\/p>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 3 febbraio al Teatro Giuseppetti un appuntamento da non perdere. &#8220;Mumble Mumble ovvero confessioni di un orfano d&#8217;arte&#8221; di Emanuele Salce e Andrea Pergolari,\u00a0con Emanuele Salce e Paolo Giommarelli. [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-356","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 3 febbraio al Teatro Giuseppetti un appuntamento da non perdere. &#8220;Mumble Mumble ovvero confessioni di un orfano d&#8217;arte&#8221; di Emanuele Salce e Andrea Pergolari,\u00a0con Emanuele Salce e Paolo Giommarelli. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-02T13:47:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI\",\"datePublished\":\"2017-02-02T13:47:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/\"},\"wordCount\":284,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/\",\"name\":\"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2017-02-02T13:47:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/02\\\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/","og_locale":"it_IT","og_type":"article","og_title":"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI - Tivoli","og_description":"Venerd\u00ec 3 febbraio al Teatro Giuseppetti un appuntamento da non perdere. &#8220;Mumble Mumble ovvero confessioni di un orfano d&#8217;arte&#8221; di Emanuele Salce e Andrea Pergolari,\u00a0con Emanuele Salce e Paolo Giommarelli. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-02-02T13:47:00+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI","datePublished":"2017-02-02T13:47:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/"},"wordCount":284,"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/","name":"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2017-02-02T13:47:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/02\/il-grande-teatro-a-tivoli-domani-sera-terzo-spettacolo-al-giuseppetti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"IL GRANDE TEATRO A TIVOLI. DOMANI SERA TERZO SPETTACOLO AL GIUSEPPETTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"predecessor-version":[{"id":357,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/356\/revisions\/357"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}