{"id":376,"date":"2017-02-20T16:04:18","date_gmt":"2017-02-20T15:04:18","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=376"},"modified":"2017-02-20T16:04:18","modified_gmt":"2017-02-20T15:04:18","slug":"stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/","title":{"rendered":"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI"},"content":{"rendered":"<p>Dalle ore 22 di oggi via Pacifici sar\u00e0 chiusa al traffico per permettere la sostituzione della griglia della raccolta delle acque pluviali &#8211; che occupa l&#8217;intera sede stradale &#8211; disposta dal settore lavori pubblici del Comune. Lo ha comunicato la Polizia locale.<\/p>\n<p>Pertanto fino alle 6 del mattino il traffico delle automobili di\u00a0via della Missione sar\u00e0 deviato verso piazza Trento, attraverso via Santa Maria Maggiore; dalle ore 22 alle 6 sar\u00e0 vietato il transito di furgoni e autocarri all&#8217;arco del Macello.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle ore 22 di oggi via Pacifici sar\u00e0 chiusa al traffico per permettere la sostituzione della griglia della raccolta delle acque pluviali &#8211; che occupa l&#8217;intera sede stradale &#8211; disposta [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-376","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dalle ore 22 di oggi via Pacifici sar\u00e0 chiusa al traffico per permettere la sostituzione della griglia della raccolta delle acque pluviali &#8211; che occupa l&#8217;intera sede stradale &#8211; disposta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-20T15:04:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI\",\"datePublished\":\"2017-02-20T15:04:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/\"},\"wordCount\":88,\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/\",\"name\":\"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2017-02-20T15:04:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/02\\\/20\\\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/","og_locale":"it_IT","og_type":"article","og_title":"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI - Tivoli","og_description":"Dalle ore 22 di oggi via Pacifici sar\u00e0 chiusa al traffico per permettere la sostituzione della griglia della raccolta delle acque pluviali &#8211; che occupa l&#8217;intera sede stradale &#8211; disposta [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-02-20T15:04:18+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/manutenzione-e-lavori.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI","datePublished":"2017-02-20T15:04:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/"},"wordCount":88,"articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/","name":"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2017-02-20T15:04:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/02\/20\/stanotte-chiusa-al-traffico-via-pacifici-per-lavori-urgenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"STANOTTE CHIUSA AL TRAFFICO VIA PACIFICI PER LAVORI URGENTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=376"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/376\/revisions"}],"predecessor-version":[{"id":377,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/376\/revisions\/377"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}