{"id":412,"date":"2017-03-04T17:31:05","date_gmt":"2017-03-04T16:31:05","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=412"},"modified":"2017-03-04T17:31:05","modified_gmt":"2017-03-04T16:31:05","slug":"il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/","title":{"rendered":"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19"},"content":{"rendered":"<h2 class=\"_2cuy _509y _2vxa\">Alla manifestazione tradizionale verr\u00e0 affiancata una edizione &#8220;revival&#8221; nell&#8217;area delle vecchie cartiere: venti ore di spettacoli no stop con djset il sabato sera, fattoria degli animali, giostre e attrazioni, laboratori dei mastri artigiani, parate e manifestazioni itineranti, visite guidate nel centro storico, tornei e giochi, l&#8217;antica trattoria dei comitati, mercatino dei bambini e una estemporanea di pittura.<\/h2>\n<div class=\"_2cuy _3dgx _2vxa\">Due giorni di festa nel cuore del centro storico. La Fiera di San Giuseppe raddoppia e torna alle origini, a 122 anni di distanza dalla prima sua edizione del 1895. Alla manifestazione tradizionale del 19 marzo quest&#8217;anno si aggiunge una storica novit\u00e0: la fiera &#8220;revival&#8221; nell&#8217;area delle vecchie cartiere, ai piedi del Carapone, in cui si riprongono le atmosfere delle prime edizioni.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">La manifestazione, promossa dagli assessorati alle attivit\u00e0 produttive e alla cultura del Comune di Tivoli, \u00e8 organizzata con la collaborazione della Pro Loco, del Fai-Parco Villa Gregoriana e di comitati e associazioni di tutto il territorio cittadino, che hanno aderito all&#8217;invito dell&#8217;amministrazione comunale a partecipare all&#8217;ideazione del programma e ad attivarsi per la sua attuazione.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">La fiera revival andr\u00e0 in scena per due giorni: sabato 18 e domenica 19 marzo. Il programma, ancora in fase di costruzione, al momento comprende la fattoria, con l&#8217;esposizione di cavalli, mucche, asini, capre, pecore, galline e altri animali; un vero e proprio luna park, con giostre e spettacoli viaggianti; l&#8217;antica trattoria, gestita dai comitati di quartiere, che per la prima volta si uniscono in una manifestazione organizzata nel centro di Tivoli; il borgo dei mastri artigiani, con laboratori in cui i visitatori potranno cimentarsi anche nella creazione di cesti di vimini e nella lavorazione dell&#8217;argilla e del legno; il mercatino dei bambini nell&#8217;area del duomo; una estemporanea di pittura; tornei di briscola e di burraco; un concorso fotografico sul tema della fiera; spettacoli itineranti di artisti di strada, trampolieri e tamburellare tiburtine; una sfilata con coppie di umani e animali domestici.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">Per tutta la giornata di sabato il Fai organizzer\u00e0 visite guidate, con partenza ogni ora da piazza Rivarola, lungo uno speciale itinerario nel cuore antico della citt\u00e0.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">Il cuore della festa sar\u00e0 per entrambi i giorni l&#8217;area spettacoli, ancora ai piedi del Carapone, in cui verranno allestiti due palchi con una vera e propria maratona di oltre venti ore di musica, danza, poesia, teatro e saltimbanchi, con il djset il sabato sera e un coinvolgente gioco dei palloni per i bambini, nel pomeriggio di entrambi i giorni.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">La fiera tradizionale di domenica 19 si svolger\u00e0 nella stessa area dello scorso anno, cio\u00e8 il quadrante compreso tra piazza Rivarola, via Parrozzani-via Colsereno, piazza Santa Croce, le aree del municipio, di piazza del Plebiscito, di piazza Campitelli e di piazza Tani, nella zona del Duomo. Ci saranno circa 200 mercanti e artigiani, 50 in pi\u00f9 rispetto allo scorso anno.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">Nei prossimi giorni, sulla pagina facebook &#8220;Fiera di San Giuseppe Tivoli&#8221; e sul sito internet del Comune, saranno diffusi il programma completo e dettagliato e le modalit\u00e0 per iscriversi alle varie manifestazioni.<\/div>\n<div class=\"_2cuy _3dgx _2vxa\"><\/div>\n<div class=\"_2cuy _3dgx _2vxa\">Per quel che riguarda il programma degli spettacoli, gli artisti locali che intendono partecipare ed esibirsi sui palchi possono contattare la direzione artistica presso Beats Generation al numero 0774330881. Per informazioni chiamare il numero 0774453216 o inviare un messaggio alla pagina facebook della Fiera.<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Alla manifestazione tradizionale verr\u00e0 affiancata una edizione &#8220;revival&#8221; nell&#8217;area delle vecchie cartiere: venti ore di spettacoli no stop con djset il sabato sera, fattoria degli animali, giostre e attrazioni, laboratori [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Alla manifestazione tradizionale verr\u00e0 affiancata una edizione &#8220;revival&#8221; nell&#8217;area delle vecchie cartiere: venti ore di spettacoli no stop con djset il sabato sera, fattoria degli animali, giostre e attrazioni, laboratori [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-04T16:31:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/fiera-diario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19\",\"datePublished\":\"2017-03-04T16:31:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/\"},\"wordCount\":542,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/fiera-diario.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/\",\"name\":\"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/fiera-diario.jpg\",\"datePublished\":\"2017-03-04T16:31:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/fiera-diario.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/fiera-diario.jpg\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/04\\\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/","og_locale":"it_IT","og_type":"article","og_title":"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19 - Tivoli","og_description":"Alla manifestazione tradizionale verr\u00e0 affiancata una edizione &#8220;revival&#8221; nell&#8217;area delle vecchie cartiere: venti ore di spettacoli no stop con djset il sabato sera, fattoria degli animali, giostre e attrazioni, laboratori [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-03-04T16:31:05+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/fiera-diario.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19","datePublished":"2017-03-04T16:31:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/"},"wordCount":542,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/fiera-diario.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/","name":"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/fiera-diario.jpg","datePublished":"2017-03-04T16:31:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/fiera-diario.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/fiera-diario.jpg","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/04\/il-revival-della-fiera-di-san-giuseppe-due-giorni-di-festa-sabato-18-e-domenica-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"IL REVIVAL DELLA FIERA DI SAN GIUSEPPE: DUE GIORNI DI FESTA SABATO 18 E DOMENICA 19"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=412"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/412\/revisions"}],"predecessor-version":[{"id":414,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/412\/revisions\/414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/413"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}