{"id":415,"date":"2017-03-06T11:56:13","date_gmt":"2017-03-06T10:56:13","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=415"},"modified":"2017-03-06T11:56:13","modified_gmt":"2017-03-06T10:56:13","slug":"otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/","title":{"rendered":"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI."},"content":{"rendered":"<p>L\u20198 marzo, Giornata internazionale della donna, nei musei, aree archeologiche e monumenti statali l\u2019 ingresso \u00e8 gratuito per le donne.<\/p>\n<p>L\u2019Istituto autonomo Villa Adriana e Villa d\u2019Este aderisce all\u2019iniziativa con le seguenti proposte culturali:<\/p>\n<p><strong>VILLA ADRIANA<\/strong><\/p>\n<p>Visita guidata gratuita sul tema \u201cVibia Sabina. Immagine pubblica e privata\u201d a cura della dott.ssa Benedetta Adembri, responsabile del sito archeologico (partenza ore 10.00 dal Plastico, massimo 30 persone, prenotazione obbligatoria e informazioni al +39 0774382733, email <a href=\"mailto:villa.adriana@coopculture.it\">villa.adriana@coopculture.it<\/a>)<\/p>\n<p>Orario Area Archeologica: 9.00 \u2013 18.30<br \/>\nLa biglietteria chiude alle ore 17.00<\/p>\n<p><strong>VILLA D&#8217;ESTE<\/strong><\/p>\n<p>Visita guidata gratuita sul tema &#8220;Figure mitologiche femminili e allegorie nell&#8217;iconografia di Villa d&#8217;Este&#8221; a cura di Laura Baruzzi e Laura Ferracci.<br \/>\nOrario visite:10.00 e 15.30, massimo 30 persone<br \/>\nPrenotazione obbligatoria<br \/>\nInformazioni:+39 0774312070, email <a href=\"mailto:va-ve@beniculturali.it\">va-ve@beniculturali.it<\/a><\/p>\n<p>Orario Villa d&#8217;Este: 8.30 \u2013 18.15<br \/>\nLa biglietteria chiude alle ore 17.15<br \/>\n<strong>SANTUARIO DI ERCOLE VINCITORE<\/strong><\/p>\n<p>\u2018Amabili spoglie. Racconti scritti nei resti femminili\u2019<\/p>\n<p>Evento ad ingresso libero, accessibile a tutte le categorie di pubblico, anche quelle speciali, con esame diretto e concreto di resti ossei e corredi funerari femminili.<\/p>\n<p>La conferenza e il laboratorio prendono spunto dalla consuetudine di inferire conoscenze sulla vita di un defunto, tramite l\u2019analisi del corredo funerario posto nelle antiche sepolture, che spesso si connota diversamente a seconda del sesso e dell\u2019et\u00e0 dell\u2019individuo; ma si possono riconoscere anche particolari status sociali, che i celebranti del rituale funerario hanno voluto ricordare e\/o ostentare nel corso della cerimonia.<\/p>\n<p>Anche l\u2019analisi antropometrica dei resti ossei, pu\u00f2 fornire notizie circa le patologie, il sesso e le eventuali attivit\u00e0 lavorative svolte nel corso della vita e, con l\u2019apporto di studi multisciplinari, tra cui l\u2019estrazione del DNA, siamo in grado di riconoscere tipologie e \u201clussi\u201d alimentari, caratteristiche ereditarie e provenienze.<br \/>\nTutto quanto \u00e8 \u201cscritto\u201d in una sepoltura ci permette di intravedere il riflesso delle dinamiche di una comunit\u00e0.<\/p>\n<p>Il laboratorio sar\u00e0 condotto sia tramite una presentazione con immagini, sia con un\u2019attivit\u00e0 di riconoscimento e tattile di calchi e resti originali.<\/p>\n<p>Sono previsti due turni di visita, uno alle 11:00, l\u2019altro alle 16:30, ciascuno riservato ad un massimo di 50 persone. Le prenotazioni sono possibili sino alle 12:00 del giorno precedente la manifestazione.<\/p>\n<p>Evento progettato e curato dal Laboratorio didattico del Santuario di Ercole Vincitore, illustrato da Micaela Angle, Patrizia Cocchieri, Lucilla D\u2019Alessandro e Silvia Mogliazza.<\/p>\n<p>Santuario di Ercole Vincitore,<br \/>\nVia degli Stabilimenti, 5<br \/>\nTivoli (RM)<br \/>\nInformazioni ed eventuali prenotazioni: +39 0774330329.<br \/>\n<strong>Poich\u00e9 \u00e8 previsto uno sciopero generale, l\u2019orario potrebbe subire variazioni; si consiglia pertanto di chiamare per informazioni<\/strong><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>L\u20198 marzo, Giornata internazionale della donna, nei musei, aree archeologiche e monumenti statali l\u2019 ingresso \u00e8 gratuito per le donne. L\u2019Istituto autonomo Villa Adriana e Villa d\u2019Este aderisce all\u2019iniziativa con [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-415","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI. - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI. - Tivoli\" \/>\n<meta property=\"og:description\" content=\"L\u20198 marzo, Giornata internazionale della donna, nei musei, aree archeologiche e monumenti statali l\u2019 ingresso \u00e8 gratuito per le donne. L\u2019Istituto autonomo Villa Adriana e Villa d\u2019Este aderisce all\u2019iniziativa con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-06T10:56:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI.\",\"datePublished\":\"2017-03-06T10:56:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/\"},\"wordCount\":425,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/\",\"name\":\"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI. - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2017-03-06T10:56:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/03\\\/06\\\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI. - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/","og_locale":"it_IT","og_type":"article","og_title":"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI. - Tivoli","og_description":"L\u20198 marzo, Giornata internazionale della donna, nei musei, aree archeologiche e monumenti statali l\u2019 ingresso \u00e8 gratuito per le donne. L\u2019Istituto autonomo Villa Adriana e Villa d\u2019Este aderisce all\u2019iniziativa con [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-03-06T10:56:13+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI.","datePublished":"2017-03-06T10:56:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/"},"wordCount":425,"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/","name":"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI. - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2017-03-06T10:56:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/03\/06\/otto-marzo-ingresso-gratuito-per-le-donne-a-villa-adriana-e-a-villa-deste-al-santuario-anche-per-gli-uomini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"OTTO MARZO, INGRESSO GRATUITO PER LE DONNE A VILLA ADRIANA E A VILLA D\u2019ESTE. AL SANTUARIO ANCHE PER GLI UOMINI."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=415"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/415\/revisions"}],"predecessor-version":[{"id":417,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/415\/revisions\/417"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}