{"id":468,"date":"2017-04-03T16:40:36","date_gmt":"2017-04-03T14:40:36","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=468"},"modified":"2017-04-03T16:40:36","modified_gmt":"2017-04-03T14:40:36","slug":"bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/","title":{"rendered":"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA"},"content":{"rendered":"<p>Apertura di sportelli di ascolto in tutte le scuole del territorio e una serie di seminari e laboratori sull\u2019educazione alla legalit\u00e0. Sono le azioni per prevenire e contrastare il bullismo appena avviate dal Comune di Tivoli attraverso il progetto Previs (prevenzione, integrazione, sicurezza).<\/p>\n<p><em>\u201cL\u2019obiettivo ultimo di questi interventi nei confronti dei minori \u00e8 individuare, prevenire e contrastare fenomeni di vandalismo, bullismo e violenza sotto ogni forma \u2013 ha dichiarato l\u2019assessore alle politiche sociali Maria Luisa Cappelli-. Mettendo i giovani e le famiglie al centro di ogni programma di intervento \u00e8 possibile arginare il fenomeno; accogliendo l\u2019individuo da un punto di vista emotivo e sociale si possono dare risposte concrete ed efficaci. Il progetto &#8211; attraverso il quale il Comune ha ottenuto un finanziamento regionale &#8211; comprende percorsi di sensibilizzazione sul fenomeno del bullismo e cyber-bullismo che si concluderanno con la creazione di un manifesto pubblicitario elaborato dagli studenti degli istituti scolastici tiburtini, che contenga un messaggio sociale contro la violenza. Alla fine il cartellone pi\u00f9 rappresentativo sar\u00e0 parte integrante di una vera e propria campagna sociale di sensibilizzazione, mediante la sua affissione in citt\u00e0\u201d.<\/em><\/p>\n<p>Il programma di Previs prevede anche l\u2019organizzazione di iniziative dedicate agli adulti e agli anziani, in particolare incontri e focus group nei comitati di quartiere, nei centri sociali e nelle sedi delle associazioni.<\/p>\n<p>Tivoli, 3 aprile 2017<\/p>\n<p>&nbsp;<\/p>\n<p>nella foto il gruppo di lavoro del progetto Previs in municipio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apertura di sportelli di ascolto in tutte le scuole del territorio e una serie di seminari e laboratori sull\u2019educazione alla legalit\u00e0. Sono le azioni per prevenire e contrastare il bullismo [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-468","post","type-post","status-publish","format-standard","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Apertura di sportelli di ascolto in tutte le scuole del territorio e una serie di seminari e laboratori sull\u2019educazione alla legalit\u00e0. Sono le azioni per prevenire e contrastare il bullismo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-03T14:40:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/servizi-sociali-e-casa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA\",\"datePublished\":\"2017-04-03T14:40:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/\"},\"wordCount\":249,\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/\",\"name\":\"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2017-04-03T14:40:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/04\\\/03\\\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/","og_locale":"it_IT","og_type":"article","og_title":"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA - Tivoli","og_description":"Apertura di sportelli di ascolto in tutte le scuole del territorio e una serie di seminari e laboratori sull\u2019educazione alla legalit\u00e0. Sono le azioni per prevenire e contrastare il bullismo [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-04-03T14:40:36+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/servizi-sociali-e-casa.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA","datePublished":"2017-04-03T14:40:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/"},"wordCount":249,"articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/","name":"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2017-04-03T14:40:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/04\/03\/bullismo-avviato-il-progetto-previs-nelle-scuole-sportelli-seminari-e-laboratori-di-educazione-contro-la-violenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"BULLISMO, AVVIATO IL PROGETTO PREVIS: NELLE SCUOLE SPORTELLI, SEMINARI E LABORATORI DI EDUCAZIONE CONTRO LA VIOLENZA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=468"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/468\/revisions"}],"predecessor-version":[{"id":469,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/468\/revisions\/469"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}