{"id":4911,"date":"2020-06-08T20:24:41","date_gmt":"2020-06-08T18:24:41","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=4911"},"modified":"2020-06-09T10:29:20","modified_gmt":"2020-06-09T08:29:20","slug":"chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/","title":{"rendered":"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Si avverte la popolazione che a seguito di un un improvviso e rilevante movimento franoso, che ha interessato il costone e parte della sede stradale, si \u00e8 resa indispensabile la chiusura al traffico del tratto iniziale di via Maria SS. di Quintiliolo. Il santuario e le abitazioni della zona saranno raggiungibili esclusivamente dalla str. dell\u2019Acquoria o dalla str. Collenocello.<\/span><\/p>\n<p><a href=\"https:\/\/static.comune.tivoli.rm.it\/uploads\/ORDINANZA-QUINTILIOLO.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Di seguito l&#8217;ordinanza della Polizia Locale<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si avverte la popolazione che a seguito di un un improvviso e rilevante movimento franoso, che ha interessato il costone e parte della sede stradale, si \u00e8 resa indispensabile la [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":2815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si avverte la popolazione che a seguito di un un improvviso e rilevante movimento franoso, che ha interessato il costone e parte della sede stradale, si \u00e8 resa indispensabile la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T18:24:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T08:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso\",\"datePublished\":\"2020-06-08T18:24:41+00:00\",\"dateModified\":\"2020-06-09T08:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/\"},\"wordCount\":80,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/\",\"name\":\"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"datePublished\":\"2020-06-08T18:24:41+00:00\",\"dateModified\":\"2020-06-09T08:29:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/08\\\/Viabilita\u0300.png\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/06\\\/08\\\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/","og_locale":"it_IT","og_type":"article","og_title":"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso - Tivoli","og_description":"Si avverte la popolazione che a seguito di un un improvviso e rilevante movimento franoso, che ha interessato il costone e parte della sede stradale, si \u00e8 resa indispensabile la [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-08T18:24:41+00:00","article_modified_time":"2020-06-09T08:29:20+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso","datePublished":"2020-06-08T18:24:41+00:00","dateModified":"2020-06-09T08:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/"},"wordCount":80,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/","url":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/","name":"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","datePublished":"2020-06-08T18:24:41+00:00","dateModified":"2020-06-09T08:29:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/08\/Viabilita\u0300.png","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/06\/08\/chiuso-al-traffico-il-tratto-iniziale-di-via-maria-ss-di-quintiliolo-per-movimento-franoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Chiuso al traffico il tratto iniziale di via Maria SS. Di Quintiliolo per movimento franoso"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/4911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=4911"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/4911\/revisions"}],"predecessor-version":[{"id":4919,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/4911\/revisions\/4919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/2815"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=4911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=4911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=4911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}