{"id":5295,"date":"2020-08-26T12:07:19","date_gmt":"2020-08-26T10:07:19","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=5295"},"modified":"2020-08-26T13:18:12","modified_gmt":"2020-08-26T11:18:12","slug":"coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/","title":{"rendered":"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico"},"content":{"rendered":"<p>La giunta comunale di Tivoli ha approvato la\u00a0<strong>delibera 140 del 24 agosto<\/strong>\u00a0con la quale il Comune aderisce all\u2019avviso pubblico del\u00a0<em>Dipartimento per il sistema educativo d\u2019istruzione e di formazione del ministero dell\u2019Istruzione<\/em>, che assegna agli enti locali titolari delle competenze di edilizia scolastica risorse per<strong>\u00a0l\u2019affitto, l\u2019acquisto, il leasing o il noleggio di strutture temporanee a uso scolastico.<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Dai numerosi contatti avuti nel corso delle ultime settimane tra l\u2019amministrazione comunale, gli uffici tecnici e le direzioni didattiche tiburtine con i relativi responsabili della sicurezza &#8211; in particolare con l\u2019istituto comprensivo Tivoli 1 &#8211; nonostante gli interventi di adeguamento in corso nei plessi esistenti e gli spazi comunali messi a disposizione per il riavvio delle prossime attivit\u00e0 didattiche, \u00e8 stata evidenziata dai dirigenti scolastici l\u2019esigenza di disporre di spazi integrativi, per poter cos\u00ec migliorare la pianificazione del nuovo anno, in considerazione dei disagi determinati dall\u2019emergenza sanitaria legata al Cov-Sars-2.<\/p>\n<p>Nel dettaglio, andrebbero a essere collocati nei moduli provvisori:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<strong>tre aule da installare nella corte esterna d\u2019ingresso del plesso scolastico di Villa Braschi;<\/strong><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>due aule nella corte esterna del plesso \u201cSandro Pertini\u201d di Via Colsereno.<\/strong><\/p>\n<p>Questa soluzione (il noleggio di idonee strutture leggere e rapidamente installabili) consentir\u00e0 di superare le criticit\u00e0 sinora riscontrate per l\u2019avvio in serenit\u00e0 delle attivit\u00e0 scolastiche il 14 settembre. Con il modulo di via Colsereno si verrebbe, per esempio, a evitare la necessit\u00e0 di utilizzare \u2013 come precedentemente individuato dal settore comunale ai Lavori pubblici \u2013 i locali del museo cittadino, mentre si manterrebbero le quattro aule all\u2019interno della biblioteca comunale. Per quanto riguarda, invece, il plesso di Villa Braschi, la collocazione delle classi\u00a0 nella struttura provvisoria consentir\u00e0 di evitare i doppi turni.<\/p>\n<p>\u201cPer finanziare tali strutture, che ospiteranno complessivamente circa 100 alunni, abbiamo risposto all&#8217;avviso pubblico del Miur dello scorso 19 agosto, tramite il quale gli enti locali possono indicare i propri fabbisogni per il riavvio dell\u2019anno scolastico e puntare ad avere finanziamenti statali per affitti di immobili o noleggio di strutture temporanee\u201d, spiega l\u2019assessora ai Lavori pubblici e vicesindaca\u00a0<strong>Laura Di Giuseppe<\/strong>. \u201cPer risolvere la problematica della paventata turnazione pomeridiana &#8211; che era stata in prima istanza ipotizzata dalla dirigente scolastica dell&#8217;istituto comprensivo Tivoli 1 per i ragazzi delle terze classi della scuola secondaria di I grado \u2018E. Segr\u00e8\u2019 &#8211; si \u00e8 pensato di realizzare una struttura temporanea (climatizzata e dotata di elementi e impianti certificati) da collocare nel cortile del plesso di Braschi, in grado di ospitare tre classi. Questo, insieme all&#8217;utilizzo di altri due spazi all&#8217;interno del plesso \u2018Don Nello del Raso\u2019, consentir\u00e0 di scongiurare il ricorso alla riorganizzazione didattica. Inoltre, per limitare a soli due plessi la distribuzione delle classi della primaria della \u2018S. Pertini\u2019, si \u00e8 ipotizzata la realizzazione di un&#8217;ulteriore struttura temporanea nel cortile del plesso di Colsereno: una soluzione, quest\u2019ultima, che consentirebbe di ospitare gli alunni della \u2018Pertini\u2019 nell\u2019edificio di Colsereno e all&#8217;interno della biblioteca comunale\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La giunta comunale di Tivoli ha approvato la\u00a0delibera 140 del 24 agosto\u00a0con la quale il Comune aderisce all\u2019avviso pubblico del\u00a0Dipartimento per il sistema educativo d\u2019istruzione e di formazione del ministero [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":5296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-5295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico - Tivoli\" \/>\n<meta property=\"og:description\" content=\"La giunta comunale di Tivoli ha approvato la\u00a0delibera 140 del 24 agosto\u00a0con la quale il Comune aderisce all\u2019avviso pubblico del\u00a0Dipartimento per il sistema educativo d\u2019istruzione e di formazione del ministero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T10:07:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-26T11:18:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/08\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico\",\"datePublished\":\"2020-08-26T10:07:19+00:00\",\"dateModified\":\"2020-08-26T11:18:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/\"},\"wordCount\":502,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/08\\\/scuola.png\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/\",\"name\":\"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/08\\\/scuola.png\",\"datePublished\":\"2020-08-26T10:07:19+00:00\",\"dateModified\":\"2020-08-26T11:18:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/08\\\/scuola.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/08\\\/scuola.png\",\"width\":512,\"height\":384},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/26\\\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico - Tivoli","og_description":"La giunta comunale di Tivoli ha approvato la\u00a0delibera 140 del 24 agosto\u00a0con la quale il Comune aderisce all\u2019avviso pubblico del\u00a0Dipartimento per il sistema educativo d\u2019istruzione e di formazione del ministero [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-08-26T10:07:19+00:00","article_modified_time":"2020-08-26T11:18:12+00:00","og_image":[{"width":512,"height":384,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/08\/scuola.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico","datePublished":"2020-08-26T10:07:19+00:00","dateModified":"2020-08-26T11:18:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/"},"wordCount":502,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/08\/scuola.png","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/","url":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/","name":"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/08\/scuola.png","datePublished":"2020-08-26T10:07:19+00:00","dateModified":"2020-08-26T11:18:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/08\/scuola.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/08\/scuola.png","width":512,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/26\/coronavirus-scuole-il-comune-aderisce-allavviso-del-miur-per-laffitto-di-strutture-temporanee-a-uso-scolastico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, scuole: il Comune aderisce all\u2019avviso del Miur per l\u2019affitto di strutture temporanee a uso scolastico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=5295"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5295\/revisions"}],"predecessor-version":[{"id":5298,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5295\/revisions\/5298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/5296"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=5295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=5295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=5295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}