{"id":5313,"date":"2020-08-28T22:35:40","date_gmt":"2020-08-28T20:35:40","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=5313"},"modified":"2020-08-28T22:35:40","modified_gmt":"2020-08-28T20:35:40","slug":"pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/","title":{"rendered":"Pubblicato l&#8217;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019"},"content":{"rendered":"<p>Attraverso un avviso pubblico con scadenza luned\u00ec 7 settembre, il Comune di Tivoli promuove una selezione di associazioni senza scopo di lucro (onlus) per la riqualificazione dei percorsi paesistici e archeologici del territorio che circonda i siti Unesco di Villa Adriana e Villa d\u2019Este, e per l\u2019attivit\u00e0 a supporto della mostra dal titolo \u201cTivoli e le grandi ville di et\u00e0 romana\u201d. L\u2019iniziativa \u00e8 sostenuta dal finanziamento che l\u2019assessorato regionale della Cultura ha riconosciuto per il Comune di Tivoli: si tratta di oltre 33mila euro destinati a valorizzare e promuovere i siti Unesco di Villa Adriana e di Villa d\u2019Este.<\/p>\n<p>L\u2019avviso pubblico \u00e8 disponibile sull\u2019albo pretorio online e nella sezione trasparenza del sito istituzionale del Comune .<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019obiettivo dell\u2019amministrazione comunale \u00e8 promuovere con questa iniziativa il territorio delle Villae attraverso l\u2019allestimento di una mostra e la riqualificazione di tre percorsi di collegamento fra i due siti Unesco, paesisticamente rilevanti e ricchi di resti archeologici riferibili alle ville romane. La riqualificazione dei percorsi, scelti in base alla valenza storico-paesaggistica e alla facilit\u00e0 nel collegamento pedonale tra i due siti come itinerari culturali per la conoscenza del territorio circostante, saranno mete di visite guidate, arricchite con pannelli dedicati e materiale turistico.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cUn\u2019iniziativa ancor pi\u00f9 importante in un periodo dell\u2019anno in cui cerchiamo di riemergere dalle difficolt\u00e0 dovute all\u2019emergenza sanitaria e al blocco delle attivit\u00e0, tra cui quelle culturali\u201d, commentano il sindaco\u00a0<strong>Giuseppe Proietti<\/strong>. \u201cIl 19 agosto scorso la giunta comunale ha approvato un altro atto significativo per la valorizzazione del territorio tiburtino: la delibera di giunta n. 136 con la quale l\u2019amministrazione intende riqualificare i percorsi storici, archeologici e paesaggistici di via di Pomata, strada antica di servizio e manutenzione dei principali acquedotti romani che attraversano il territorio comunale e luogo panoramico scelto per alcune delle ville romane residenziali e di villeggiatura, fino alla residenza dell\u2019imperatore Adriano. E, poi, il percorso di San Marco, che lasciando la via Tiburtina poco oltre il centro urbano, consente un collegamento naturalistico-archeologico di facile percorrenza con Villa Adriana, costeggiato da altri importanti ruderi di ville romane. Infine, il percorso Piranesi, che da Villa d\u2019Este rappresenta un cammino turistico di collegamento con Villa Adriana, con l\u2019illustrazione delle opere pi\u00f9 significative dell\u2019incisore e architetto veneziano,\u00a0<strong>Giovanni Battista Piranesi<\/strong>, che riguardano il territorio e i monumenti di Tivoli\u201d.<\/p>\n<p>\u201cL\u2019esigenza imposta dal Coronavirus di spostare all\u2019aperto le manifestazioni culturali ci ha spinto a riqualificare i percorsi naturalistici e turistici cittadini con segnaletica e pannellistica nuove e aggiornate: oltre al percorso Piranesi, anche i due percorsi di Pomata e di San Marco che partendo da Tivoli conducono a Villa Adriana, di cui quest\u2019anno si celebra il ventennale dell\u2019iscrizione nella lista dei beni patrimonio dell\u2019umanit\u00e0. Due cammini suggestivi, riprodotti da grandi paesaggisti e fotografi, molto amati dai tiburtini e dai turisti come meta di passeggiate a piedi e in bicicletta, che devono essere conservati e valorizzati. La loro riqualificazione avverr\u00e0 in connessione con la mostra che illustrer\u00e0 in dettaglio l\u2019architettura e le sculture delle ville romane disseminate nel territorio e tra gli uliveti che circondano Tivoli\u201d, spiega la consigliera del sindaco per i musei,<strong>\u00a0Maria Antonietta Tomei.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attraverso un avviso pubblico con scadenza luned\u00ec 7 settembre, il Comune di Tivoli promuove una selezione di associazioni senza scopo di lucro (onlus) per la riqualificazione dei percorsi paesistici e [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-5313","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pubblicato l&#039;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019 - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pubblicato l&#039;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019 - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Attraverso un avviso pubblico con scadenza luned\u00ec 7 settembre, il Comune di Tivoli promuove una selezione di associazioni senza scopo di lucro (onlus) per la riqualificazione dei percorsi paesistici e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-28T20:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Pubblicato l&#8217;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019\",\"datePublished\":\"2020-08-28T20:35:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/\"},\"wordCount\":559,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/\",\"name\":\"Pubblicato l'avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019 - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2020-08-28T20:35:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/08\\\/28\\\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pubblicato l&#8217;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pubblicato l'avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019 - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/","og_locale":"it_IT","og_type":"article","og_title":"Pubblicato l'avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019 - Tivoli","og_description":"Attraverso un avviso pubblico con scadenza luned\u00ec 7 settembre, il Comune di Tivoli promuove una selezione di associazioni senza scopo di lucro (onlus) per la riqualificazione dei percorsi paesistici e [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-08-28T20:35:40+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Pubblicato l&#8217;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019","datePublished":"2020-08-28T20:35:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/"},"wordCount":559,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/","url":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/","name":"Pubblicato l'avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019 - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2020-08-28T20:35:40+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/08\/28\/pubblicato-lavviso-per-la-riqualificazione-dei-percorsi-paesistici-e-archeologici-e-per-lattivita-a-supporto-della-mostra-tivoli-e-le-grandi-ville-di-eta-romana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Pubblicato l&#8217;avviso per la riqualificazione dei percorsi paesistici e archeologici e per l\u2019attivit\u00e0 a supporto della mostra \u2018Tivoli e le grandi ville di et\u00e0 romana\u2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=5313"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5313\/revisions"}],"predecessor-version":[{"id":5314,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5313\/revisions\/5314"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=5313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=5313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=5313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}