{"id":5528,"date":"2020-09-16T12:16:20","date_gmt":"2020-09-16T10:16:20","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=5528"},"modified":"2020-09-16T12:16:20","modified_gmt":"2020-09-16T10:16:20","slug":"materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/","title":{"rendered":"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso"},"content":{"rendered":"<p>Il settore Istruzione del Comune di Tivoli ricorda che i genitori dei bambini frequentanti le scuole materne\u00a0<em>Igino Giordani<\/em>\u00a0e\u00a0<em>Don Nello Del Raso<\/em>, appartenenti all\u2019istituto comprensivo Tivoli 1, anche per quest\u2019anno hanno la possibilit\u00e0 di utilizzare lo scuolabus gratuitamente.<\/p>\n<p>Per iscriversi al servizio \u00e8 necessario rivolgersi allo sportello del servizio scolastico, nei seguenti giorni e orari:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 sportello di Tivoli centro, via del Governo,\u00a0<strong>luned\u00ec e gioved\u00ec<\/strong>, dalle 9 alle 12;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 sportello di Villa Adriana, sede della delegazione (via di Villa Adriana n. 178),\u00a0<strong>marted\u00ec, mercoled\u00ec e venerd\u00ec\u00a0<\/strong>dalle 9 alle 12.<\/p>\n<p>Si ricorda, inoltre, che \u2013 come gli altri anni \u2013 la fermata dello scuolabus resta in piazza del Governo, davanti alla sede municipale.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il settore Istruzione del Comune di Tivoli ricorda che i genitori dei bambini frequentanti le scuole materne\u00a0Igino Giordani\u00a0e\u00a0Don Nello Del Raso, appartenenti all\u2019istituto comprensivo Tivoli 1, anche per quest\u2019anno hanno [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":2809,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-5528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani\u200b-e-del-don-nello-del-raso\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Il settore Istruzione del Comune di Tivoli ricorda che i genitori dei bambini frequentanti le scuole materne\u00a0Igino Giordani\u00a0e\u00a0Don Nello Del Raso, appartenenti all\u2019istituto comprensivo Tivoli 1, anche per quest\u2019anno hanno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani\u200b-e-del-don-nello-del-raso\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T10:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso\",\"datePublished\":\"2020-09-16T10:16:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/\"},\"wordCount\":130,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/\",\"name\":\"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"datePublished\":\"2020-09-16T10:16:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2019\\\/07\\\/AVVISO.png\",\"width\":800,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/09\\\/16\\\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani\u200b-e-del-don-nello-del-raso\/","og_locale":"it_IT","og_type":"article","og_title":"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso - Tivoli","og_description":"Il settore Istruzione del Comune di Tivoli ricorda che i genitori dei bambini frequentanti le scuole materne\u00a0Igino Giordani\u00a0e\u00a0Don Nello Del Raso, appartenenti all\u2019istituto comprensivo Tivoli 1, anche per quest\u2019anno hanno [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani\u200b-e-del-don-nello-del-raso\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-09-16T10:16:20+00:00","og_image":[{"width":800,"height":514,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso","datePublished":"2020-09-16T10:16:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/"},"wordCount":130,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/","url":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/","name":"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","datePublished":"2020-09-16T10:16:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2019\/07\/AVVISO.png","width":800,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/09\/16\/materne-tivoli-1-scuolabus-gratuito-anche-questanno-per-gli-alunni-delli-giordani%e2%80%8b-e-del-don-nello-del-raso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Materne Tivoli 1: scuolabus gratuito anche quest\u2019anno per gli alunni dell\u2019I. Giordani\u200b e del Don Nello Del Raso"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=5528"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5528\/revisions"}],"predecessor-version":[{"id":5529,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5528\/revisions\/5529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/2809"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=5528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=5528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=5528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}