{"id":5644,"date":"2020-10-02T09:05:10","date_gmt":"2020-10-02T07:05:10","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=5644"},"modified":"2020-10-02T09:05:10","modified_gmt":"2020-10-02T07:05:10","slug":"trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/","title":{"rendered":"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre"},"content":{"rendered":"<p>Si terr\u00e0 sabato 3 ottobre, dopo il rinvio causa maltempo di domenica scorsa, il terzo\u00a0<em>\u201cTrofeo Lazio di marcia Fulvio Villa&#8221;\u00a0<\/em>con<em>\u00a0<\/em>la partecipazione di decine di atleti di varie categorie che gareggeranno allo stadio comunale\u00a0<em>Olindo Galli<\/em>\u00a0di Tivoli.<\/p>\n<p>La gara, organizzata dall\u2019Atletica Tivoli in collaborazione con il comitato regionale Fidal Lazio, rientra nel campionato regionale individuale cadetti e cadette 3^ prova su pista ed \u00e8 inserito nel programma del\u00a0<em>\u201cSettembre tiburtino 2020\u201d.<\/em><\/p>\n<p>Le gare partiranno alle 15 con gli atleti delle diverse categorie di appartenenza. Primi a correre saranno le assolute e gli assoluti: quattro gli atleti azzurri attesi all\u2019Olindo Galli: la medaglia di bronzo ai mondiali di Londra 2017 e quarta classificata alle Olimpiadi di Rio 2016,\u00a0<strong>Antonella Palmisano; Francesco Fortunato<\/strong>, otto titoli italiani assoluti;\u00a0<strong>Andrea Agrusti<\/strong>, sei presenze in Nazionale e\u00a0<strong>Marco De Luca<\/strong>, 29 presenze in Nazionale, ha anche partecipato a tre Olimpiadi.<\/p>\n<p>Subito dopo, in pista le altre categorie: ragazzi e ragazze, master F e\u00a0 master M, cadetti e cadette.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Si terr\u00e0 sabato 3 ottobre, dopo il rinvio causa maltempo di domenica scorsa, il terzo\u00a0\u201cTrofeo Lazio di marcia Fulvio Villa&#8221;\u00a0con\u00a0la partecipazione di decine di atleti di varie categorie che gareggeranno [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":5645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si terr\u00e0 sabato 3 ottobre, dopo il rinvio causa maltempo di domenica scorsa, il terzo\u00a0\u201cTrofeo Lazio di marcia Fulvio Villa&#8221;\u00a0con\u00a0la partecipazione di decine di atleti di varie categorie che gareggeranno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-02T07:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/trofeo-marcia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"474\" \/>\n\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre\",\"datePublished\":\"2020-10-02T07:05:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/\"},\"wordCount\":173,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/trofeo-marcia.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/\",\"name\":\"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/trofeo-marcia.jpeg\",\"datePublished\":\"2020-10-02T07:05:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/trofeo-marcia.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/trofeo-marcia.jpeg\",\"width\":474,\"height\":265},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/02\\\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/","og_locale":"it_IT","og_type":"article","og_title":"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre - Tivoli","og_description":"Si terr\u00e0 sabato 3 ottobre, dopo il rinvio causa maltempo di domenica scorsa, il terzo\u00a0\u201cTrofeo Lazio di marcia Fulvio Villa&#8221;\u00a0con\u00a0la partecipazione di decine di atleti di varie categorie che gareggeranno [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-10-02T07:05:10+00:00","og_image":[{"width":474,"height":265,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/trofeo-marcia.jpeg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre","datePublished":"2020-10-02T07:05:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/"},"wordCount":173,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/trofeo-marcia.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/","url":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/","name":"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/trofeo-marcia.jpeg","datePublished":"2020-10-02T07:05:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/trofeo-marcia.jpeg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/trofeo-marcia.jpeg","width":474,"height":265},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/02\/trofeo-fulvio-villa-trofeo-lazio-di-marcia-2020-gli-azzurri-allolindo-galli-sabato-3-ottobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Trofeo Fulvio Villa-Trofeo Lazio di marcia 2020: gli azzurri all\u2019Olindo Galli sabato 3 ottobre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=5644"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5644\/revisions"}],"predecessor-version":[{"id":5646,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5644\/revisions\/5646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/5645"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=5644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=5644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=5644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}