{"id":5780,"date":"2020-10-22T13:08:55","date_gmt":"2020-10-22T11:08:55","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=5780"},"modified":"2020-10-22T13:08:55","modified_gmt":"2020-10-22T11:08:55","slug":"le-antiche-pietre-raccontano-evento-virtuale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/","title":{"rendered":"Le antiche pietre raccontano, evento virtuale"},"content":{"rendered":"<p class=\"western\" align=\"center\"><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Museo Archeologico Comunale<\/span><\/span><\/span> <span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>Lily Ross Taylor<\/i><\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"center\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Comune di Ciciliano<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">25 ottobre 2020 <\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">ore 16.00<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">L\u2019Istituto <\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>Villa Adriana e Villa d\u2019Este<\/i><\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> \u2013 <\/span><\/span><span style=\"font-family: Garamond, serif\"><i><b>VILL\u00c6<\/b><\/i><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> e il <\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Comune di Ciciliano<\/b><\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> sono lieti di annunciare <\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">l\u2019evento virtuale <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i><b>Le antiche pietre raccontano<\/b><\/i><\/span><\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> in calendario <\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">domenica 25 ottobre alle ore 16.00 per la promozione del <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Museo Archeologico Comunale<\/b><\/span><\/span><\/span> <span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>di Ciciliano<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>on line<\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> sul sito del medesimo Comune (www.comune.ciciliano.rm.it). <\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">La manifestazione, organizzata dal Comune di Ciciliano con il contributo del Consiglio Regionale del Lazio e in collaborazione con l\u2019Associazione <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>Comitato articolo 9<\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, celebra l\u2019<\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>esposizione a Ciciliano <\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">di importanti <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>reperti musivi<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> rinvenuti nell\u2019antica\u00a0citt\u00e0 di <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Trebula Suffen\u00e0s<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, afferenti all\u2019Istituto <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>Villa Adriana e Villa d\u2019Este<\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> e sinora conservati nei magazzini del <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Santuario di Ercole Vincitore<\/span><\/span><\/span><b> <\/b><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">a Tivoli.<\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> Il Consiglio Comunale all\u2019unanimit\u00e0 ha voluto intitolare il <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Museo Archeologico<\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, di recentissima istituzione, a <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Lily Ross Taylor,<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> studiosa americana, filologa, gi\u00e0 direttrice della sezione classica dell\u2019Accademia americana di Roma. Attraverso uno studio del 1956, <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>Trebula Suffenas and the Plautii Silvani<\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, la ricercatrice ha contribuito a definire con certezza la collocazione del municipio romano all\u2019interno del territorio dell\u2019odierna Ciciliano. La manifestazione \u00e8 l\u2019occasione per presentare il progetto condiviso tra le <\/span><\/span><\/span><span style=\"font-family: Garamond, serif\"><i>VILL\u00c6<\/i><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> e il Comune di Ciciliano, tra i quali di recente \u00e8 stata sottoscritta una convenzione per la concessione in prestito dei reperti, nonch\u00e9 un accordo di collaborazione tecnico-scientifica. <\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Nell\u2019ambito della manifestazione, si intendono illustrare inoltre le attivit\u00e0 gi\u00e0 avviate dall\u2019<\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Universit\u00e0<\/b><\/span><\/span><\/span> <span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i><b>La Sapienza <\/b><\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>di Roma<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, Facolt\u00e0 di <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Architettura<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, oggetto di un contratto di ricerca sottoscritto con il Comune di Ciciliano, e volte a rafforzare l\u2019attivit\u00e0 di studio e valorizzazione del patrimonio archeologico del territorio.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #212121\">\u201c<span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Questa manifestazione \u2013 dichiara <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Massimiliano Calore<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Sindaco di Ciciliano<\/b><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> \u2013 \u00e8 l\u2019espressione dell\u2019impegno di questi anni, profuso con passione e attenta dedizione, che oggi si trasforma in soddisfazione personale e collettiva. Purtroppo la grave emergenza sanitaria che stiamo vivendo non ci ha permesso di organizzare questo evento, genesi di un\u2019intensa attivit\u00e0 di ricerca e valorizzazione del nostro patrimonio archeologico, cos\u00ec come avrebbe meritato e cos\u00ec come avremmo voluto, per il valore che lo stesso rappresenta, sia per la comunit\u00e0 di Ciciliano che per l\u2019intero territorio circostante. Un ringraziamento particolare va al direttore dell\u2019Istituto Autonomo <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>Villa Adriana e Villa d\u2019Este<\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, dott. <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Andrea Bruciati, che ha contribuito a realizzare questo \u201csogno\u201d condividendo con entusiasmo il progetto di valorizzazione e futura fruizione del museo; alla prof.ssa Donatella Fiorani per le qualificate attivit\u00e0 avviate nell\u2019ambito del contratto di ricerca sottoscritto tra il Comune di Ciciliano e il Dipartimento di Storia, Disegno e Restauro dell\u2019Architettura dell\u2019Universit\u00e0 <\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><i>La Sapienza<\/i><\/span><\/span><\/span><span style=\"color: #212121\"><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> di Roma.\u201d<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\">\u201c<span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">Il progetto \u2013 commenta <\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>Andrea Bruciati<\/b><\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\">, <\/span><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"><b>direttore delle<\/b><\/span><\/span> <span style=\"font-family: Garamond, serif\"><i><b>VILL\u00c6<\/b><\/i><\/span><span style=\"font-family: Garamond, serif\"><span style=\"font-size: large\"> \u2013 intende favorire la fruizione dell\u2019inestimabile patrimonio archeologico di cui siamo custodi e depositari e garantire al pubblico la conoscenza di materiali spesso inaccessibili. Vogliamo far riemergere il grande museo diffuso che connota il territorio del nostro paese, per offrire una proposta culturale, didattica e turistica ancor pi\u00f9 densa e diversificata. Nel contempo creiamo nuove aree di ricerca aperte a rinnovati contributi scientifici, ponendo l\u2019attenzione su opere sottovalutate o misconosciute, come \u00e8 connaturato alla nostra missione istituzionale\u201d.<\/span><\/span><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Museo Archeologico Comunale Lily Ross Taylor Comune di Ciciliano 25 ottobre 2020 ore 16.00 L\u2019Istituto Villa Adriana e Villa d\u2019Este \u2013 VILL\u00c6 e il Comune di Ciciliano sono lieti di [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":5781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-5780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le antiche pietre raccontano, evento virtuale - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le antiche pietre raccontano, evento virtuale - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Museo Archeologico Comunale Lily Ross Taylor Comune di Ciciliano 25 ottobre 2020 ore 16.00 L\u2019Istituto Villa Adriana e Villa d\u2019Este \u2013 VILL\u00c6 e il Comune di Ciciliano sono lieti di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T11:08:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/FOTO-DEL-MOSAICO-INTERO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1917\" \/>\n\t<meta property=\"og:image:height\" content=\"1615\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Le antiche pietre raccontano, evento virtuale\",\"datePublished\":\"2020-10-22T11:08:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/\"},\"wordCount\":525,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/FOTO-DEL-MOSAICO-INTERO.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/\",\"name\":\"Le antiche pietre raccontano, evento virtuale - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/FOTO-DEL-MOSAICO-INTERO.jpg\",\"datePublished\":\"2020-10-22T11:08:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/FOTO-DEL-MOSAICO-INTERO.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/10\\\/FOTO-DEL-MOSAICO-INTERO.jpg\",\"width\":1917,\"height\":1615},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2020\\\/10\\\/22\\\/le-antiche-pietre-raccontano-evento-virtuale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le antiche pietre raccontano, evento virtuale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le antiche pietre raccontano, evento virtuale - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/","og_locale":"it_IT","og_type":"article","og_title":"Le antiche pietre raccontano, evento virtuale - Tivoli","og_description":"Museo Archeologico Comunale Lily Ross Taylor Comune di Ciciliano 25 ottobre 2020 ore 16.00 L\u2019Istituto Villa Adriana e Villa d\u2019Este \u2013 VILL\u00c6 e il Comune di Ciciliano sono lieti di [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-10-22T11:08:55+00:00","og_image":[{"width":1917,"height":1615,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/FOTO-DEL-MOSAICO-INTERO.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Le antiche pietre raccontano, evento virtuale","datePublished":"2020-10-22T11:08:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/"},"wordCount":525,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/FOTO-DEL-MOSAICO-INTERO.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/","url":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/","name":"Le antiche pietre raccontano, evento virtuale - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/FOTO-DEL-MOSAICO-INTERO.jpg","datePublished":"2020-10-22T11:08:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/FOTO-DEL-MOSAICO-INTERO.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/10\/FOTO-DEL-MOSAICO-INTERO.jpg","width":1917,"height":1615},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2020\/10\/22\/le-antiche-pietre-raccontano-evento-virtuale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Le antiche pietre raccontano, evento virtuale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=5780"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5780\/revisions"}],"predecessor-version":[{"id":5782,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/5780\/revisions\/5782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/5781"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=5780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=5780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=5780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}