{"id":611,"date":"2017-05-19T18:56:32","date_gmt":"2017-05-19T16:56:32","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=611"},"modified":"2017-05-19T18:56:32","modified_gmt":"2017-05-19T16:56:32","slug":"primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/","title":{"rendered":"Primavera Tiburtina &#8211; sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia"},"content":{"rendered":"<h4 class=\"fontTitolo\"><\/h4>\n<p><strong>Sabato 20 maggio Museo del Pizzutello in Via della Sibilla, 33, ore 15.30 \u2013 19.30<\/strong><br \/>\n<strong>Le erbe nella tradizione popolare tra ricette tiburtine, medicina e magia<\/strong><br \/>\nMostra sulle erbe utilizzate nell\u2019alimentazione, nella medicina, nella cosmesi e nelle credenze popolari delle genti di Tivoli con visite guidate al museo degli attrezzi contadini, accoglienza con infusi alle erbe e laboratorio sulla preparazione del sale aromatico.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato 20 maggio Museo del Pizzutello in Via della Sibilla, 33, ore 15.30 \u2013 19.30 Le erbe nella tradizione popolare tra ricette tiburtine, medicina e magia Mostra sulle erbe utilizzate [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primavera Tiburtina - sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primavera Tiburtina - sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Sabato 20 maggio Museo del Pizzutello in Via della Sibilla, 33, ore 15.30 \u2013 19.30 Le erbe nella tradizione popolare tra ricette tiburtine, medicina e magia Mostra sulle erbe utilizzate [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-19T16:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/primavera-generico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Primavera Tiburtina &#8211; sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia\",\"datePublished\":\"2017-05-19T16:56:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/\"},\"wordCount\":73,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/primavera-generico.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/\",\"name\":\"Primavera Tiburtina - sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/primavera-generico.jpg\",\"datePublished\":\"2017-05-19T16:56:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/primavera-generico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2017\\\/03\\\/primavera-generico.jpg\",\"width\":1120,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/05\\\/19\\\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primavera Tiburtina &#8211; sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primavera Tiburtina - sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/","og_locale":"it_IT","og_type":"article","og_title":"Primavera Tiburtina - sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia - Tivoli","og_description":"Sabato 20 maggio Museo del Pizzutello in Via della Sibilla, 33, ore 15.30 \u2013 19.30 Le erbe nella tradizione popolare tra ricette tiburtine, medicina e magia Mostra sulle erbe utilizzate [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-05-19T16:56:32+00:00","og_image":[{"width":1120,"height":800,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/primavera-generico.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Primavera Tiburtina &#8211; sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia","datePublished":"2017-05-19T16:56:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/"},"wordCount":73,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/primavera-generico.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/","name":"Primavera Tiburtina - sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/primavera-generico.jpg","datePublished":"2017-05-19T16:56:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/primavera-generico.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2017\/03\/primavera-generico.jpg","width":1120,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/05\/19\/primavera-tiburtina-sabato-20-le-erbe-nella-tradizione-popolare-tra-ricette-medicina-e-magia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Primavera Tiburtina &#8211; sabato 20 Le erbe nella tradizione popolare tra ricette, medicina e magia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/611\/revisions"}],"predecessor-version":[{"id":612,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/611\/revisions\/612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/456"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}