{"id":6377,"date":"2021-01-05T13:15:45","date_gmt":"2021-01-05T12:15:45","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=6377"},"modified":"2021-01-05T13:15:45","modified_gmt":"2021-01-05T12:15:45","slug":"ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/","title":{"rendered":"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno"},"content":{"rendered":"<p>Dalle 8 di gioved\u00ec 7 gennaio alle 18 del 7 aprile sar\u00e0 in vigore la seguente modifica alla regolamentazione stradale per via Colsereno, disponibile al seguente link: https:\/\/albopretorio.datamanagementitalia.it\/AlboPretorioWeb\/?ente=ComuneDiTivoli&amp;tipoSubmit=ricerca#<\/p>\n<p><a href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/01\/ord.-n\u00b02-2021.pdf\">ord. n\u00b02-2021<\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_6378\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/01\/ord.-n\u00b02-2021.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/01\/ord.-n\u00b02-2021.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ord. n\u00b02-2021<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dalle 8 di gioved\u00ec 7 gennaio alle 18 del 7 aprile sar\u00e0 in vigore la seguente modifica alla regolamentazione stradale per via Colsereno, disponibile al seguente link: https:\/\/albopretorio.datamanagementitalia.it\/AlboPretorioWeb\/?ente=ComuneDiTivoli&amp;tipoSubmit=ricerca# ord. n\u00b02-2021 [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":6210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-6377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Dalle 8 di gioved\u00ec 7 gennaio alle 18 del 7 aprile sar\u00e0 in vigore la seguente modifica alla regolamentazione stradale per via Colsereno, disponibile al seguente link: https:\/\/albopretorio.datamanagementitalia.it\/AlboPretorioWeb\/?ente=ComuneDiTivoli&amp;tipoSubmit=ricerca# ord. n\u00b02-2021 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-05T12:15:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/12\/allerta_meteo_300x300.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno\",\"datePublished\":\"2021-01-05T12:15:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/\"},\"wordCount\":44,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/12\\\/allerta_meteo_300x300.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/\",\"name\":\"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/12\\\/allerta_meteo_300x300.png\",\"datePublished\":\"2021-01-05T12:15:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/12\\\/allerta_meteo_300x300.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2020\\\/12\\\/allerta_meteo_300x300.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/01\\\/05\\\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno - Tivoli","og_description":"Dalle 8 di gioved\u00ec 7 gennaio alle 18 del 7 aprile sar\u00e0 in vigore la seguente modifica alla regolamentazione stradale per via Colsereno, disponibile al seguente link: https:\/\/albopretorio.datamanagementitalia.it\/AlboPretorioWeb\/?ente=ComuneDiTivoli&amp;tipoSubmit=ricerca# ord. n\u00b02-2021 [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-01-05T12:15:45+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/12\/allerta_meteo_300x300.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno","datePublished":"2021-01-05T12:15:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/"},"wordCount":44,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/12\/allerta_meteo_300x300.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/","name":"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/12\/allerta_meteo_300x300.png","datePublished":"2021-01-05T12:15:45+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/12\/allerta_meteo_300x300.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2020\/12\/allerta_meteo_300x300.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/01\/05\/ordinanza-n-2-modifica-regolamentazione-stradale-per-via-colsereno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Ordinanza n. 2 modifica regolamentazione stradale per via Colsereno"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/6377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=6377"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/6377\/revisions"}],"predecessor-version":[{"id":6379,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/6377\/revisions\/6379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/6210"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=6377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=6377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=6377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}