{"id":680,"date":"2017-06-08T20:04:48","date_gmt":"2017-06-08T18:04:48","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=680"},"modified":"2017-06-08T20:04:48","modified_gmt":"2017-06-08T18:04:48","slug":"viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/","title":{"rendered":"VIABILITA&#8217;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE"},"content":{"rendered":"<p>A causa di un grave incidente stradale, accaduto lungo la Tiburtina all&#8217;altezza del bivio di Guidonia, il traffico \u00e8 molto rallentato in entrambe le direzioni di marcia.<\/p>\n<p>Si consigliano percorso alternativi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa di un grave incidente stradale, accaduto lungo la Tiburtina all&#8217;altezza del bivio di Guidonia, il traffico \u00e8 molto rallentato in entrambe le direzioni di marcia. Si consigliano percorso [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIABILITA&#039;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIABILITA&#039;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE - Tivoli\" \/>\n<meta property=\"og:description\" content=\"A causa di un grave incidente stradale, accaduto lungo la Tiburtina all&#8217;altezza del bivio di Guidonia, il traffico \u00e8 molto rallentato in entrambe le direzioni di marcia. Si consigliano percorso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-08T18:04:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/12\/scioperocobas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"VIABILITA&#8217;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE\",\"datePublished\":\"2017-06-08T18:04:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/\"},\"wordCount\":41,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/12\\\/scioperocobas.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/\",\"name\":\"VIABILITA', CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/12\\\/scioperocobas.jpg\",\"datePublished\":\"2017-06-08T18:04:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/12\\\/scioperocobas.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2016\\\/12\\\/scioperocobas.jpg\",\"width\":800,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2017\\\/06\\\/08\\\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIABILITA&#8217;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIABILITA', CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/","og_locale":"it_IT","og_type":"article","og_title":"VIABILITA', CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE - Tivoli","og_description":"A causa di un grave incidente stradale, accaduto lungo la Tiburtina all&#8217;altezza del bivio di Guidonia, il traffico \u00e8 molto rallentato in entrambe le direzioni di marcia. Si consigliano percorso [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-06-08T18:04:48+00:00","og_image":[{"width":800,"height":490,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/12\/scioperocobas.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"VIABILITA&#8217;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE","datePublished":"2017-06-08T18:04:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/"},"wordCount":41,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/12\/scioperocobas.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/","url":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/","name":"VIABILITA', CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/12\/scioperocobas.jpg","datePublished":"2017-06-08T18:04:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/12\/scioperocobas.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2016\/12\/scioperocobas.jpg","width":800,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2017\/06\/08\/viabilita-code-sulla-tiburtina-altezza-bivio-di-guidonia-per-grave-incidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"VIABILITA&#8217;, CODE SULLA TIBURTINA ALTEZZA BIVIO DI GUIDONIA PER GRAVE INCIDENTE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=680"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/680\/revisions"}],"predecessor-version":[{"id":681,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/680\/revisions\/681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/201"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}