{"id":7640,"date":"2021-08-11T16:56:41","date_gmt":"2021-08-11T14:56:41","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=7640"},"modified":"2021-08-11T16:57:32","modified_gmt":"2021-08-11T14:57:32","slug":"sospensione-distributore-sacchi-tivoli-terme-per-manutenzione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/","title":{"rendered":"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione"},"content":{"rendered":"<div class=\"et_pb_module et_pb_text et_pb_text_0 et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<blockquote>\n<h4>Si comunica alle utenze la momentanea sospensione del distributore dei sacchetti sito a Tivoli Terme per manutenzione straordinaria.<\/h4>\n<\/blockquote>\n<\/div>\n<\/div>\n<div class=\"et_pb_module et_pb_text et_pb_text_1 et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<h4><em>Si ricorda che \u00e8 possibile ritirare i sacchetti negli altri distributori dislocati sul territorio tiburtino:<br \/>\n<\/em><\/h4>\n<ul>\n<li><em>Tivoli, piazza Massimo<\/em><\/li>\n<li>Villa Adriana, Parco Sogno di Malala<\/li>\n<li>San pastore, lottizzazione Giglio, Campolimpido e Favale \u2013 farmacia Giovannola<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p><em>Ci scusiamo per il disagio \u00a0e assicuriamo che lo stesso verr\u00e0 ripristinato in tempi brevissimi.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica alle utenze la momentanea sospensione del distributore dei sacchetti sito a Tivoli Terme per manutenzione straordinaria. Si ricorda che \u00e8 possibile ritirare i sacchetti negli altri distributori dislocati [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":7641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-7640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Si comunica alle utenze la momentanea sospensione del distributore dei sacchetti sito a Tivoli Terme per manutenzione straordinaria. Si ricorda che \u00e8 possibile ritirare i sacchetti negli altri distributori dislocati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T14:56:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-11T14:57:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/08\/info-sul-sito-sacchetti-tivoli-terme-guasto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione\",\"datePublished\":\"2021-08-11T14:56:41+00:00\",\"dateModified\":\"2021-08-11T14:57:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/\"},\"wordCount\":74,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/08\\\/info-sul-sito-sacchetti-tivoli-terme-guasto.png\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/\",\"name\":\"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/08\\\/info-sul-sito-sacchetti-tivoli-terme-guasto.png\",\"datePublished\":\"2021-08-11T14:56:41+00:00\",\"dateModified\":\"2021-08-11T14:57:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/08\\\/info-sul-sito-sacchetti-tivoli-terme-guasto.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/08\\\/info-sul-sito-sacchetti-tivoli-terme-guasto.png\",\"width\":1280,\"height\":783},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/08\\\/11\\\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/","og_locale":"it_IT","og_type":"article","og_title":"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione - Tivoli","og_description":"Si comunica alle utenze la momentanea sospensione del distributore dei sacchetti sito a Tivoli Terme per manutenzione straordinaria. Si ricorda che \u00e8 possibile ritirare i sacchetti negli altri distributori dislocati [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-08-11T14:56:41+00:00","article_modified_time":"2021-08-11T14:57:32+00:00","og_image":[{"width":1280,"height":783,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/08\/info-sul-sito-sacchetti-tivoli-terme-guasto.png","type":"image\/png"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione","datePublished":"2021-08-11T14:56:41+00:00","dateModified":"2021-08-11T14:57:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/"},"wordCount":74,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/08\/info-sul-sito-sacchetti-tivoli-terme-guasto.png","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/","name":"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/08\/info-sul-sito-sacchetti-tivoli-terme-guasto.png","datePublished":"2021-08-11T14:56:41+00:00","dateModified":"2021-08-11T14:57:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/08\/info-sul-sito-sacchetti-tivoli-terme-guasto.png","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/08\/info-sul-sito-sacchetti-tivoli-terme-guasto.png","width":1280,"height":783},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/08\/11\/sospensione-distributore-sacchi-tivoli-terme-per-manutenzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Sospensione distributore sacchi raccolta differenziata Tivoli Terme per manutenzione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=7640"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7640\/revisions"}],"predecessor-version":[{"id":7643,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7640\/revisions\/7643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/7641"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=7640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=7640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}