{"id":7708,"date":"2021-09-07T09:03:18","date_gmt":"2021-09-07T07:03:18","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=7708"},"modified":"2021-09-07T09:03:18","modified_gmt":"2021-09-07T07:03:18","slug":"cantagiro-2021-vince-ledizione-raffaella-carleo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/","title":{"rendered":"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo"},"content":{"rendered":"<p>Luci, colori, spettacolo e tanta emozione per i finalisti dell&#8217;edizione 2021 de\u00a0<strong>Il Cantagiro<\/strong>, lo storico concorso canoro che per la prima volta \u00e8 approdato nella splendida citt\u00e0 di\u00a0<strong>Tivoli<\/strong>. La serata\u00a0<strong>Finalissima<\/strong>\u00a0presso il\u00a0<strong>Teatro Giuseppetti<\/strong>\u00a0ha visto trionfare\u00a0<strong>Raffaella Carleo<\/strong>, giovane artista campana con il brano inedito \u201cPolline nell\u2019aria\u201d. Secondo classificato\u00a0<strong>Francesco Simoncini<\/strong>\u00a0delle Marche e terzo posto per il romagnolo Rocco. I \u201cpremi speciali\u201d vanno rispettivamente a\u00a0<strong>Venere\u00a0<\/strong>(Lombardia) -\u201cPremio Little Tony\u201d,\u00a0<strong>Alessio Caterini<\/strong>\u00a0\u2013 \u201cPremio Sergio Bardotti\u201d,\u00a0<strong>Arianna Carchedi<\/strong>\u00a0(Calabria) &#8211; \u201cPremio Radio Italia anni 60\u201d,\u00a0<strong>Grazia Miscia<\/strong>\u00a0\u2013 \u201cPremio Emozione\u201d,\u00a0<strong>Valentina Savastano\u00a0<\/strong>(Abruzzo) -\u201cPremio Mio\u201d,\u00a0<strong>Sara De Sanctis<\/strong>\u00a0(Abruzzo) &#8211; \u201cPremio 2 Righe\u201d,\u00a0<strong>Alfonso Masucci<\/strong>\u00a0(Campania) &#8211; \u201cPremio Opportunit\u00e0.<\/p>\n<p>La giuria di esperti ha come sempre svolto un lavoro eccellente sebbene la scelta del vincitore \u00e8 stata ardua visto l&#8217;alto livello artistico dei finalisti.<\/p>\n<p>Diversi i momenti di spettacolo grazie alla presenza del cantautore\u00a0<strong>Davide De Marinis<\/strong>\u00a0che si \u00e8 esibito con un medley dei suoi successi e dell&#8217;illusionista e showman\u00a0<strong>Mago Heldin<\/strong>\u00a0che con la sua performance ha attratto ed incuriosito il pubblico presente in sala e la stessa giuria. Sul palco, ospite d&#8217;eccezione anche\u00a0<strong>Claudio Lippi<\/strong>\u00a0personaggio\u00a0amatissimo dal pubblico e fedele sostenitore della manifestazione\u00a0che si \u00e8 esibito con il brano \u201cMeraviglioso\u201d.<\/p>\n<p>Quest&#8217;anno alla conduzione oltre all&#8217;ormai collaudato\u00a0<strong>Marco Zingaretti<\/strong>, \u00a0per la prima volta in veste di presentatrice \u00e8 arrivata\u00a0<strong>Cristiana Ciacci<\/strong>\u00a0(figlia di Little Tony) che insieme alla\u00a0<strong>Little Tony Family<\/strong>\u00a0, ha voluto omaggiare e ricordare il noto pap\u00e0 (nativo peraltro di Tivoli) non solo con la musica ma\u00a0 anche presentando il libro autobiografico \u201cMio padre Little Tony\u201d da poco pubblicato.<\/p>\n<p>Durante la serata sono intervenuti la vicesindaca\u00a0<strong>Laura Di Giuseppe<\/strong> e l&#8217;assessora<strong>\u00a0al Bilancio<\/strong>\u00a0del Comune di Tivoli\u00a0<strong>Maria Rosaria Cecchetti<\/strong>\u00a0che hanno raccontato come \u00e8 nato il sodalizio con gli organizzatori del Cantagiro.<\/p>\n<p>Una serata veramente ricca di avvenimenti dove ha trovato posto anche la presentazione di un&#8217;iniziativa che sta molto a cuore al Patron\u00a0<strong>Enzo De Carlo<\/strong>\u00a0e al Direttore Artistico\u00a0<strong>Elvino Echeoni<\/strong>: l\u2019 \u201c<strong>Accademia del Cantagiro<\/strong>\u201d, uno strumento in pi\u00f9 offerto ai giovani talenti che vogliono formarsi e studiare con la direzione\u00a0affidata a\u00a0<strong>Marco Biaggioli<\/strong>. Un aiuto concreto per sviluppare talento ed idee in particolare nella composizione di nuovi brani, atti a stimolare creativit\u00e0 e idee anche da parte degli autori musicali. Uno strumento per fornire nuova linfa e spessore al futuro della musica italiana.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Luci, colori, spettacolo e tanta emozione per i finalisti dell&#8217;edizione 2021 de\u00a0Il Cantagiro, lo storico concorso canoro che per la prima volta \u00e8 approdato nella splendida citt\u00e0 di\u00a0Tivoli. La serata\u00a0Finalissima\u00a0presso [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":7709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-7708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cantagiro 2021: vince l\u2019edizione Raffaella Carleo - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Luci, colori, spettacolo e tanta emozione per i finalisti dell&#8217;edizione 2021 de\u00a0Il Cantagiro, lo storico concorso canoro che per la prima volta \u00e8 approdato nella splendida citt\u00e0 di\u00a0Tivoli. La serata\u00a0Finalissima\u00a0presso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-07T07:03:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/09\/Cantagiro1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo\",\"datePublished\":\"2021-09-07T07:03:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/\"},\"wordCount\":398,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/09\\\/Cantagiro1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/\",\"name\":\"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/09\\\/Cantagiro1.jpg\",\"datePublished\":\"2021-09-07T07:03:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/09\\\/Cantagiro1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/wp-content\\\/uploads\\\/sites\\\/72\\\/2021\\\/09\\\/Cantagiro1.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/07\\\/cantagiro-2021-vince-ledizione-raffaella-carleo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/","og_locale":"it_IT","og_type":"article","og_title":"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo - Tivoli","og_description":"Luci, colori, spettacolo e tanta emozione per i finalisti dell&#8217;edizione 2021 de\u00a0Il Cantagiro, lo storico concorso canoro che per la prima volta \u00e8 approdato nella splendida citt\u00e0 di\u00a0Tivoli. La serata\u00a0Finalissima\u00a0presso [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-07T07:03:18+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/09\/Cantagiro1.jpg","type":"image\/jpeg"}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo","datePublished":"2021-09-07T07:03:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/"},"wordCount":398,"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/09\/Cantagiro1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/","name":"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/09\/Cantagiro1.jpg","datePublished":"2021-09-07T07:03:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#primaryimage","url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/09\/Cantagiro1.jpg","contentUrl":"https:\/\/comunicacity.net\/tivoli\/wp-content\/uploads\/sites\/72\/2021\/09\/Cantagiro1.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/07\/cantagiro-2021-vince-ledizione-raffaella-carleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Cantagiro 2021: vince l\u2019edizione Raffaella Carleo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=7708"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7708\/revisions"}],"predecessor-version":[{"id":7710,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7708\/revisions\/7710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media\/7709"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=7708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=7708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}