{"id":7727,"date":"2021-09-10T13:53:28","date_gmt":"2021-09-10T11:53:28","guid":{"rendered":"https:\/\/comunicacity.net\/tivoli\/?p=7727"},"modified":"2021-09-10T14:09:03","modified_gmt":"2021-09-10T12:09:03","slug":"museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/","title":{"rendered":"Museo civico: apertura serale straordinaria domani sabato 11 settembre"},"content":{"rendered":"<p>Domani sabato 11 settembre il museo civico della citt\u00e0 di Tivoli rester\u00e0 aperto in via straordinaria dalle 15 alle 23 in occasione della prima giornata della \u201cSagra del pizzutello tiburtino\u201d. All\u2019interno di palazzo Macera sar\u00e0 visitabile la mostra\u00a0\u201cLe grandi ville romane del territorio tiburtino\u201d, alla quale l\u2019amministrazione comunale ha lavorato a lungo insieme alla consigliera del sindaco per i musei civici\u00a0Maria Antonietta Tomei, curatrice della mostra, con la collaborazione dell\u2019Istituto autonomo Villa Adriana e Villa D\u2019Este, della Soprintendenza per l\u2019archeologia, le belle arti e il paesaggio per l\u2019area metropolitana di Roma e della Provincia di Viterbo. La mostra sulle Ville romane del territorio tiburtino segue\u00a0 quella sul travertino (il\u00a0lapis tiburtinus), e riguarda un aspetto caratteristico di Tivoli e del suo comprensorio, sinora poco trattato e poco conosciuto: le ville romane.<\/p>\n<p>Essendo quello tiburtino un territorio ricco di acqua, vegetazione e splendidi paesaggi, a pochi passi da Roma, le ville di\u00a0otium, dove i proprietari potevano rilassarsi e dedicarsi alle loro attivit\u00e0 preferite, erano molto diffuse. Molti personaggi illustri della storia romana possedevano sin dal I secolo a.C. ville lussuose, come segnalano i\u00a0 testi latini. Tra loro, per citarne alcuni:\u00a0Bruto, Cassio, Orazio, Catullo, Properzio, Quintilio Varo, Mecenate. La mostra illustra anche tre\u00a0 percorsi pedonali (e ciclabili), molto rilevanti dal punto di vista paesaggistico e ambientale e\u00a0 amati dai tiburtini, che l\u2019Amministrazione ha in programma di valorizzare e di dotare di pannellistica: il percorso Piranesi; la via di Pomata;\u00a0 il percorso San Marco, lungo i quali \u00e8 possibile imbattersi nei resti archeologici di alcune\u00a0 delle\u00a0 pi\u00f9 importanti ville romane. Partendo da villa d\u2019Este, e attraversando in parte la citt\u00e0, dopo una suggestiva passeggiata che permette di ammirare monumenti antichi e splendidi panorami, si arriva a Villa Adriana.<\/p>\n<p>Si ricorda che per entrare al museo occorre essere in possesso e mostrare il\u00a0green pass, la\u00a0\u201ccertificazione verde\u201d\u00a0obbligatoria per partecipare agli eventi pubblici rilasciata dal ministero della Salute a coloro che abbiano ricevuto almeno la prima dose del vaccino anti\u00a0Covid-19, o sia guarito dalla malattia nei sei mesi precedenti, o sia in possesso di un tampone negativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani sabato 11 settembre il museo civico della citt\u00e0 di Tivoli rester\u00e0 aperto in via straordinaria dalle 15 alle 23 in occasione della prima giornata della \u201cSagra del pizzutello tiburtino\u201d. [&hellip;]<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-7727","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museo civico: apertura serale straordinaria domani sabato 11 settembre - Tivoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo civico: apertura serale straordinaria domani sabato 11 settembre - Tivoli\" \/>\n<meta property=\"og:description\" content=\"Domani sabato 11 settembre il museo civico della citt\u00e0 di Tivoli rester\u00e0 aperto in via straordinaria dalle 15 alle 23 in occasione della prima giornata della \u201cSagra del pizzutello tiburtino\u201d. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Tivoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-10T11:53:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-10T12:09:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Comune di Tivoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune di Tivoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/\"},\"author\":{\"name\":\"Comune di Tivoli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"headline\":\"Museo civico: apertura serale straordinaria domani sabato 11 settembre\",\"datePublished\":\"2021-09-10T11:53:28+00:00\",\"dateModified\":\"2021-09-10T12:09:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/\"},\"wordCount\":362,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/\",\"name\":\"Museo civico: apertura serale straordinaria domani sabato 11 settembre - Tivoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\"},\"datePublished\":\"2021-09-10T11:53:28+00:00\",\"dateModified\":\"2021-09-10T12:09:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/2021\\\/09\\\/10\\\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo civico: apertura serale straordinaria domani sabato 11 settembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/\",\"name\":\"Tivoli\",\"description\":\"Le news della Citt\u00e0 di Tivoli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/#\\\/schema\\\/person\\\/d8b562b919da26cb1663e87d1dca9211\",\"name\":\"Comune di Tivoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g\",\"caption\":\"Comune di Tivoli\"},\"description\":\"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587\",\"sameAs\":[\"https:\\\/\\\/www.comune.tivoli.rm.it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC91OP9hXxn20eW1qkj6i6TA\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/tivoli\\\/author\\\/comunetivoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo civico: apertura serale straordinaria domani sabato 11 settembre - Tivoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/","og_locale":"it_IT","og_type":"article","og_title":"Museo civico: apertura serale straordinaria domani sabato 11 settembre - Tivoli","og_description":"Domani sabato 11 settembre il museo civico della citt\u00e0 di Tivoli rester\u00e0 aperto in via straordinaria dalle 15 alle 23 in occasione della prima giornata della \u201cSagra del pizzutello tiburtino\u201d. [&hellip;]","og_url":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/","og_site_name":"Tivoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-10T11:53:28+00:00","article_modified_time":"2021-09-10T12:09:03+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/tivoli\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"Comune di Tivoli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune di Tivoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/"},"author":{"name":"Comune di Tivoli","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"headline":"Museo civico: apertura serale straordinaria domani sabato 11 settembre","datePublished":"2021-09-10T11:53:28+00:00","dateModified":"2021-09-10T12:09:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/"},"wordCount":362,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/","url":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/","name":"Museo civico: apertura serale straordinaria domani sabato 11 settembre - Tivoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/tivoli\/#website"},"datePublished":"2021-09-10T11:53:28+00:00","dateModified":"2021-09-10T12:09:03+00:00","author":{"@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/tivoli\/2021\/09\/10\/museo-civico-apertura-serale-straordinaria-domani-sabato-11-settembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/tivoli\/"},{"@type":"ListItem","position":2,"name":"Museo civico: apertura serale straordinaria domani sabato 11 settembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/tivoli\/#website","url":"https:\/\/comunicacity.net\/tivoli\/","name":"Tivoli","description":"Le news della Citt\u00e0 di Tivoli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/tivoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/tivoli\/#\/schema\/person\/d8b562b919da26cb1663e87d1dca9211","name":"Comune di Tivoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7cd91fb433b736df6e91911b7f94b005e7f7ecdddb7967fc1b2aa1a30a930ce?s=96&d=mm&r=g","caption":"Comune di Tivoli"},"description":"Comune di Tivoli Piazza del Governo, 1, 00019 Tivoli (RM) telefono: +39 0774 4531 fax: +39 0774 33 06 75 PEC: info@pec.comune.tivoli.rm.it codice fiscale: 02696630587","sameAs":["https:\/\/www.comune.tivoli.rm.it\/","https:\/\/www.youtube.com\/channel\/UC91OP9hXxn20eW1qkj6i6TA"],"url":"https:\/\/comunicacity.net\/tivoli\/author\/comunetivoli\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/comments?post=7727"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7727\/revisions"}],"predecessor-version":[{"id":7730,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/posts\/7727\/revisions\/7730"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/media?parent=7727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/categories?post=7727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/tivoli\/wp-json\/wp\/v2\/tags?post=7727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}